{"id":21164,"date":"2013-09-25T17:44:13","date_gmt":"2013-09-25T15:44:13","guid":{"rendered":"http:\/\/onsoftware.softonic.com.br\/?p=21164"},"modified":"2024-03-06T10:07:59","modified_gmt":"2024-03-06T14:07:59","slug":"google-remove-bittorrent-e-utorrent-dos-seus-filtros-antipirataria","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/br\/google-remove-bittorrent-e-utorrent-dos-seus-filtros-antipirataria\/","title":{"rendered":"Google remove BitTorrent e uTorrent dos seus filtros antipirataria"},"content":{"rendered":"<p><strong>O Google decidiu trazer de volta os termos BitTorrent e uTorrent \u00e0s suas sugest\u00f5es de busca.<\/strong> Algum tempo atr\u00e1s, os dois populares programas de P2P haviam sido inclu\u00eddos numa lista antipirataria e eliminados dos resultados sugeridos em buscas no Google.<\/p>\n<h4>Leia tamb\u00e9m:<\/h4>\n<hr \/>\n<ul>\n<li><a href=\"http:\/\/artigos.softonic.com.br\/download-arquivos-internet-utorrent\" title=\"uTorrent: aprenda a baixar arquivos da internet\"><strong>uTorrent: aprenda a baixar arquivos da internet<\/strong><\/a><\/li>\n<li><a title=\"Veja como funciona o BitTorrent Sync\" href=\"http:\/\/artigos.softonic.com.br\/como-usar-bittorrent-sync\"><strong>Veja como funciona o BitTorrent Sync<\/strong><\/a><\/li>\n<li><a title=\"The Pirate Bay lan\u00e7a browser contra censura a torrents\" href=\"http:\/\/noticias.softonic.com.br\/the-pirate-bay-browser-contra-censura-torrents\"><strong>The Pirate Bay lan\u00e7a browser contra censura a torrents<\/strong><\/a><\/li>\n<\/ul>\n<hr \/>\n<p>\nO BitTorrent venceu a batalha judicial que o acusava de pirataria ao provar que o programa em si n\u00e3o \u00e9 ilegal. Na verdade, o problema est\u00e1 no uso que alguns usu\u00e1rios fazem do recurso que o BitTorrent (e muitos outros programas <em>peer-to-peer<\/em>) oferece, realizando a <strong>distribui\u00e7\u00e3o e o download de conte\u00fados protegidos por direitos autorais<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2013\/09\/utorrent1-568x111.png\" alt=\"\" title=\"Autocompletar do Google sugere programa de P2P\" width=\"568\" height=\"111\" class=\"aligncenter size-full wp-image-21166\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/7\/2013\/09\/utorrent1-568x111.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/7\/2013\/09\/utorrent1-568x111-268x52.png 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>A decis\u00e3o do Google contrasta fortemente com a recente cria\u00e7\u00e3o da MPAA (Motion Picture Association of America), a associa\u00e7\u00e3o americana que defende os interesses dos est\u00fadios de cinema. De fato, a MPAA publicou um estudo que revela o papel crucial dos buscadores no download de conte\u00fado protegidos pelas regras de <em>copyright<\/em>: <strong>82% das buscas por conte\u00fados &#8220;piratas&#8221; s\u00e3o feitas via Google<\/strong>.<\/p>\n<p>\n<strong>Download do BitTorrent e do uTorrent:<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/bittorrent.softonic.com.br\/\" title=\"BitTorrent para Windows\"><strong>BitTorrent<\/strong> para Windows<\/a><\/li>\n<li><a href=\"http:\/\/bittorrent.softonic.com.br\/mac\" title=\"BitTorrent para Mac\"><strong>BitTorrent<\/strong> para Mac<\/a><\/li>\n<li><a href=\"http:\/\/utorrent.softonic.com.br\/\" title=\"uTorrent para Windows\"><strong>uTorrent<\/strong> para Windows<\/a><\/li>\n<li><a href=\"http:\/\/utorrent-utorrent.softonic.com.br\/mac\" title=\"uTorrent para Mac\"><strong>uTorrent<\/strong> para Mac<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O Google decidiu trazer de volta os termos BitTorrent e uTorrent \u00e0s suas sugest\u00f5es de busca. Algum tempo atr\u00e1s, os dois populares programas de P2P haviam sido inclu\u00eddos numa lista antipirataria e eliminados dos resultados sugeridos em buscas no Google. Leia tamb\u00e9m: uTorrent: aprenda a baixar arquivos da internet Veja como funciona o BitTorrent Sync &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/br\/google-remove-bittorrent-e-utorrent-dos-seus-filtros-antipirataria\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Google remove BitTorrent e uTorrent dos seus filtros antipirataria&#8221;<\/span><\/a><\/p>\n","protected":false},"author":6012,"featured_media":21166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[3170,4184,3173,3172,3174,3169,3168,3171],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-21164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-antipirataria","tag-app-subdomain-redirectionutorrent","tag-download-conteudo-copyright","tag-download-conteudo-pirata","tag-download-conteudo-protegido","tag-google-bittorrent","tag-google-utorrent","tag-mpaa"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/21164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/users\/6012"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/comments?post=21164"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/21164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media\/21166"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media?parent=21164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/categories?post=21164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/tags?post=21164"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/usertag?post=21164"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/vertical?post=21164"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/content-category?post=21164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}