{"id":23370,"date":"2014-03-19T10:11:05","date_gmt":"2014-03-19T09:11:05","guid":{"rendered":"http:\/\/onsoftware.softonic.com.br\/?p=23370"},"modified":"2024-03-06T09:58:26","modified_gmt":"2024-03-06T13:58:26","slug":"backup-android-como-conservar-todos-dados-sms-contatos-aplicativos-configuracoes","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/br\/backup-android-como-conservar-todos-dados-sms-contatos-aplicativos-configuracoes\/","title":{"rendered":"Backup no Android: Como conservar TODOS os seus dados (SMS, contatos, aplicativos, configura\u00e7\u00f5es&#8230;)"},"content":{"rendered":"<p>Quer fazer uma c\u00f3pia de seguran\u00e7a de SMS, contatos e aplicativos no Android de um dispositivo a outro? Hoje, n\u00f3s vamos explicar como <strong>fazer backup e restaurar todos os seus dados<\/strong> (SMS, contatos, aplicativos, configura\u00e7\u00f5es, documentos, m\u00fasica, fotos, etc.) sem ter que acessar o <em>root<\/em> do celular ou tablet.<\/p>\n<h3>Configurar as op\u00e7\u00f5es de c\u00f3pia de seguran\u00e7a e de redefini\u00e7\u00e3o no Android<\/h3>\n<p>O Android faz c\u00f3pia de seguran\u00e7a automaticamente de alguns par\u00e2metros e <strong>dados associados a uma conta do Google<\/strong>, como senhas do wi-fi, favoritos de navega\u00e7\u00e3o, aplicativos instalados a partir do Google Play, termos adicionados no dicion\u00e1rio e a maioria das configura\u00e7\u00f5es do dispositivo e dos apps que utilizam a op\u00e7\u00e3o de backup.<\/p>\n<p><strong>1.<\/strong> Para ter certeza de que as op\u00e7\u00f5es de backup est\u00e3o bem configuradas, v\u00e1 em &#8220;Configura\u00e7\u00f5es&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" style=\"height: 286px;width: 161px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/10\/Screenshot_2013-10-10-11-26-12-268x476.png\" alt=\"Acesse as configura\u00e7\u00f5es do Android\" title=\"Acesse as configura\u00e7\u00f5es do Android\" \/><\/p>\n<p><strong>2.<\/strong> Dentro de se\u00e7\u00e3o Pessoal, toque em &#8220;Fazer o backup e redefinir&#8221;.<br \/>\n<img decoding=\"async\" class=\"aligncenter\" style=\"height: 286px;width: 161px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/10\/Screenshot_2013-10-10-11-26-47-268x476.png\" alt=\"Acesse a op\u00e7\u00e3o fazer o backup e redefinir\" title=\"Acesse a op\u00e7\u00e3o fazer o backup e redefinir\" \/><\/p>\n<p><strong>3.<\/strong> Selecione a op\u00e7\u00e3o &#8220;Fazer backup&#8221;.<br \/>\n<img decoding=\"async\" class=\"aligncenter\" style=\"height: 286px;width: 161px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/10\/Screenshot_2013-10-10-11-26-561-268x476.png\" alt=\"Marque a op\u00e7\u00e3o fazer backup\" title=\"Marque a op\u00e7\u00e3o fazer backup\" \/><\/p>\n<p><strong>4.<\/strong> Configure a conta do Google que ser\u00e1 utilizada para backup, clicando em &#8220;Conta de backup&#8221;.<br \/>\n<img decoding=\"async\" class=\"aligncenter\" style=\"height: 286px;width: 161px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/10\/Screenshot_2013-10-10-11-26-5611-268x476.png\" alt=\"Configure a conta de backup\" title=\"Configure a conta de backup\" \/><\/p>\n<p><strong>5.<\/strong> Selecione uma conta Google existente ou adicione uma nova, clicando em &#8220;Adicionar conta&#8221;.<br \/>\n<img decoding=\"async\" class=\"aligncenter\" style=\"height: 286px;width: 161px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/10\/Screenshot_2013-10-10-11-27-13-268x476.png\" alt=\"Selecione ou crie uma conta Google\" \/><\/p>\n<p>\nPronto! Agora os dados associados \u00e0 sua conta Google ser\u00e3o armazenados de forma segura. Em caso de perda dos dados, voc\u00ea deve se identificar com a conta Google do seu dispositivo para <strong>recuperar todas as suas configura\u00e7\u00f5es<\/strong> e dados associados.<\/p>\n<p>Note que os aplicativos comprados na loja Google Play estar\u00e3o automaticamente dispon\u00edveis para baixar sem nenhum custo adicional.<\/p>\n<h3>Fazer uma c\u00f3pia de seguran\u00e7a dos seus SMS, contatos, fotos, etc.<\/h3>\n<p>Existem v\u00e1rias solu\u00e7\u00f5es para fazer uma c\u00f3pia de seguran\u00e7a no Android, por\u00e9m o aplicativo <strong>G Cloud Backup<\/strong> chamou nossa aten\u00e7\u00e3o por causa de sua flexibilidade e facilidade de uso. O G Cloud Backup permite fazer o backup dos seus dados online gratuitamente: <strong>contatos, registros de chamadas, SMS, fotos, v\u00eddeos, m\u00fasica, documentos, configura\u00e7\u00f5es, hist\u00f3rico de navega\u00e7\u00e3o&#8230;<\/strong> Voc\u00ea t\u00eam 1 GB de armazenamento para guardar todo o conte\u00fado do seu celular ou tablet Android.<\/p>\n<p><strong>Aten\u00e7\u00e3o:<\/strong> A c\u00f3pia de seguran\u00e7a dos dados dos aplicativos &#8211; o backup de jogos ou configura\u00e7\u00f5es de aplicativos, por exemplo &#8211; s\u00e3o reservadas ao dispositivo Android e n\u00e3o \u00e9 suportado pelo G Cloud Backup.<\/p>\n<p><strong>1.<\/strong> Fa\u00e7a o <a title=\"G Cloud Backup para Android\" href=\"http:\/\/g-cloud-backup.softonic.com.br\/android\">download do aplicativo G Cloud Backup<\/a>. Quando o aplicativo j\u00e1 estiver baixado e instalado no seu dispositivo Android, inicie a configura\u00e7\u00e3o em seguida.<\/p>\n<p><strong>2. <\/strong>Clique em &#8220;New User&#8221; para criar uma nova conta no G Cloud Backup. Introduza um endere\u00e7o de e-mail v\u00e1lido, escolha uma senha e clique em &#8220;Sign up&#8221;. Na etapa seguinte, confirme o endere\u00e7o de e-mail fornecido e clique em &#8220;Proceed&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/81-337x600.png\" alt=\"Tela inicial do GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/8-02-337x600.png\" alt=\"Tela de login do GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/8-11-337x600.png\" alt=\"Tela de verifica\u00e7\u00e3o de registro do GCloud Backup\" \/><\/p>\n<p><strong>3.<\/strong> Selecione as <strong>categorias a serem guardadas<\/strong> marcando as caixas correspondentes e depois clique no bot\u00e3o &#8220;Done&#8221;. O G Cloud Backup se encarrega de copiar seus dados numa conta segura.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/9-337x600.png\" alt=\"Selecione tudo o que deseja fazer backup no GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/9-0-337x600.png\" alt=\"Backup autom\u00e1tico do GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/9-1-337x600.png\" alt=\"Tela de recupera\u00e7\u00e3o de dados do GCloud Backup\" \/><\/p>\n<p><strong>4.<\/strong> Por padr\u00e3o, o G Cloud Backup, vai automatizar os backups. Se voc\u00ea quiser desativar para ter mais controle manual, v\u00e1 at\u00e9 as op\u00e7\u00f5es do aplicativo, clicando no bot\u00e3o situado no topo \u00e0 direita. Clique em &#8220;Backup Schedule&#8221; e depois desmarque a caixa de &#8220;Enable Auto Backup&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/10-337x600.png\" alt=\"Backup do GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/10-0-337x600.png\" alt=\"Agendamento de backup no GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 311px;width: 175px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/10-1-337x600.png\" alt=\"Sele\u00e7\u00e3o de backup autom\u00e1tico no GCloud Backup\" \/><\/p>\n<p><strong>5.<\/strong> Para <strong>restaurar os dados guardados<\/strong>, reinstale o G Cloud Backup e inicie o aplicativo. Clique no bot\u00e3o &#8220;Existing user\/Restore&#8221;, introduza seus dados de identifica\u00e7\u00e3o (e-mail e senha) e depois v\u00e1 \u00e0 aba &#8220;Restore&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" style=\"height: 480px;width: 270px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/11-337x600.png\" alt=\"Acesso \u00e0 conta existente no GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 480px;width: 270px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/11-0-337x600.png\" alt=\"Tela de recupera\u00e7\u00e3o de dados do GCloud Backup\" \/><\/p>\n<p><strong>6.<\/strong> Marque as op\u00e7\u00f5es ao lado dos dados que voc\u00ea gostaria de copiar no seu dispositivo e, depois, clique no bot\u00e3o&#8221;Restore&#8221; para iniciar a restaura\u00e7\u00e3o. Tenha paci\u00eancia at\u00e9 o processo terminar e depois clique em &#8220;OK&#8221;. Pronto, todos os seus dados foram restaurados!<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" style=\"height: 480px;width: 270px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/12-337x600.png\" alt=\"Sele\u00e7\u00e3o de itens para recupera\u00e7\u00e3o no GCloud Backup\" \/>&nbsp;<img decoding=\"async\" class=\"alignnone\" style=\"height: 480px;width: 270px\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/06\/12-0-337x600.png\" alt=\"Recupera\u00e7\u00e3o completa no GCloud Backup\" \/><\/p>\n<p>Qualquer d\u00favida sobre o Android, pergunte aos nossos especialistas usando os coment\u00e1rios!<\/p>\n<p style=\"text-align: right\"><em>[<a title=\"Sauvegarde Android: Comment conserver TOUTES ses donn\u00e9es (SMS, contacts, applications, r\u00e9glages...)\" href=\"http:\/\/articles.softonic.fr\/2013-06-04-sauvegarde-android-sms-contacts-applications-backup\">Artigo original em franc\u00eas<\/a>]<\/em><\/p>\n<h4>Leia tamb\u00e9m<\/p>\n<ul>\n<li><a href=\"http:\/\/artigos.softonic.com.br\/como-limpar-cache-aplicativos-android\">Como limpar o cache de aplicativos?<\/a><\/li>\n<li><a href=\"http:\/\/artigos.softonic.com.br\/como-encontrar-celular-android-roubado-perdido\">Encontrar ou localizar seu celular Android roubado ou perdido<\/a><\/li>\n<\/ul>\n<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Quer fazer uma c\u00f3pia de seguran\u00e7a de SMS, contatos e aplicativos no Android de um dispositivo a outro? Hoje, n\u00f3s vamos explicar como fazer backup e restaurar todos os seus dados (SMS, contatos, aplicativos, configura\u00e7\u00f5es, documentos, m\u00fasica, fotos, etc.) sem ter que acessar o root do celular ou tablet. Configurar as op\u00e7\u00f5es de c\u00f3pia de &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/br\/backup-android-como-conservar-todos-dados-sms-contatos-aplicativos-configuracoes\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Backup no Android: Como conservar TODOS os seus dados (SMS, contatos, aplicativos, configura\u00e7\u00f5es&#8230;)&#8221;<\/span><\/a><\/p>\n","protected":false},"author":6023,"featured_media":23778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[4081,1],"tags":[153,3929,3931,3930,1255],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-23370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","category-uncategorized","tag-backup","tag-backup-android","tag-configuracoes","tag-gcloud-backup","tag-sms"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/23370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/users\/6023"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/comments?post=23370"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/23370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media\/23778"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media?parent=23370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/categories?post=23370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/tags?post=23370"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/usertag?post=23370"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/vertical?post=23370"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/content-category?post=23370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}