{"id":33588,"date":"2014-06-27T14:34:52","date_gmt":"2014-06-27T12:34:52","guid":{"rendered":"http:\/\/onsoftware.softonic.com.br\/?p=33588"},"modified":"2024-03-06T09:47:23","modified_gmt":"2024-03-06T13:47:23","slug":"jogos-japao-tendencias","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/br\/jogos-japao-tendencias\/","title":{"rendered":"Descubra as \u00faltimas tend\u00eancias de jogos do Jap\u00e3o"},"content":{"rendered":"<p>Jogos de intelig\u00eancia, clones do Flappy Bird\u2026 \u00c9 quase como aqui, mas com um toque t\u00edpico japon\u00eas. Descubra o que nossos colegas do<strong> Softonic Jap\u00e3o<\/strong> andam jogando no momento.<\/p>\n<p><a title=\"Plants vs Zombies 2 para Android\" href=\"http:\/\/plants-vs-zombies-2.softonic.com.br\/android\">Plants vs Zombies 2<\/a>, <a title=\"Monument Valley para Android\" href=\"http:\/\/monument-valley.softonic.com.br\/android\">Monument Valley<\/a>, <a title=\"Clash of Clans para Android\" href=\"http:\/\/clash-of-clans.softonic.com.br\/android\">Clash of Clans<\/a> ou\u00a0<a title=\"Farm Heroes Saga para Android\" href=\"http:\/\/farm-heroes-saga.softonic.com.br\/android\">Farm Heroes Saga<\/a> s\u00e3o alguns dos games para dispositivos m\u00f3veis mais jogados no Ocidente. Mas ser\u00e1 que os usu\u00e1rios japoneses curtem a mesma coisa? Parece que n\u00e3o, e isso porque a cultura daquele pa\u00eds \u00e9 t\u00e3o rica que tem seus pr\u00f3prios fen\u00f4menos de massa que, como n\u00e3o, tamb\u00e9m aparecem nos apps mais baixados.<\/p>\n<p>Descubra com a ajuda de Yoko, Junko, Chris, Midori e Sayaka, nossos editores do Softonic Jap\u00e3o,<strong> quais s\u00e3o os jogos que est\u00e3o bombando no pa\u00eds <\/strong>e quais eles n\u00e3o conseguem parar de jogar.<\/p>\n<h3>Yoko: Neo Mushroom Garden<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-89779\" title=\"Yoko\" src=\"\" alt=\"\" width=\"100\" height=\"100\" \/>Ultimamente jogo muito o NEO Mushroom Garden, cujo protagonista \u00e9 um personagem chamado Fungi. Mas n\u00e3o h\u00e1 apenas um. Os Fungus s\u00e3o muito variados: brancos, vermelhos, musculosos\u2026 O objetivo do jogo \u00e9\u00a0<strong>recolher v\u00e1rios deles e fazer com que cres\u00e7am e se multipliquem<\/strong>.<\/p>\n<p>O grande m\u00e9rito do t\u00edtulo \u00e9 a possibilidade de jog\u00e1-lo em partidas curt\u00edssimas de apenas 10 segundos (colher alguns Fungus e aliment\u00e1-los). Dessa forma, at\u00e9 a pessoa mais ocupada pode se divertir com ele.<\/p>\n<p>O protagonista tem uma\u00a0<strong>apar\u00eancia extremamente simples e surrealista<\/strong>, o que o transformou em um personagem muito popular no Jap\u00e3o. Podemos encontr\u00e1-lo em diversas lojas em forma de chaveiro, bonecos, camisetas&#8230; Reconhe\u00e7o que tenho em casa um Fungi de pel\u00facia e v\u00e1rios objetos tem\u00e1ticos de papelaria. Adoro o t\u00edtulo e espero que voc\u00eas tamb\u00e9m gostem.<\/p>\n<p>N\u00e3o h\u00e1 desculpa para n\u00e3o experiment\u00e1-lo. Neo Mushroom Garden est\u00e1 dispon\u00edvel\u00a0<strong>em ingl\u00eas.<\/strong><\/p>\n<p><a title=\"NEO Mushroom Garden no Google Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=jp.co.beeworks.mushroomNEO\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download do Neo Mushroom Garden para Android<\/strong><\/a><\/p>\n<p><a title=\"NEO Mushroom Garden no iTunes App Store\" href=\"https:\/\/itunes.apple.com\/app\/id855028978\"><strong>Download do Neo Mushroom Garden para iOS<\/strong><\/a><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89826\" title=\"Neo Mushroom Garden \u00e9 um divertido jogo para pessoas ocupadas\" src=\"\" alt=\"Neo Mushroom Garden \u00e9 um divertido jogo para pessoas ocupadas\" width=\"568\" height=\"441\" \/><\/p>\n<h3>Junko: Awesome Pixel Granny- classic retro game<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-89776\" title=\"Junko\" src=\"\" alt=\"\" width=\"100\" height=\"100\" \/>No Jap\u00e3o, <a title=\"Flappy Bird para Android\" href=\"http:\/\/flappy-bird.softonic.com.br\/android\">Flappy Bird<\/a> e suas alternativas s\u00e3o muito populares, mas n\u00e3o tanto como no Brasil. Pessoalmente, gosto muito desta mec\u00e2nica de jogo t\u00e3o simples, e, mesmo que n\u00e3o possa baixar o original, posso me divertir com alguns de seus <strong>clones<\/strong>.<\/p>\n<p>Entre todos eles, fico com sua vers\u00e3o japonesa, que se chama Awesome Pixel Granny- classic retro game. \u00c9 muito semelhante ao original, com a diferen\u00e7a de que o p\u00e1ssaro \u00e9 substitu\u00eddo, aqui, por uma <strong>garota em uma vassoura voadora<\/strong>.<\/p>\n<p>Essa garota com um enorme la\u00e7o vermelho no cabelo e um gato preto sobre a vassoura \u00e9 a protagonista da anima\u00e7\u00e3o\u00a0<strong>\u201c<a title=\"Majo no Takky\u016bbin no Wikip\u00e9dia\" href=\"https:\/\/pt.wikipedia.org\/wiki\/Majo_no_Takky%C5%ABbin\" target=\"_blank\" rel=\"noopener noreferrer\">Kiki\u2019s Delivery Service<\/a>\u201d <\/strong>(&#8220;O Servi\u00e7o de Entregas da Kiki&#8221;, em portugu\u00eas), <strong>de <a title=\"Hayao Miyazaki no Wikip\u00e9dia\" href=\"https:\/\/pt.wikipedia.org\/wiki\/Hayao_Miyazaki\" target=\"_blank\" rel=\"noopener noreferrer\">Hayao Miyazaki<\/a><\/strong>. Em uma cena do longa, a jovem Kiki sobe em uma vassoura at\u00e9 acabar se chocando contra um muro; e este jogo recria essa sequ\u00eancia.<\/p>\n<p>Experimente o t\u00edtulo e, sobretudo, se ainda n\u00e3o viu o filme, corra! \u00c9 uma \u00f3tima pedida!<\/p>\n<p><a title=\"Awesome Pixel Granny- classic retro game no iTunes App Store\" href=\"https:\/\/itunes.apple.com\/app\/id818335875?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download do Awesome Pixel Granny- classic retro game para iOS<\/strong><\/a><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89830\" title=\"O Servi\u00e7o de Entregas da Kiki \u00e9 um dos jogos parecidos com Flappy Bird\" src=\"\" alt=\"O Servi\u00e7o de Entregas da Kiki \u00e9 um dos jogos parecidos com Flappy Bird\" width=\"568\" height=\"489\" \/><\/p>\n<h3>Chris: AKB48 Tsuini Koushiki Otoge Demashita<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-89775\" title=\"Chris\" src=\"\" alt=\"\" width=\"100\" height=\"100\" \/>Normalmente, o que mais curto s\u00e3o jogos de quebra-cabe\u00e7a ou para exercitar a mente, mas, para este artigo, decidi apresentar um <strong>jogo de m\u00fasica <\/strong>que \u00e9 um grande representante do lado mais <a title=\"Kawaii no Wikip\u00e9dia\" href=\"http:\/\/pt.wikipedia.org\/wiki\/Kawaii\" target=\"_blank\" rel=\"noopener noreferrer\"><em>kawaii<\/em><\/a> da cultura japonesa.<\/p>\n<p>Intitulado AKB48 Tsuini Koushiki Otoge Demashita (tradu\u00e7\u00e3o: &#8220;O jogo de ritmo de AKB48 finalmente chegou&#8221;), \u00e9 o primeiro jogo oficial do popular grupo de pop japon\u00eas AKB48. Nele, voc\u00ea deve\u00a0<strong>escolher 5 dos 77 membros da <em>girl-band <\/em><\/strong>para criar seu time dos sonhos e lev\u00e1-lo ao estrelato.<\/p>\n<p>O funcionamento do jogo \u00e9 o seguinte: em cada n\u00edvel, toca uma can\u00e7\u00e3o popular do grupo, e o jogador deve pressionar bot\u00f5es para completar uma <strong>atua\u00e7\u00e3o ao vivo<\/strong>. N\u00e3o \u00e9 uma mec\u00e2nica complicada, mas exige certo senso de ritmo para jogar.<\/p>\n<p>Neste jogo, voc\u00ea n\u00e3o apenas poder\u00e1 escutar as m\u00fasicas mais famosas do AKB48 enquanto joga, mas tamb\u00e9m ver\u00e1 uma vers\u00e3o animada das garotas do grupo <strong>dan\u00e7ando as coreografias reais, <\/strong><strong>cantando e falando<\/strong>, com di\u00e1logos que variam conforme voc\u00ea joga bem ou mal.<\/p>\n<p>As can\u00e7\u00f5es do AKB48 s\u00e3o\u00a0<strong>muito famosas no Jap\u00e3o<\/strong>, todo mundo entre a adolesc\u00eancia e os vinte anos conhece as faixas. Logo, se voc\u00ea planeja viajar para o nosso pa\u00eds no futuro, recomendo que descubra alguns temas e coreografias destas meninas. Ser\u00e1 uma excelente maneira de quebrar o gelo e estreitar amizades com os jovens japoneses.<\/p>\n<p><a title=\"AKB48 Tsuini Koushiki Otoge Demashita no iOS\" href=\"https:\/\/itunes.apple.com\/app\/akb48-tsuini-gong-shi-yingedemashita\/id799368190\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download do AKB48 Tsuini Koushiki Otoge Demashita para iOS<\/strong><\/a><\/p>\n<p><a title=\"AKB48 Tsuini Koushiki Otoge Demashita no Google Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=jp.akb48game.aol\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download do AKB48 Tsuini Koushiki Otoge Demashita para Android<\/strong><\/a><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89816\" title=\"AKB48 Tsuini Koushiki Otoge Demashita \u00e9 uma das bandas mais populares entre os jovens japoneses\" src=\"\" alt=\"AKB48 Tsuini Koushiki Otoge Demashita \u00e9 uma das bandas mais populares entre os jovens japoneses\" width=\"568\" height=\"488\" \/><\/p>\n<h3>Midori: A Kuchisaki Bancho<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-89777\" title=\"Midori\" src=\"\" alt=\"\" width=\"100\" height=\"100\" \/>Mesmo que n\u00e3o seja uma especialista em jogos, curto muitos quebra-cabe\u00e7as, games de intelig\u00eancia e perguntas e respostas. Hoje, apresento a voc\u00eas um dos meus jogos favoritos de <strong>treinamento da mente<\/strong>.<\/p>\n<p>Voc\u00eas conhecem o jogo de\u00a0<em>Shiritori<\/em>? Trata-se de um game de palavras cujo t\u00edtulo em japon\u00eas significa \u201cprimeiro e \u00faltimo\u201d. Neste t\u00edtulo tradicional, muito popular entre as crian\u00e7as, voc\u00ea tem que dizer <strong>uma palavra que come\u00e7a com a \u00faltima letra da palavra que disse o jogador anterior<\/strong>.<\/p>\n<p>A vers\u00e3o app do Shiritori, que se chama A Kuchisaki Bancho, tem ares <strong>nost\u00e1lgicos <\/strong>e ainda adiciona interessantes elementos ao jogo tradicional.<\/p>\n<p>Neste caso, o her\u00f3i do game \u00e9 um jovem g\u00e2ngster. Em menos de 40 segundos, cada jogador deve dizer uma palavra correta. O limite de tempo transforma o app do Shiritori em um t\u00edtulo muito mais divertido e competitivo. Voc\u00ea s\u00f3 pode confiar no seu c\u00e9rebro. Se perder, significa que tem <strong>reflexos lentos <\/strong>e dir\u00e1 mais\u00a0de uma vez em voz alta: &#8220;como n\u00e3o me ocorreu nenhuma palavra?&#8221;<\/p>\n<p>Ainda \u00e9 dif\u00edcil imaginar a mec\u00e2nica do A Kuchisaki Bancho? Ent\u00e3o pense em um filme de <a title=\"Yakuza no Wikip\u00e9dia\" href=\"http:\/\/pt.wikipedia.org\/wiki\/Yakuza\" target=\"_blank\" rel=\"noopener noreferrer\"><em>yakuzas<\/em><\/a> misturado com o popular jogo de mesa Scramble.<\/p>\n<p><a title=\"A Kuchisaki Bancho no iTunes App Store\" href=\"https:\/\/itunes.apple.com\/app\/id827719262\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download do A Kuchisaki Bancho para iOS<\/strong><\/a><\/p>\n<p><strong><a title=\"A Kuchisaki Bancho no Google Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=jp.filament.KuchisakiBancho01\">Download do A Kuchisaki Bancho para Android<\/a><\/strong><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89819\" title=\"A Kuchisaki Bancho pede para voc\u00ea formar uma palavra com a \u00faltima letra da palavra anterior\" src=\"\" alt=\"A Kuchisaki Bancho pede para voc\u00ea formar uma palavra com a \u00faltima letra da palavra anterior\" width=\"568\" height=\"486\" \/><\/p>\n<h3>Sayaka: Onigiri shooter<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-89778\" title=\"Sayaka\" src=\"\" alt=\"\" width=\"100\" height=\"100\" \/><em>Sushi, sashimi, tempura<\/em>&#8230; O Jap\u00e3o tem muitos pratos tradicionais. Voc\u00ea conhece o onigiri? (tamb\u00e9m \u00e9 chamado de <em>omusubi<\/em> ou bola de arroz). \u00c9 feito de arroz branco modelado em forma triangular ou oval e normalmente \u00e9 envolvido em <em>nori <\/em>(algas marinhas).<\/p>\n<p>Onigiri shooter, o jogo que estou jogando agora, busca inspira\u00e7\u00e3o nesse prato popular para criar um <em><strong>shooter<\/strong><\/em>. Pode parecer estranho, mas se voc\u00ea jogar uma vez, vai entender o conceito facilmente. Assim, a arma principal \u00e9 um onigiri enorme. E no lugar de bombas, esta \u201cnave\u201d lan\u00e7a gr\u00e3os de arroz. E n\u00e3o espere ver entre os inimigos pequenos marcianos, j\u00e1 que o que h\u00e1 no game s\u00e3o camar\u00f5es, salm\u00e3o grelhado,\u00a0<em>ramen<\/em> gigante ou<em> sashimi<\/em>\u2026<\/p>\n<p>A\u00a0<strong>jogabilidade <\/strong>do\u00a0Onigiri Shooter sim que \u00e9 a mesma dos shooter tradicionais. Voc\u00ea move a nave onigiri livremente e lan\u00e7a gr\u00e3os e tigelas de arroz. Existem tr\u00eas n\u00edveis de dificuldade.<\/p>\n<p>Sei que tudo parece um pouco bizarro, mas \u00e9 extremamente divertido.<\/p>\n<p><a title=\"Onigiri Shooter no Google Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=yuga.onigiri_shooter\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download do Onigiri Shooter para Android<\/strong><\/a><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89824\" title=\"Em Onigiri Shooter, voc\u00ea controla uma nave de... Onigiri\" src=\"\" alt=\"Em Onigiri Shooter, voc\u00ea controla uma nave de... Onigiri\" width=\"568\" height=\"430\" \/><\/p>\n<h3>G\u00eaneros semelhantes em vers\u00f5es japonesas<\/h3>\n<p>Os jogos que est\u00e3o fazendo a cabe\u00e7a de nossos amigos japoneses n\u00e3o diferem muito em g\u00eanero dos que jogamos por aqui. A principal diferen\u00e7a s\u00e3o os <strong>\u00edcones e tem\u00e1ticas<\/strong>, muito mais pr\u00f3ximos \u00e0 sensibilidade japonesa: anime, bandas locais, gastronomia t\u00edpica\u2026<\/p>\n<p style=\"text-align: right\"><em>[Artigo original em espanhol]<\/em><\/p>\n<h4>\n<p style=\"text-align: left\">Leia tamb\u00e9m:<\/p>\n<ul>\n<li><a title=\"PES 2015: o simulador de futebol da Konami est\u00e1 no padr\u00e3o FIFA?\" href=\"http:\/\/artigos.softonic.com.br\/pes-2015-preview\">PES 2015: o simulador de futebol da Konami est\u00e1 no padr\u00e3o FIFA?<\/a><\/li>\n<li><a title=\"Jogos de simula\u00e7\u00e3o que passaram dos limites\" href=\"http:\/\/artigos.softonic.com.br\/jogos-simulacao-que-passaram-dos-limites\">Jogos de simula\u00e7\u00e3o que passaram dos limites<\/a><\/li>\n<\/ul>\n<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Jogos de intelig\u00eancia, clones do Flappy Bird\u2026 \u00c9 quase como aqui, mas com um toque t\u00edpico japon\u00eas. Descubra o que nossos colegas do Softonic Jap\u00e3o andam jogando no momento. Plants vs Zombies 2, Monument Valley, Clash of Clans ou\u00a0Farm Heroes Saga s\u00e3o alguns dos games para dispositivos m\u00f3veis mais jogados no Ocidente. Mas ser\u00e1 que &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/br\/jogos-japao-tendencias\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Descubra as \u00faltimas tend\u00eancias de jogos do Jap\u00e3o&#8221;<\/span><\/a><\/p>\n","protected":false},"author":6017,"featured_media":33601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-33588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/33588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/users\/6017"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/comments?post=33588"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/33588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media\/33601"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media?parent=33588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/categories?post=33588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/tags?post=33588"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/usertag?post=33588"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/vertical?post=33588"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/content-category?post=33588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}