{"id":40950,"date":"2014-10-16T16:00:44","date_gmt":"2014-10-16T14:00:44","guid":{"rendered":"http:\/\/onsoftware.softonic.com.br\/?p=40950"},"modified":"2024-03-06T09:36:30","modified_gmt":"2024-03-06T13:36:30","slug":"electronic-arts-combate-contrabando-moedas-virtuais-fifa-15-ultimate-team","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/br\/electronic-arts-combate-contrabando-moedas-virtuais-fifa-15-ultimate-team\/","title":{"rendered":"Electronic Arts come\u00e7a a agir contra o contrabando de moedas virtuais"},"content":{"rendered":"<p>At\u00e9 ent\u00e3o, FIFA 15 apenas ensaiava mostrar o cart\u00e3o amarelo aos usu\u00e1rios que n\u00e3o jogavam limpo. Pois agora, a Electronic Arts resolveu agir <strong>e promete banir os jogadores que compram moedas no modo Ultimate Team<\/strong>.<\/p>\n<p>A EA publicou em seu Twitter oficial uma imagem (veja abaixo) com a seguinte mensagem: &#8220;N\u00e3o seja expulso! Se voc\u00ea compra moedas virtuais, voc\u00ea coloca a sua conta em risco em FIFA 15 Ultimate Team&#8221;.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"FIFA 15 advert\u00eancia\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/10\/fifa-151-568x266.jpg\" alt=\"FIFA 15 advert\u00eancia\" width=\"568\" height=\"266\" \/><\/p>\n<p style=\"text-align: left\">A imagem faz parte de uma campanha da EA Sports para combater o mercado negro que se esconde no modo Ultimate Team. <strong>Muitos jogadores contrabandeiam as moedas virtuais para se beneficiar nesta modalidade<\/strong>. No entanto, a empresa n\u00e3o explicou como faria para &#8220;ca\u00e7as&#8221; aqueles que utilizam deste expediente.<\/p>\n<p style=\"text-align: left\">E se voc\u00ea acha que essa medida da EA \u00e9 um exagero, repense: muitos jogadores do Ultimate Team est\u00e3o viciados em comprar moedas virtuais, para que tenham as melhores cartas e ganhem consider\u00e1vel vantagem sobre os advers\u00e1rios, frustrando a experi\u00eancia de jogo de muitos.<\/p>\n<p style=\"text-align: right\"><em>Fonte: <a href=\"https:\/\/twitter.com\/EASPORTSFIFA\/status\/522349999217475585\" target=\"_blank\" rel=\"noopener noreferrer\">EA Sports<\/a><\/em><\/p>\n<p style=\"text-align: left\">\n<h4 style=\"text-align: left\">Veja tamb\u00e9m<\/h4>\n<p style=\"text-align: left\">\n<ul>\n<li><a title=\"FIFA 15 vs PES 2015: qual \u00e9 o melhor jogo de futebol?\" href=\"http:\/\/artigos.softonic.com.br\/fifa-15-pes-2015-melhor-jogo-futebol\">FIFA 15 vs PES 2015: qual \u00e9 o melhor jogo de futebol?<\/a><\/li>\n<li><a title=\"FIFA Ultimate Team: truques para gerenciar melhor seu time no FIFA 15\" href=\"http:\/\/artigos.softonic.com.br\/fifa-ultimate-team-truques-gerenciar-melhor-time\">FIFA Ultimate Team: truques para gerenciar melhor seu time no FIFA 15<\/a><\/li>\n<li><a title=\"FIFA 15: Dicas e truques para ganhar todas as partidas\" href=\"http:\/\/artigos.softonic.com.br\/fifa-15-dicas-truques-ganhar-todas-partidas\">FIFA 15: Dicas e truques para ganhar todas as partidas<\/a><\/li>\n<\/ul>\n<p>Acompanhe o Softonic nas redes sociais: curta a\u00a0<a href=\"https:\/\/www.facebook.com\/SoftonicBrasil\">fanpage do Softonic<\/a> no Facebook e siga <a href=\"https:\/\/twitter.com\/softonic_br\">@softonic_br<\/a> no Twitter.<\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 ent\u00e3o, FIFA 15 apenas ensaiava mostrar o cart\u00e3o amarelo aos usu\u00e1rios que n\u00e3o jogavam limpo. Pois agora, a Electronic Arts resolveu agir e promete banir os jogadores que compram moedas no modo Ultimate Team. A EA publicou em seu Twitter oficial uma imagem (veja abaixo) com a seguinte mensagem: &#8220;N\u00e3o seja expulso! Se voc\u00ea &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/br\/electronic-arts-combate-contrabando-moedas-virtuais-fifa-15-ultimate-team\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Electronic Arts come\u00e7a a agir contra o contrabando de moedas virtuais&#8221;<\/span><\/a><\/p>\n","protected":false},"author":6025,"featured_media":40952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[4099],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-40950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-app-subdomain-redirectionfifa-15"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/40950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/users\/6025"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/comments?post=40950"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/40950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media\/40952"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media?parent=40950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/categories?post=40950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/tags?post=40950"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/usertag?post=40950"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/vertical?post=40950"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/content-category?post=40950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}