{"id":5895,"date":"2012-03-22T09:36:05","date_gmt":"2012-03-22T09:36:05","guid":{"rendered":"http:\/\/onsoftware.softonic.com.br\/?p=5895"},"modified":"2024-03-06T10:23:19","modified_gmt":"2024-03-06T14:23:19","slug":"novo-angry-birds-space","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/br\/novo-angry-birds-space\/","title":{"rendered":"Conhe\u00e7a o novo Angry Birds Space"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5897\" title=\"Angry Birds Space\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/angrybirds_space01.jpg\" alt=\"\" width=\"270\" height=\"191\" \/>Depois de muita espera, finalmente foi lan\u00e7ado o novo jogo da s\u00e9rie Angry Birds. Desde o <a href=\"http:\/\/onsoftware.softonic.com.br\/trailer-angry-birds-space\">anuncio oficial<\/a> que os f\u00e3s da saga se perguntam como seria o novo cap\u00edtulo da guerra entre p\u00e1ssaros e porcos.<\/p>\n<p>Diferentemente de <a href=\"http:\/\/www.softonic.com.br\/s\/angry-birds-season:celular\" target=\"_blank\" rel=\"noopener noreferrer\">Angry Birds Seasons<\/a> e <a href=\"http:\/\/www.softonic.com.br\/s\/angry-birds-rio:celular\" target=\"_blank\" rel=\"noopener noreferrer\">Angry Birds Rio<\/a>, <a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\" target=\"_blank\" rel=\"noopener noreferrer\">Angry Birds Space<\/a> foge da mesmice de incluir novos p\u00e1ssaros e <strong>inova completamente o sistema de jogo<\/strong>. O campo de batalha foi levado ao espa\u00e7o, onde as leis da gravidade influenciam de uma forma distinta da que estamos acostumados.<\/p>\n<p><!--more--><\/p>\n<h3>Modo in\u00e9dito de jogo<\/h3>\n<address style=\"width: 300px;float: right;margin-left: 15px;margin-bottom: 15px;background-color: #d5eeee\">\n<ul>\n<h5>Fa\u00e7a o download:<\/h5>\n<p><strong>\u00bb<\/strong> <a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\" target=\"_blank\" rel=\"noopener noreferrer\">Angry Birds Space (para Android)<\/a><\/p>\n<p><strong>\u00bb<\/strong> <a href=\"http:\/\/angry-birds-space.softonic.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Angry Birds Space (para PC)<\/a><\/p>\n<p><strong>\u00bb<\/strong> <a href=\"http:\/\/angry-birds-space-wallpaper.softonic.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Papel de Parede do Angry Birds Space<\/a><\/ul>\n<\/address>\n<p>Agora, os p\u00e1ssaros voam em linha reta e sofrem influ\u00eancia dos <strong>campos gravitacionais<\/strong> de planetas e asteroides.<\/p>\n<p>Isso significa que o seu p\u00e1ssaro pode ser desviado para qualquer dire\u00e7\u00e3o, at\u00e9 mesmo para cima. Outra coisa a ser levada em considera\u00e7\u00e3o \u00e9 a trajet\u00f3ria dos destro\u00e7os das explos\u00f5es.<\/p>\n<p><object><\/object><\/p>\n<p>Para mais detalhes, voc\u00ea pode conferir o <a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-trailer-da-nasa-do-angry-birds-space-11641\" target=\"_blank\" rel=\"noopener noreferrer\">trailer do Angry Birds Space<\/a>, gravado na <strong>Esta\u00e7\u00e3o Espacial Internacional (ISS)<\/strong> e com uma explica\u00e7\u00e3o de um astronauta da NASA de como funciona a mec\u00e2nica do jogo.<\/p>\n<h3>Novos p\u00e1ssaros<\/h3>\n<p>E claro que novo t\u00edtulo do Angry Birds n\u00e3o podia deixar de apresentar p\u00e1ssaros novos. S\u00e3o eles:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5901 alignnone\" title=\"Lazer Bird - Angry Birds\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/Lazer-Bird.png\" alt=\"\" width=\"70\" height=\"70\" \/> <a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-angry-birds-space-lazer-bird-11759\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Lazer Bird<\/strong><\/a>: \u00e9 capaz de mudar a sua trajet\u00f3ria em pleno voo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5902\" title=\"Ice Bird - Angry Birds Space\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/IceBird.png\" alt=\"\" width=\"70\" height=\"70\" \/><a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-angry-birds-space-ice-bird-11757\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Ice Bird<\/strong><\/a>: congela a \u00e1rea onde \u00e9 arremessado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5903\" title=\"Terence - Angry Birds Space\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/Terence.png\" alt=\"\" width=\"70\" height=\"70\" \/><a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-angry-birds-space-terence-11761\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Terence<\/strong><\/a>: a vers\u00e3o espacial do Big Brother Bird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5904\" title=\"Bomb - Angry Birds Space\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/Bomb.png\" alt=\"\" width=\"70\" height=\"70\" \/><a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-angry-birds-space-bomb-11758\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Bomb<\/strong><\/a>: a vers\u00e3o espacial do Black Bird.<\/p>\n<p>E claro que os tradicionais Red Bird e Blue Birds continuam no game, mas de visual novo:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5905\" title=\"Red Bird - Angry Birds Space\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/Redx.png\" alt=\"\" width=\"70\" height=\"70\" \/><a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-angry-birds-space-red-bird-11760\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Red Bird<\/strong><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5906\" title=\"Blue Birds - Space Birds Space\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/03\/Blues.png\" alt=\"\" width=\"70\" height=\"70\" \/><a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\/video\/angry-birds-space-angry-birds-space-blue-birds-11756\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Blue Birds<\/strong><\/a><\/p>\n<p><strong>E a\u00ed, bateu uma curiosidade para conhecer o novo Angry Birds Space? Ent\u00e3o confira a nossa <a href=\"http:\/\/angry-birds-space.softonic.com.br\/android\" target=\"_blank\" rel=\"noopener noreferrer\">an\u00e1lise para Android<\/a>, conhe\u00e7a o <a href=\"http:\/\/angry-birds-space.softonic.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Angry Birds Space para PC<\/a> e comece a jogar agora mesmo!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de muita espera, finalmente foi lan\u00e7ado o novo jogo da s\u00e9rie Angry Birds. Desde o anuncio oficial que os f\u00e3s da saga se perguntam como seria o novo cap\u00edtulo da guerra entre p\u00e1ssaros e porcos. Diferentemente de Angry Birds Seasons e Angry Birds Rio, Angry Birds Space foge da mesmice de incluir novos p\u00e1ssaros &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/br\/novo-angry-birds-space\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Conhe\u00e7a o novo Angry Birds Space&#8221;<\/span><\/a><\/p>\n","protected":false},"author":6005,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[97,620,600,4115],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-5895","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-angry-birds","tag-angry-birds-celular","tag-angry-birds-space","tag-app-subdomain-redirectionangry-birds"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/5895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/users\/6005"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/comments?post=5895"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/5895\/revisions"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media?parent=5895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/categories?post=5895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/tags?post=5895"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/usertag?post=5895"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/vertical?post=5895"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/content-category?post=5895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}