{"id":6576,"date":"2012-05-02T15:24:40","date_gmt":"2012-05-02T15:24:40","guid":{"rendered":"http:\/\/onsoftware.softonic.com.br\/?p=6576"},"modified":"2024-03-06T10:22:46","modified_gmt":"2024-03-06T14:22:46","slug":"como-criar-temas-para-google-chrome","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/br\/como-criar-temas-para-google-chrome\/","title":{"rendered":"Como criar temas para o Google Chrome"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-6596\" title=\"Como criar tema para o Google Chrome\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/05\/criar-tema-google-chrome.jpg\" alt=\"\" width=\"300\" height=\"147\" \/>Faz algum tempo que o <a href=\"http:\/\/google-chrome.softonic.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Google Chrome<\/a> \u00e9 o navegador mais usado no Brasil. Uma das caracter\u00edsticas mais bacanas do programa \u00e9 que d\u00e1 para mudar o visual usando as centenas de temas dispon\u00edveis na <a title=\"Galeria de Temas do Google Chrome\" href=\"https:\/\/chrome.google.com\/webstore\/category\/themes?hl=pt-br\" target=\"_blank\" rel=\"noopener noreferrer\">galeria do Chrome<\/a>.<\/p>\n<p>Voc\u00ea passou horas procurando um tema e n\u00e3o achou nada para deixar o browser com a sua cara? N\u00e3o tem que se preocupar mais com isso. A <a title=\"Meu Tema do Chrome\" href=\"http:\/\/meu-tema-do-chrome.softonic.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">extens\u00e3o Meu Tema do Chrome<\/a> soluciona esse probleminha em apenas quatro passos e deixa que voc\u00ea crie seus pr\u00f3prios temas e compartilhe com toda a comunidade Google. Quer saber como? Ent\u00e3o continue lendo o artigo.<!--more--><\/p>\n<h4>Como criar temas para o Chrome em 4 passos<\/h4>\n<p><strong>1.<\/strong> O primeiro passo, obviamente, \u00e9 instalar o <a title=\"Meu Tema do Chrome\" href=\"http:\/\/meu-tema-do-chrome.softonic.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">Meu Tema do Chrome<\/a>. Depois disso, clique no \u00edcone da extens\u00e3o que aparece na p\u00e1gina de in\u00edcio do Chrome e aperte o bot\u00e3o &#8220;Iniciar a cria\u00e7\u00e3o de seu tema&#8221;.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6584\" title=\"Meu Tema do Chrome\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-2.jpg\" alt=\"\" width=\"600\" height=\"475\" \/><\/p>\n<p><strong>2.<\/strong> Fa\u00e7a o upload da imagem que voc\u00ea quer por como fundo do tema ou, se preferir, tire uma foto usando sua webcam. Ajuste a posi\u00e7\u00e3o da imagem para ficar perfeita.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6581\" title=\"Fa\u00e7a o upload da imagem para o tema do Chrome\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-4.jpg\" alt=\"\" width=\"600\" height=\"396\" \/><\/p>\n<p><strong>3.<\/strong> Chegou a hora de definir as cores para a janela do navegador, da aba que voc\u00ea est\u00e1 usando e das abas abertas que aparecem em segundo plano. Se preferir, pode deixar que o aplicativo escolha uma combina\u00e7\u00e3o de cores especial para voc\u00ea.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6582\" title=\"Selecione o esquema de cores do tema do Chrome\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-13.jpg\" alt=\"\" width=\"600\" height=\"480\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-13.jpg 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-13-300x240.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>4.<\/strong> Por \u00faltimo, voc\u00ea deve escolher um nome para o tema que vai criar e, se quiser, escrever uma descri\u00e7\u00e3o. Aperte no bot\u00e3o \u201cCriar meu tema\u201d e deixe que a extens\u00e3o cuide do resto. Agora s\u00f3 falta instalar e publicar o seu tema para compartilh\u00e1-lo com outras pessoas na galeria do Chrome.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6585\" title=\"Tema instalado no Chrome\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-12.jpg\" alt=\"\" width=\"600\" height=\"480\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-12.jpg 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/7\/2012\/05\/meutema-12-300x240.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>E a\u00ed, est\u00e1 esperando o qu\u00ea para mandar o link dos seus temas para a gente?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faz algum tempo que o Google Chrome \u00e9 o navegador mais usado no Brasil. Uma das caracter\u00edsticas mais bacanas do programa \u00e9 que d\u00e1 para mudar o visual usando as centenas de temas dispon\u00edveis na galeria do Chrome. Voc\u00ea passou horas procurando um tema e n\u00e3o achou nada para deixar o browser com a sua &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/br\/como-criar-temas-para-google-chrome\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Como criar temas para o Google Chrome&#8221;<\/span><\/a><\/p>\n","protected":false},"author":6003,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[4081,1],"tags":[552,685],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-6576","post","type-post","status-publish","format-standard","hentry","category-how-to","category-uncategorized","tag-google-chrome","tag-tema-google-chrome"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/6576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/users\/6003"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/comments?post=6576"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/posts\/6576\/revisions"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/media?parent=6576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/categories?post=6576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/tags?post=6576"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/usertag?post=6576"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/vertical?post=6576"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/br\/wp-json\/wp\/v2\/content-category?post=6576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}