{"id":46398,"date":"2014-03-05T14:31:31","date_gmt":"2014-03-05T13:31:31","guid":{"rendered":"http:\/\/onsoftware.softonic.de\/?p=46398"},"modified":"2024-03-08T06:19:47","modified_gmt":"2024-03-08T05:19:47","slug":"yahoo-blockiert-die-anmeldung-mit-facebook-und-google-05-03-2014","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/de\/yahoo-blockiert-die-anmeldung-mit-facebook-und-google-05-03-2014\/","title":{"rendered":"Yahoo! blockiert die Anmeldung mit Facebook und Google"},"content":{"rendered":"<p><a href=\"http:\/\/news.softonic.de\/b\/yahoo\" target=\"_self\" rel=\"noopener noreferrer\">Yahoo!<\/a> schaltet die M\u00f6glichkeit zur Anmeldung mit einem Facebook- oder Google-Konto ab. In Zukunft m\u00fcssen sich Nutzer <strong>direkt bei Yahoo!<\/strong> registrieren, um die Dienste des Anbieters nutzen zu k\u00f6nnen. Die Umstellung erfolgt <strong>nach und nach<\/strong>, ist aber f\u00fcr alle Produkte geplant.<\/p>\n<p>In einer Stellungnahme gegen\u00fcber der Nachrichtenagentur <a href=\"http:\/\/www.reuters.com\/article\/2014\/03\/05\/us-yahoo-login-idUSBREA2407820140305\" target=\"_blank\" rel=\"noopener noreferrer\">Reuters <\/a>hat die Firma bekannt gegeben, man wolle mit dem Schritt das eigene Angebot verbessern und personalisierter gestalten. F\u00fcr Nutzer bedeut das vor allem, dass sie sich ein <strong>Yahoo!-Konto<\/strong> <strong>anlegen <\/strong>m\u00fcssen, um Dienste wie <em>Yahoo! Mail<\/em>, <em>Finance<\/em> und <em>Flickr<\/em> weiter nutzen zu k\u00f6nnen.<\/p>\n<p>Yahoo! z\u00e4hlt nach YouTube, Google und Facebook zu den <strong>vier gro\u00dfen Internetriesen<\/strong>. Als einziger unter diesen erlaubt Yahoo! momentan noch die Anmeldung mit einem <strong>fremden Konto<\/strong>. Ein Zeitfenster f\u00fcr die geplante Umstellung hat Yahoo! nicht angegeben.<\/p>\n<h3>Passende Artikel<\/h3>\n<ul>\n<li><a href=\"http:\/\/news.softonic.de\/yahoo-mail-neue-version-liest-e-mails-mit\" target=\"_self\" rel=\"noopener noreferrer\">Yahoo Mail: Neue Version liest E-Mails mit<\/a><\/li>\n<li><a href=\"http:\/\/artikel.softonic.de\/software-sterben-2013-diese-programme-haben-sich-in-diesem-jahr-verabschiedet-30-12-2013\" target=\"_self\" rel=\"noopener noreferrer\">Software-Sterben 2013: Diese Programme haben sich in diesem Jahr verabschiedet<\/a><\/li>\n<li><a href=\"http:\/\/artikel.softonic.de\/ask-bing-icq-yahoo-co-versehentlich-installierte-suchmaschinen-aus-mozilla-firefox-loschen\" target=\"_self\" rel=\"noopener noreferrer\">Ask, Bing, ICQ, Yahoo &amp; Co.: Versehentlich installierte Suchmaschinen aus Mozilla Firefox l\u00f6schen<\/a><\/li>\n<\/ul>\n<p><em>Quelle: <a href=\"http:\/\/www.reuters.com\/article\/2014\/03\/05\/us-yahoo-login-idUSBREA2407820140305\" target=\"_blank\" rel=\"noopener noreferrer\">Reuters<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yahoo! schaltet die M\u00f6glichkeit zur Anmeldung mit einem Facebook- oder Google-Konto ab. In Zukunft m\u00fcssen sich Nutzer direkt bei Yahoo! registrieren, um die Dienste des Anbieters nutzen zu k\u00f6nnen. Die Umstellung erfolgt nach und nach, ist aber f\u00fcr alle Produkte geplant. In einer Stellungnahme gegen\u00fcber der Nachrichtenagentur Reuters hat die Firma bekannt gegeben, man wolle &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/de\/yahoo-blockiert-die-anmeldung-mit-facebook-und-google-05-03-2014\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Yahoo! blockiert die Anmeldung mit Facebook und Google&#8221;<\/span><\/a><\/p>\n","protected":false},"author":7038,"featured_media":46399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[3383],"tags":[3175,364,769,94,99,770],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-46398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-app-subdomain-redirectionfacebook","tag-facebook","tag-flickr","tag-google","tag-yahoo","tag-yahoo-mail"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/46398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/users\/7038"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/comments?post=46398"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/46398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media\/46399"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media?parent=46398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/categories?post=46398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/tags?post=46398"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/usertag?post=46398"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/vertical?post=46398"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/content-category?post=46398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}