{"id":46728,"date":"2014-03-10T11:45:35","date_gmt":"2014-03-10T10:45:35","guid":{"rendered":"http:\/\/onsoftware.softonic.de\/?p=46728"},"modified":"2024-03-08T06:19:19","modified_gmt":"2024-03-08T05:19:19","slug":"so-halt-man-windows-xp-nach-dem-supportende-2014-virenfrei-10-03-2014","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/de\/so-halt-man-windows-xp-nach-dem-supportende-2014-virenfrei-10-03-2014\/","title":{"rendered":"So h\u00e4lt man Windows XP nach dem Supportende 2014 virenfrei"},"content":{"rendered":"<p>Microsoft bringt <strong>keine neuen Aktualisierungen und Sicherheitspatches f\u00fcr Windows XP<\/strong>, was  das System immer anf\u00e4lliger f\u00fcr Sicherheitsrisiken macht. Man kann Windows XP zwar auch nach dem <a title=\"Windows XP stirbt\" href=\"http:\/\/news.softonic.de\/windows-xp-stirbt-am-8-april-microsoft-stellt-auch-support-fur-security-essentials-ein-09-01-2014\" target=\"_self\" rel=\"noopener noreferrer\">Supportende<\/a> behalten, ohne Sicherheitsma\u00dfnahmen ist das aber gef\u00e4hrlich. Wer die folgenden Tipps beachtet,  kann sein <strong>XP gegen Viren und andere Bedrohungen<\/strong> sch\u00fctzen.<\/p>\n<p>Microsoft selbst bietet nur eine L\u00f6sung: <a title=\"Auf Windows 8.1 umziehen\" href=\"http:\/\/artikel.softonic.de\/pcmover-express-so-ziehen-sie-mit-windows-xp-auf-windows-7-und-8-um-07-03-2014\" target=\"_self\" rel=\"noopener noreferrer\">Auf Windows 8.1 umziehen<\/a>.  Aber ein Umzug hat immer auch Nachteile: Man muss Geld zahlen, ein  neues System erlernen und die alten Anwendungen funktionieren nicht mehr.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Windows XP Virengefahr\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/infect.jpg\" alt=\"\" width=\"568\" height=\"418\" \/><\/p>\n<p style=\"text-align: center\"><em>Prozentzahl der infizierten Rechner: XP ist angreifbarer. (Quelle: <\/em><a href=\"http:\/\/blogs.technet.com\/b\/security\/archive\/2013\/08\/15\/the-risk-of-running-windows-xp-after-support-ends.aspx\"><em>Microsoft<\/em><\/a><em>)<\/em><\/p>\n<h3>\u00dcberpr\u00fcfen, ob man die letzte gro\u00dfe XP-Aktualisierung hat<\/h3>\n<p>Zun\u00e4chst sollte man \u00fcberpr\u00fcfen, <strong>welche Version von Windows XP\u00a0 auf dem Rechner l\u00e4uft<\/strong>. Am schnellsten geht das folgenderma\u00dfen: <em>Start &gt; Ausf\u00fchren<\/em> und dann <em>winver <\/em>eintippen. Enter dr\u00fccken und schon erscheint ein Kasten mit der XP-Version, direkt nach Version 5.1 in der Klammer:<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Windows Version feststellen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/xpwinver.gif\" alt=\"\" width=\"568\" height=\"354\" \/><\/p>\n<p style=\"text-align: center\"><em>Dieses XP braucht nun keinen Service-Pack mehr: SP3 wurde erfolgreich installiert.<\/em><\/p>\n<p style=\"text-align: left\">Die neueste Version hat <a title=\"Windows XP Service Pack\" href=\"windows-xp-service-pack-3.softonic.de\" target=\"_self\" rel=\"noopener noreferrer\">Service-Pack 3<\/a> installiert. Das Service-Pack bringt viele Windows-Aktualisierungen\u00a0f\u00fcr XP. Erscheint etwas anderes, etwa Service-Pack 1 oder\u00a0<a title=\"Windows XP Service Pack 2\" href=\"http:\/\/windows-xp-service-pack.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Service-Pack 2<\/a>, muss man erst das System aktualisieren, um sich so vor schlimmeren Infizierungen zu sch\u00fctzen.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Service Pack und Infizierungen durch Viren\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/sp2-sp3.jpg\" alt=\"\" width=\"491\" height=\"285\" \/><\/p>\n<p style=\"text-align: center\"><em>Wozu aktualisieren? XP SP2 wird leichter infiziert als XP SP3. (Quelle: <\/em><a href=\"http:\/\/www.computerworld.com\/s\/article\/9243660\/Windows_XP_infection_rate_may_jump_66_after_patches_end_in_April\"><em>Computerworld<\/em><\/a><em>)<\/em><\/p>\n<h3>Die letzten verf\u00fcgbaren Aktualisierungen installieren<\/h3>\n<p style=\"text-align: left\">Auch  wenn Windows keine neuen Aktualisierungen mehr f\u00fcr XP ver\u00f6ffentlicht,  k\u00f6nnen die alten noch \u00fcber Windows Update heruntergeladen werden. Am  besten installiert man sich alle verf\u00fcgbaren Updates \u00fcber <em>Systemsteuerung &gt; Aktualisierungen<\/em>. Da ist dann auch Service-Pack 1, 2 und 3 dabei.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Windows XP Update\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/xpupdate.jpg\" alt=\"\" width=\"568\" height=\"319\" \/><\/p>\n<p style=\"text-align: center\"><em>Die alten XP-Aktualisierungen kann man auf der Website von Windows heruntergeladen.<\/em><\/p>\n<p>Alle Aktualisierungen auf einmal kann man auch \u00fcber <a href=\"http:\/\/download.wsusoffline.net\/wsusoffline89.zip\">WSUS<\/a> herunterladen. Dieses Tool, das ganze Aktualisierungspakete erstellt,  kann auch offline angewendet werden. Die Version 8.9 ist die letzte mit  XP kompatible: einfach das Betriebssystem markieren, die Sprache  ausw\u00e4hlen und auf <em>Start<\/em> klicken.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"WSUS\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/wsus-screen.jpg\" alt=\"\" width=\"586\" height=\"489\" \/><\/p>\n<p style=\"text-align: center\"><em>Die Version 8.9 von <\/em><a href=\"http:\/\/download.wsusoffline.net\/wsusoffline89.zip\"><em>WSUS<\/em><\/a><em> l\u00e4dt XP-Aktualisierungen herunter und entpackt sie.<\/em><\/p>\n<p>Meiner  Meinung nach ist WSUS die sicherere Variante, kann man XP doch auch  offline bedienen und so Eindringlinge w\u00e4hrend der Aktualisierung  vermeiden. Ebenfalls zu empfehlen ist ein H\u00e4kchen bei .NET Framework zu  machen,\u00a0ein Plugin, das zum korrekten Betrieb der Programme unbedingt notwendig ist.<\/p>\n<h3>Internet Explorer aktualisieren und Alternativ-Browser hinzuf\u00fcgen<\/h3>\n<p style=\"text-align: left\">Windows XP wurde mit\u00a0<a href=\"http:\/\/articulos.softonic.com\/usuarios-de-internet-explorer-6-la-tribu-perdida\">Internet Explorer 6<\/a> vertrieben, einem Browser, der heutzutage als unsicher gilt und mit den  meisten Websites nicht kompatibel ist. Um zu erfahren, welche  IE-Version man benutzt, sieht man am besten im Men\u00fc\u00a0unter <em>Hilfe &gt; \u00dcber <\/em>den Browser. Sieht das dann so aus, handelt es sich um den gef\u00fcrchteten Internet Explorer 6.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Internet Explorer 6\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/ie6.jpg\" alt=\"\" width=\"568\" height=\"392\" \/><\/p>\n<p style=\"text-align: center\"><em>Der unverwechselbare Internet Explorer 6. (Quelle: Wikipedia)<\/em><\/p>\n<p>Handelt es sich beim verwendeten IE um die Version 6.0, sollte\u00a0man sofort auf Internet Explorer 8, die letzte verf\u00fcgbare Version, aktualisieren. Diese ist ziemlich sicher und dar\u00fcber hinaus mit den meisten Websites\u00a0kompatibel. Mit einem Kick <a title=\"IE 8\" href=\"http:\/\/internet-explorer-8.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">hier<\/a> kann man sie ganz einfach herunterladen. IE 9 gibt es nicht f\u00fcr XP und  wir wissen auch nicht, wie man ihn auf Windows XP zum Laufen bekommt.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"IE 8\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2010\/06\/comple.png\" alt=\"\" width=\"599\" height=\"372\" \/><\/p>\n<p style=\"text-align: center\"><a title=\"IE 8\" href=\"http:\/\/internet-explorer-8.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\"><em>IE8<\/em><\/a><em> ist die letzte Version des Internet Explorers f\u00fcr Windows XP; IE9 gibt es nicht f\u00fcr XP.<br \/>\n<\/em><\/p>\n<p>Gleichzeitig sollte man sich aber einen alternativen Browser herunterladen. Da gibt es eine gro\u00dfe Auswahl:\u00a0<a title=\"Chrome\" href=\"http:\/\/google-chrome.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Chrome<\/a>,\u00a0<a title=\"Firefox\" href=\"http:\/\/firefox.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Firefox<\/a> und\u00a0<a title=\"Opera\" href=\"http:\/\/opera.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Opera<\/a> sind  die besten Alternativen. Man surft schnell und effizient und erspart sich einen Haufen Malware.<\/p>\n<h3>Unn\u00f6tige und veraltete Programme deinstallieren<\/h3>\n<p>Eine andere Form zum Senken der eigenen Verletzbarkeit und zum Beschleunigen von Windows ist das\u00a0Entfernen von Programmen,  die man nicht mehr braucht und die ein Risiko f\u00fcr die Sicherheit des  Rechners bedeuten. Am schnellsten geht das mit\u00a0<a title=\"CCleaner\" href=\"http:\/\/ccleaner.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">CCleaner<\/a> oder\u00a0<a title=\"Revo Uninstaller\" href=\"http:\/\/revo-uninstaller.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Revo Uninstaller<\/a>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Revo Uninstaller\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/revo.jpg\" alt=\"\" width=\"568\" height=\"407\" \/><\/p>\n<p style=\"text-align: center\"><a title=\"Revo Uninstaller\" href=\"http:\/\/revo-uninstaller.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\"><em>Revo Uninstaller<\/em><\/a><em> ist ein sehr leistungsstarkes Deinstallationsprogramm, das mit Windows XP kompatibel ist.<\/em><\/p>\n<p>Man kann aber auch nicht mehr genutzte Programme und Serviceleistungen <a title=\"Programme aus dem Autostart entfernen\" href=\"http:\/\/artikel.softonic.de\/gewusst-wie-autostarteintrage-aus-windows-7-vista-und-xp-entfernen\" target=\"_self\" rel=\"noopener noreferrer\">vom Autostart entfernen<\/a>,  das bedeutet\u00a0weniger Programme, die automatisch starten und den  Arbeitsspeicher unn\u00f6tig belasten, und\u00a0weniger Schwachstellen im  Betriebssystem. Hierbei gilt immer zu beachten: Man sollte alle  laufenden Programme kennen.<\/p>\n<h3>Aktualisierungsprogramm installieren<\/h3>\n<p>Doch  man muss nicht nur daf\u00fcr sorgen, dass das System aktualisiert ist, auch  die Programme m\u00fcssen auf dem neuesten Stand sein. Ein Programm in  einer veralteten Version kann M\u00e4ngel oder Sicherheitsrisiken aufweisen  und zum Hintert\u00fcrchen f\u00fcr Viren werden.<\/p>\n<p>Einige Hilfsprogramme sp\u00fcren Aktualisierungen auf und machen ihr Herunterladen m\u00f6glich. Eine der besten Funktionen von <a title=\"Softonic f\u00fcr Windows\" href=\"http:\/\/softonic-fuer-windows.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Softonic for Windows<\/a> kann  genau das:\u00a0veraltete Programme aktualisieren. Mit einem schnellen  System-Scan und einem Vergleich mit der Datenbank von Softonic geht das  ganz einfach.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Softonic f\u00fcr Windows\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/sfw.jpg\" alt=\"Softonic f\u00fcr Windows\" width=\"509\" height=\"309\" \/><\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/softonic-para-windows.softonic.com\/\"><em>Softonic for Windows<\/em><\/a><em> entdeckt alte Versionen und hilft bei deren Aktualisierung unter XP.<\/em><\/p>\n<p>Softonic  f\u00fcr Windows funktioniert hierbei wie ein Programm-Manager, der au\u00dfer  Informationen zu liefern auch bei der Aktualisierung der Programme hilft  und die Installierung neuer \u2013 mit Windows XP kompatibler\u00a0\u2013Programme  erst m\u00f6glich macht.<\/p>\n<h3>Ein mit Windows XP kompatibles Antivirusprogramm installieren<\/h3>\n<p>Microsoft Security Essentials, das offizielle Antivirusprogramm von Microsoft, erh\u00e4lt <a title=\"Microsoft Security Essentials\" href=\"http:\/\/news.softonic.de\/microsoft-verlangert-updates-fur-windows-xp-security-essentials-bis-2015-16-01-2014\" target=\"_self\" rel=\"noopener noreferrer\">ab dem 14. Juli 2015<\/a> keine Aktualisierungen mehr f\u00fcr XP. Ab diesem Zeitpunkt f\u00e4llt die letzte Sicherheitsbastion von Microsoft.<\/p>\n<p>Aber  kein Grund zum Verzweifeln: Die meisten Antivirusprogramme werden noch  Jahre lang mit Windows XP kompatibel sein. Im gro\u00dfen <a title=\"Antiviren-Vergleich 2013\" href=\"http:\/\/artikel.softonic.de\/antivirus-vergleich-2014-besten-programme-fur-optimalen-schutz-kostenlos-kommerziell\" target=\"_self\" rel=\"noopener noreferrer\">Softonic-Antivirus-Vergleich von 2014<\/a> haben wir 15 kostenlose und kostenpflichtige Antivirus-Programme verglichen. Das Resultat: Die besten sind <a title=\"AVG\" href=\"http:\/\/avg-anti-virus.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">AVG<\/a>,\u00a0<a title=\"Oihoo 360\" href=\"http:\/\/360-internet-security-2013.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Qihoo 360<\/a> und\u00a0<a title=\"Avira\" href=\"http:\/\/avira-free-antivirus.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Avira<\/a>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Antiviren Vergleich 2013\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2013\/12\/1-Total-Chart1.jpg\" alt=\"\" width=\"494\" height=\"567\" \/><\/p>\n<p style=\"text-align: center\"><em>Gesamtnoten im <\/em><a title=\"Antiviren-Vergleich 2013\" href=\"http:\/\/artikel.softonic.de\/antivirus-vergleich-2014-besten-programme-fur-optimalen-schutz-kostenlos-kommerziell\" target=\"_self\" rel=\"noopener noreferrer\"><em>Antivirus-Vergleich 2014<\/em><\/a><em>: All diese sind mit XP kompatibel.<\/em><\/p>\n<p>Hierbei  ist es wichtig, ein effizientes Antivirusprogramm zu w\u00e4hlen, das  gleichzeitig aber auch wenig Ressourcen verbraucht. Wer nicht viel Speicherplatz zur  Verf\u00fcgung hat, kann auch ein tragbares Antivirusprogramm herunterladen. Diese m\u00fcssen nicht installiert werden und laufen nur,  wenn man den PC reinigen will. Einer Bekannten mit einem etwas  altersschwachen Laptop mit XP habe ich avast! entfernt und <a title=\"Avira PC Cleaner\" href=\"avira-pc-cleaner.softonic.de\" target=\"_self\" rel=\"noopener noreferrer\">Avira PC Cleaner<\/a> auf dem Desktop gelassen.<\/p>\n<h3>Eine einfach zu bedienende Firewall installieren<\/h3>\n<p style=\"text-align: left\">Wer  beim Gebrauch von Windows XP ruhig schlafen will, muss auch die Programme kontrollieren, die  Daten aus dem Internet empfangen. Warum? Einige von diesen k\u00f6nnten die  Privatsph\u00e4re verletzen oder \u2013 schlimmer noch \u2013 einen Virus  herunterladen.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Comodo Firewall\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/comodofire.jpg\" alt=\"\" width=\"568\" height=\"328\" \/><\/p>\n<p style=\"text-align: center\"><em>Die exzellente und kostenlose Firewall <\/em><a title=\"Comodo Firewall\" href=\"http:\/\/comodo-firewall.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\"><em>Comodo Firewall<\/em><\/a><em> ist mit Windows XP kompatibel.<\/em><\/p>\n<p>Die beiden am meisten empfohlenen Firewalls sind die etwas alte, aber zuverl\u00e4ssige <a title=\"Sygate Personal Firewall\" href=\"http:\/\/sygate-personal-firewall.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Sygate Personal Firewall<\/a>, die auf XP wirklich fantastisch funktioniert, und die etwas j\u00fcngere\u00a0<a title=\"Comodo Firewall\" href=\"http:\/\/comodo-firewall.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Comodo Firewall<\/a> mit einem eleganteren und intuitiven Design. Effizient sind sie beide gleicherma\u00dfen.<\/p>\n<h3>Kein Outlook Express \/ Live Mail mehr nutzen<\/h3>\n<p>Wer  E-Mails auf die gute alte Art und Weise checkt, sollte sich mit dem  Gedanken anfreunden, Outlook Express (OE) und Live Mail so schnell wie  m\u00f6glich aufzugeben. Diese Anwendungen sind veraltet und k\u00f6nnen trotz  Antivirus unz\u00e4hlige Viren einschleusen.<\/p>\n<p>Eine f\u00fcr Windows XP verf\u00fcgbare \u00a0Desktop-Alternative ist <a title=\"Thunderbird\" href=\"http:\/\/mozilla-thunderbird.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Mozilla Thunderbird<\/a>, in letzter Zeit hat sich bei besagtem Projekt allerdings wenig bewegt. Am besten verwendet man die Web-Varianten wie\u00a0<a href=\"http:\/\/windows.microsoft.com\/en-us\/outlook\/pop-email\">Outlook.com<\/a> oder\u00a0<a href=\"https:\/\/support.google.com\/mail\/answer\/56283?hl=en\">Gmail<\/a>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Outlook Weboberfl\u00e4che\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/outlookpop.jpg\" alt=\"\" width=\"568\" height=\"331\" \/><\/p>\n<p style=\"text-align: center\"><em>Auch bei Outlook.com lassen sich POP- oder IMAP-Konten einrichten.<\/em><\/p>\n<p>Bei  beiden kann man die E-Mails via POP3 in seinen Posteingang  herunterladen, weshalb man auch E-Mails von alten Accounts erhalten und  verschicken kann. Ein Plus ist der Filter f\u00fcr SPAM und gef\u00e4hrliche Post,  dieser ist um L\u00e4ngen besser als bei jedem Programm von Windows.<\/p>\n<h3>Eigenen Backup-Plan erstellen<\/h3>\n<p>Wer  weiterhin Windows XP nutzen m\u00f6chte, hat sich f\u00fcr ein etwas riskanteres  und spannenderes Leben entschieden. F\u00fcr alle diejenigen, die ihre Daten  sch\u00fctzen m\u00f6chten, ist es daher ratsam, regelm\u00e4\u00dfig Sicherheitskopien zu  erstellen.\u00a0So kann man, selbst wenn etwas schief l\u00e4uft und sich  beispielsweise der Virus\u00a0Cryptolocker im eigenen PC einnistet, die Daten wiederbekommen.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Cryptolocker\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/comodotm.jpg\" alt=\"\" width=\"556\" height=\"315\" \/><\/p>\n<p>Am besten erstellt man sich hierzu ein eigenes\u00a0<a title=\"Backup erstellen\" href=\"http:\/\/artikel.softonic.de\/das-mussen-sie-bei-der-datensicherung-beachten-26-12-2013\" target=\"_self\" rel=\"noopener noreferrer\">Backup-Rezept<\/a>, was man \u2013 je nach Bedarf \u2013 mit Hilfe verschiedener kostenloser Programme erreichen kann: <a title=\"Dropbox\" href=\"http:\/\/dropbox.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Dropbox<\/a> f\u00fcr Dokumente,\u00a0<a title=\"Dashlane\" href=\"http:\/\/dashlane.softonic.de\" target=\"_self\" rel=\"noopener noreferrer\">Dashlane<\/a> f\u00fcr Passw\u00f6rter, <a title=\"Cobian Backup\" href=\"http:\/\/cobian-backup.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Cobian Backup<\/a> und\u00a0<a title=\"Comodo Timemachine\" href=\"http:\/\/comodo-time-machine.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Comodo Time Machine<\/a> f\u00fcr den Rest. Eine andere gro\u00dfartige M\u00f6glichkeit f\u00fcr Backups ist <a title=\"Macrium Reflect\" href=\"http:\/\/macrium-reflect.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">Macrium Reflect<\/a>. Besagtes Programm vereinigt verschiedene L\u00f6sungen und bietet daher h\u00f6chste Sicherheit und Flexibilit\u00e4t.<\/p>\n<h3>Vielleicht doch besser auf eine neuere Version umsteigen oder eine virtuelle\u00a0Maschine nutzen<\/h3>\n<p style=\"text-align: left\">Man  kann durchaus XP weiterhin benutzen, ohne sich einen Virus einzufangen. Die Betriebssysteme  entwickeln sich jedoch stets weiter, und mit ihnen die Software.\u00a0Irgendwann werden also die Programme nicht mehr f\u00fcr Windows  XP zug\u00e4nglich sein und es ist ratsam, so bald wie m\u00f6glich etwas dahingehend zu tun.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Anzahl der XP-Nutzer\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/03\/xpshare.jpg\" alt=\"\" width=\"490\" height=\"350\" \/><\/p>\n<p style=\"text-align: center\"><em>Die Anzahl der Windows-XP-User ist relativ stabil geblieben. (Quelle: <\/em><a href=\"http:\/\/www.computerworld.com\/s\/article\/9246706\/Users_refuse_to_chuck_XP_as_Windows_8_uptake_flattens\"><em>Computerworld<\/em><\/a><em>)<\/em><\/p>\n<p>Wer  auf XP angewiesen ist, um bestimmte Programme zu bedienen, sollte nicht  vergessen, dass es f\u00fcr solche Zwecke virtuelle Maschinen gibt. Das ist  ein PC, der innerhalb eines Fensters des eigenen PCs gestartet wird.  M\u00f6glich ist dies \u00fcber <a title=\"VirtualBox\" href=\"http:\/\/virtualbox.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">VirtualBox<\/a> oder\u00a0<a title=\"VMware\" href=\"http:\/\/vmware-player.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\">VMPlayer<\/a>, beide kostenfrei und 100 % kompatibel mit XP.<\/p>\n<p><strong>Welche Sicherheitsma\u00dfnahmen werden Sie nun anwenden, um weiterhin XP nutzen zu k\u00f6nnen?<\/strong><\/p>\n<p><strong>Passende Artikel:<\/strong><\/p>\n<p><a href=\"http:\/\/artikel.softonic.de\/klartext-warum-sie-windows-xp-behalten-sollten-in-guter-erinnerung-08-04-2013\" target=\"_self\" rel=\"noopener noreferrer\">Warum Sie Windows XP behalten sollten (in guter Erinnerung)<\/a><\/p>\n<p><a href=\"http:\/\/news.softonic.de\/pcmover-express-erleichtert-anwendern-die-aktualisierung-von-windows-xp-04-03-2014\" target=\"_self\" rel=\"noopener noreferrer\">Windows XP mit PCmover Express aktualisieren<\/a><strong><strong><br \/>\n<\/strong><\/strong><\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft bringt keine neuen Aktualisierungen und Sicherheitspatches f\u00fcr Windows XP, was das System immer anf\u00e4lliger f\u00fcr Sicherheitsrisiken macht. Man kann Windows XP zwar auch nach dem Supportende behalten, ohne Sicherheitsma\u00dfnahmen ist das aber gef\u00e4hrlich. Wer die folgenden Tipps beachtet, kann sein XP gegen Viren und andere Bedrohungen sch\u00fctzen. Microsoft selbst bietet nur eine L\u00f6sung: Auf &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/de\/so-halt-man-windows-xp-nach-dem-supportende-2014-virenfrei-10-03-2014\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;So h\u00e4lt man Windows XP nach dem Supportende 2014 virenfrei&#8221;<\/span><\/a><\/p>\n","protected":false},"author":7031,"featured_media":46738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[3383],"tags":[513,648],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-46728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-windows-xp","tag-windows-xp-security-essentials"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/46728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/users\/7031"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/comments?post=46728"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/46728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media\/46738"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media?parent=46728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/categories?post=46728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/tags?post=46728"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/usertag?post=46728"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/vertical?post=46728"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/content-category?post=46728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}