{"id":49977,"date":"2014-04-24T15:18:31","date_gmt":"2014-04-24T14:18:31","guid":{"rendered":"http:\/\/onsoftware.softonic.de\/?p=49977"},"modified":"2024-05-29T09:42:22","modified_gmt":"2024-05-29T08:42:22","slug":"android-auf-dem-pc-nutzen-so-installieren-sie-android-x86","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/de\/android-auf-dem-pc-nutzen-so-installieren-sie-android-x86\/","title":{"rendered":"Android auf dem PC nutzen: So installieren Sie Android x86"},"content":{"rendered":"<p>Das Betriebssystem Android wurde f\u00fcr Smartphones und Tablets entwickelt. Das inoffizielle <a href=\"http:\/\/android-x86.softonic.com\">Android-x86<\/a>-Projekt hat eine Version erstellt, mit der man <strong>Android auf dem PC nutzen kann<\/strong>.<\/p>\n<p>Die Vorteile liegen auf der Hand: Mit dem Projekt nutzt man Android-Apps ohne das Tablet oder Smartphone\u00a0 auf dem PC. Dadurch <strong>testet man Apps<\/strong>, bevor man sie auf dem mobilen Ger\u00e4t installiert.<\/p>\n<p>In diesem Beitrag zeigen wir, wie man Android-x86 in einer <strong>virtuellen Umgebung<\/strong> auf dem PC installiert. In einem separaten Windows-Fenster l\u00e4uft in der virtuelle Maschine praktisch ein eigener PC. Eine neue Festplattenpartition  muss man daf\u00fcr nicht erstellen.<\/p>\n<h3>1. VirtualBox herunterladen und installieren<\/h3>\n<p>Mit <a href=\"http:\/\/virtualbox.softonic.com\">VirtualBox<\/a> erstellt man eine virtuelle Umgebung, in der man innerhalb eines  Betriebssystem ein anderes System nutzt. F\u00fcr die Installation von  VirtualBox l\u00e4dt man die Installationsdatei herunter, klickt sie doppelt  an und folgt den Anweisungen.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Installationsdialog Virtual Box\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-12-13-50.png\" alt=\"Installationsdialog Virtual Box\" width=\"509\" height=\"398\" \/><\/p>\n<p>Wird die Meldung f\u00fcr die Installation von <strong>Oracle-Treibern<\/strong> angezeigt, w\u00e4hlt man <em>Ja<\/em>.  W\u00e4hrend der Installation kann es vorkommen, dass die Internetverbindung  f\u00fcr einige Sekunden gekappt wird. Nach der Installation startet VirtualBox.<\/p>\n<h3>2. Die neueste Version von Android-x86 herunterladen<\/h3>\n<p>Android-x86  eignet sich f\u00fcr den Betrieb auf einem PC. In diesem Tutorial nutzen wir  die Version f\u00fcr Android 4.4 KitKat. Daf\u00fcr l\u00e4dt man die <a href=\"http:\/\/android-x86.softonic.de\" target=\"_self\" rel=\"noopener noreferrer\">Android-x86-ISO-Datei<\/a> herunter. Die Datei legt man entweder in einem Ordner ab oder brennt sie auf eine CD.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Android x86 ISO\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/android-iso.png\" alt=\"Android x86 ISO\" width=\"502\" height=\"330\" \/><\/p>\n<h3>3. Eine virtuelle Umgebung erstellen<\/h3>\n<p>Um eine neue virtuelle Umgebung zu erstellen, klickt man in VirtualBox auf die Schaltfl\u00e4che <em>Neu<\/em> (das Symbol mit der blauen Sonne). Anschlie\u00dfend w\u00e4hlt man <strong>Linux 2.6 in der 32-Bit-Version<\/strong>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Virtuelle Maschine in Virtual Box erstellen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-15-48-531.png\" alt=\"Virtuelle Maschine in Virtual Box erstellen\" width=\"568\" height=\"389\" \/><\/p>\n<p>Als  n\u00e4chstes legt man die Speichergr\u00f6\u00dfe fest, die man der virtuellen  Umgebung zur Verf\u00fcgung stellt. F\u00fcr Android-x86 <strong>reichen 1.024 MB<\/strong> aus.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Speichergr\u00f6\u00dfe festelgen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-15-49-12.png\" alt=\"Sspeichergr\u00f6\u00dfe festelgen\" width=\"435\" height=\"382\" \/><\/p>\n<p>Dann erstellt man eine virtuelle VDI-Festplatte. Als Speicherkapazit\u00e4t <strong>reichen 8 GB<\/strong>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Virtuelle Festplatte erstellen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-15-49-19.png\" alt=\"Virtuelle Festplatte erstellen\" width=\"435\" height=\"382\" \/><\/p>\n<p>Die virtuelle Umgebung <strong>aktiviert<\/strong> man in VirtualBox durch einen Klick auf den Start-Button.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Virtuelle Maschine starten\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-58-42.png\" alt=\"Virtuelle Maschine starten\" width=\"392\" height=\"187\" \/><\/p>\n<p>Daraufhin  fragt VirtualBox nach einem Betriebssystem, das von CD, DVD oder \u00fcber  eine ISO-Datei in die virtuelle Umgebung eingef\u00fcgt werden soll. Hier  w\u00e4hlt man die <strong>Datei aus, die man unter Punkt 2 heruntergeladen<\/strong> hat.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Android ISO f\u00fcr virtuelle Maschine w\u00e4hlen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-15-49-40.png\" alt=\"Android ISO f\u00fcr virtuelle Maschine w\u00e4hlen\" width=\"400\" height=\"273\" \/><\/p>\n<h3>4. Installation von Android in der virtuellen Umgebung<\/h3>\n<p>Nun  geht es darum, Android-x86 auf dem PC zu installieren. Es ist wichig,  dass jeder Schritt vollzogen wird, damit es keine Fehler bei der  Installation gibt. Als erstes erscheint der <strong>Boot-Bildschirm<\/strong>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Boot-Bildschirm von Android x86\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-15-59-161.png\" alt=\"Boot-Bildschirm von Android x86\" width=\"568\" height=\"485\" \/><\/p>\n<p>Auf dem Boot-Bildschirm w\u00e4hlt man die Installation von Android-x86 aus. Anschlie\u00dfend bereitet man die <strong>virtuelle Festplattenpartition<\/strong> vor.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Partition erstellen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-13-341.png\" alt=\"Partition erstellen\" width=\"568\" height=\"370\" \/><\/p>\n<p>Mit den Pfeiltasten bewegt man sich auf dem n\u00e4chsten Bildschirm zwischen den beiden Optionen hin und her. Man w\u00e4hlt die Option <em>Create\/Modify partitions<\/em>. Anschlie\u00dfend geht man auf <em>New<\/em> und dr\u00fcckt die Enter-Taste.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Neue Partition\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-13-511.png\" alt=\"Neue Partition\" width=\"568\" height=\"370\" \/><\/p>\n<p>Nun w\u00e4hlt man <em>Pri\/Log Free Space<\/em> und dr\u00fcckt wiederum die Enter-Taste.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Typ Primary w\u00e4hlen\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-15-151.png\" alt=\"Typ Primary w\u00e4hlen\" width=\"568\" height=\"370\" \/><\/p>\n<p>Danach geht man auf <em>Bootable<\/em> und dr\u00fcckt Enter, um die Boot-Partition festzulegen. Der Bildschirm sollte so aussehen wie hier:<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Bootable\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-15-261.png\" alt=\"Bootable\" width=\"568\" height=\"370\" \/><\/p>\n<p>Zum Schluss fragt die Software, ob man sich sicher ist. Das beantwortet man mit <em>Y<\/em> und dr\u00fcckt auf Enter.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Write\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-15-381.png\" alt=\"Write\" width=\"568\" height=\"316\" \/><\/p>\n<p>Die  virtuelle Festplatte wird nun angelegt. Das dauert einige Minuten. Nach  dem Abschluss geht man auf <em>Beenden<\/em> und gelangt so zum Startbildschirm  zur\u00fcck. Dort wird eine neue Festplatte angezeigt. Mit der Enter-Taste  w\u00e4hlt man sie aus.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Disk ready\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-17-511.png\" alt=\"Disk ready\" width=\"568\" height=\"370\" \/><\/p>\n<p>Die neue virtuelle Festplatte muss noch formatiert werden.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Formatieren\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-18-011.png\" alt=\"Formatieren\" width=\"568\" height=\"370\" \/><\/p>\n<p>F\u00fcr die Formatierung nimmt man das <strong>ext3-DSateisystem<\/strong>, das Android normalerweise nutzt.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Dateisystem ext3\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-17-31-521.png\" alt=\"Dateisystem ext3\" width=\"568\" height=\"370\" \/><\/p>\n<p>Nach der Formatierung w\u00e4hlt man <em>Yes<\/em>, wenn man zur Installation des <strong>GRUB-Bootloaders<\/strong> aufgefordert wird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"GRUB Bootloader\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-18-221.png\" alt=\"GRUB Bootloader\" width=\"568\" height=\"370\" \/><\/p>\n<p>Ebenso w\u00e4hlt man <em>Yes<\/em>, um das System-Verzeichnis mit <strong>Lese- und Schreibrechten<\/strong> zu installieren.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Read-Write Android x86\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-18-281.png\" alt=\"Read-Write Android x86\" width=\"568\" height=\"370\" \/><\/p>\n<p>Die Installation dauert einige Minuten. Sobald sie abgeschlossen ist, startet man Android.<\/p>\n<h3>5. Starten von Android x86 in der virtuellen Umgebung<\/h3>\n<p>Nach der Partionierung und der Formatierung steht die virtuelle Festplatte bereit und alles ist f\u00fcr die Installation bereit. Jetzt startet man den PC neu.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Neustart\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-18-551.png\" alt=\"Neustart\" width=\"568\" height=\"370\" \/><\/p>\n<p>Die Software versucht, das System von einer CD zu starten. Um das zu vermeiden, geht man ins Ger\u00e4temen\u00fc und deaktiviert <em>CD\/DVD<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"CD\/DVD deaktivieren\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-19-25.png\" alt=\"CD\/DVD deaktivieren\" width=\"536\" height=\"121\" \/><\/p>\n<p>Nun startet man den PC noch einmal neu. Dazu \u00f6ffnet man das erste Men\u00fc <em>Machine<\/em> und w\u00e4hlt den Eintrag <em>Reset<\/em>.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Neustart \u00fcber Reset\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/reset.png\" alt=\"Neustart \u00fcber Reset\" width=\"286\" height=\"272\" \/><\/p>\n<p>Nach dem Reset w\u00e4hlt man ebenfalls im Men\u00fc <em>Machine<\/em> den Eintrag <em>Disable Mouse Integration<\/em>. Damit nutzt man die Maus bequem in der virtuellen Umgebung.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Disable Mouse Integration\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-20-02.png\" alt=\"Disable Mouse Integration\" width=\"285\" height=\"159\" \/><\/p>\n<p>Nach dem Start von Android erscheint der <strong>Willkommensbildschirm<\/strong>. Hier w\u00e4hlt man die Sprache und andere Details aus. Dazu verwendet man die Maus.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Willkommensbildschirm ANdroid x86\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-20-261.png\" alt=\"Willkommensbildschirm ANdroid x86\" width=\"568\" height=\"473\" \/><\/p>\n<p>Den Vollbildmodus erreicht man \u00fcber die Tastenkombination <em>Steuerung Rechts<\/em> + <em>F<\/em>.<\/p>\n<p>Eine  Verbindung mit einem WLAN-Netz ist nicht notwendig. Android x86  verbindet sich \u00fcber die virtuelle Umgebung mit dem Internet. Jetzt kann  man Android auf dem PC ausprobieren.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Browser Android x86\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-17-41-431.png\" alt=\"Browser Android x86\" width=\"568\" height=\"473\" \/><\/p>\n<h3>Android x86 auf dem PC nutzen<\/h3>\n<p>Android  befindet sich nun auf dem PC, ohne dass daf\u00fcr gef\u00e4hrliche \u00c4nderungen an  der Festplatte n\u00f6tig waren. Android x86 eignet sich insbesondere f\u00fcr  den Einsatz in Windows-Anwendungen.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Android x86\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/04\/09-04-2014-16-22-58.png\" alt=\"Android x86\" width=\"568\" height=\"468\" \/><\/p>\n<p>Eine  Alternative, um Android auf einem PC zu nutzen, existiert mit <a href=\"http:\/\/bluestacks-app-player.softonic.de\/\" target=\"_self\" rel=\"noopener noreferrer\"> Bluestacks<\/a>. Es handelt sich um einen Emulator. Allerdings gibt die hier  vorgestellte Option dem Nutzer mehr Bewegungsfreiheit als Bluestacks.<\/p>\n<h3>Mehr zum Thema<\/h3>\n<ul>\n<li><a href=\"http:\/\/artikel.softonic.de\/t\/ratgeber-android-tablets\" target=\"_self\" rel=\"noopener noreferrer\">Ratgeber Android Tablets<\/a><\/li>\n<li><a href=\"http:\/\/artikel.softonic.de\/video-der-bluestacks-app-player-in-aktion\" target=\"_self\" rel=\"noopener noreferrer\">Der Bluestacks App Player in Aktion<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Das Betriebssystem Android wurde f\u00fcr Smartphones und Tablets entwickelt. Das inoffizielle Android-x86-Projekt hat eine Version erstellt, mit der man Android auf dem PC nutzen kann. Die Vorteile liegen auf der Hand: Mit dem Projekt nutzt man Android-Apps ohne das Tablet oder Smartphone\u00a0 auf dem PC. Dadurch testet man Apps, bevor man sie auf dem mobilen &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/de\/android-auf-dem-pc-nutzen-so-installieren-sie-android-x86\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Android auf dem PC nutzen: So installieren Sie Android x86&#8221;<\/span><\/a><\/p>\n","protected":false},"author":7031,"featured_media":50003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[3383],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-49977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/49977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/users\/7031"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/comments?post=49977"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/49977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media\/50003"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media?parent=49977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/categories?post=49977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/tags?post=49977"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/usertag?post=49977"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/vertical?post=49977"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/content-category?post=49977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}