{"id":55161,"date":"2014-07-07T11:26:35","date_gmt":"2014-07-07T10:26:35","guid":{"rendered":"http:\/\/onsoftware.softonic.de\/?p=55161"},"modified":"2024-03-08T06:05:42","modified_gmt":"2024-03-08T05:05:42","slug":"windows-9-microsoft-testet-die-neue-version-bereits-mit-windows-store-apps","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/de\/windows-9-microsoft-testet-die-neue-version-bereits-mit-windows-store-apps\/","title":{"rendered":"Windows 9: Microsoft testet die neue Version mit Windows Store-Apps"},"content":{"rendered":"<p>Microsoft testet die <strong>neue Windows-Version<\/strong> bereits mit Anwendungen aus dem <em>Windows Store<\/em>. In den Protokolldateien der Internetseite taucht das Betriebssystem mit dem Code-Namen <em>Threshold<\/em> unter der <em>Build<\/em>-Nummer 6.4.9788 auf. Das Unternehmen pr\u00fcft bereits die <strong>Kompatibilit\u00e4t mit vorhandenen Apps<\/strong> und k\u00f6nnte eine <a title=\"Windows 9: Microsoft will noch dieses Jahr eine neue Benutzeroberfl\u00e4che mit Start-Men\u00fc zeigen\" href=\"http:\/\/news.softonic.de\/windows-9-microsoft-will-noch-dieses-jahr-eine-vorab-version-mit-neuer-benutzeroberflache-zeigen\" target=\"_self\" rel=\"noopener noreferrer\">Vorschau von Windows 9<\/a> im weiteren Verlauf des Jahres zeigen.<\/p>\n<p>Zu den Neuerungen von Windows 9 f\u00fcr Desktop- und Tablet-PCs z\u00e4hlt eine\u00a0<strong>\u00dcberarbeitung der Benutzeroberfl\u00e4che<\/strong>.<strong> <\/strong>Die R\u00fcckkehr des Start-Men\u00fcs erlaubt Anwendern, auf Wunsch alle Modern UI-Apps anzeigen zu lassen oder nur die Desktop-Anwendungen. Das <strong>neue Start-Men\u00fc<\/strong> stellt Apps entweder in Kachel-Form oder als Liste dar.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-55166\" title=\"Windows 9: Microsoft testet die neue Version bereits mit Windows Store-Apps\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/8\/2014\/07\/windows-9-windows-store-log-screenshot-568x330.jpg\" alt=\"Windows 9: Microsoft testet die neue Version bereits mit Windows Store-Apps\" width=\"568\" height=\"330\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/8\/2014\/07\/windows-9-windows-store-log-screenshot.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/8\/2014\/07\/windows-9-windows-store-log-screenshot-268x155.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>Microsoft Windows 9 wird f\u00fcr Fr\u00fchjahr 2015 erwartet. \u00a0Weitere Neuigkeiten von Microsoft zur n\u00e4chsten gro\u00dfen Windows-Version werden zur\u00a0<a title=\"Microsoft Worldwide Partner Conference 2014\" href=\"http:\/\/www.digitalwpc.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Microsoft Worldwide Partner Conference<\/a><strong> <\/strong>vom 13. bis zum 17. Juli 2014 erwartet.<\/p>\n<p style=\"text-align: left\"><em>Dem Autor Jakob Straub auf <strong><a title=\"@jakobstraub auf Twitter folgen\" href=\"https:\/\/twitter.com\/jakobstraub\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a><\/strong> und <strong><a title=\"Jakob Straub auf Google+ folgen.\" rel=\"author noopener noreferrer\" href=\"https:\/\/plus.google.com\/101955307964278377393\/\" target=\"_blank\">Google+<\/a><\/strong> folgen.<\/em><\/p>\n<h3>Passende Artikel<\/h3>\n<ul>\n<li><a title=\"Windows 9: Microsoft will noch dieses Jahr eine neue Benutzeroberfl\u00e4che mit Start-Men\u00fc zeigen\" href=\"http:\/\/news.softonic.de\/windows-9-microsoft-will-noch-dieses-jahr-eine-vorab-version-mit-neuer-benutzeroberflache-zeigen\" target=\"_self\" rel=\"noopener noreferrer\">Windows 9: Microsoft will noch dieses Jahr eine neue Benutzeroberfl\u00e4che mit Start-Men\u00fc zeigen<\/a><\/li>\n<li><a title=\"Windows 9 vereint den App Store f\u00fcr Windows, Windows Phone und Xbox\" href=\"http:\/\/news.softonic.de\/windows-phone-9-vereint-den-app-store-fur-windows-windows-phone-und-xbox\" target=\"_self\" rel=\"noopener noreferrer\">Windows 9 vereint den App Store f\u00fcr Windows, Windows Phone und Xbox<\/a><\/li>\n<li><a title=\"Windows Phone 8.1: Microsoft startet den Support-Zeitraum f\u00fcr Windows Phone mit Cortana\" href=\"http:\/\/news.softonic.de\/windows-phone-8-1-am-24-6-2014-startet-microsoft-offiziell-windows-phone-mit-der-sprachassistentin-cortana-und-vielen-neuerungen\" target=\"_self\" rel=\"noopener noreferrer\">Windows Phone 8.1: Microsoft startet den Support-Zeitraum f\u00fcr Windows Phone mit Cortana<\/a><\/li>\n<li><a title=\"Die Neuerungen von Windows Phone 8.1: Sprachassistentin Cortana, Action Center, Internet Explorer 11\" href=\"http:\/\/http\/\/news.softonic.de\/windows-phone-8-1-mit-cortana-und-action-center-das-sind-die-neuerungen-02-04-2014\" target=\"_self\" rel=\"noopener noreferrer\">Die Neuerungen von Windows Phone 8.1: Sprachassistentin Cortana, Action Center, Internet Explorer 11<\/a><\/li>\n<li><a title=\"Microsoft Windows Start-Men\u00fc: R\u00fcckkehr doch erst 2015 mit Windows 9\" href=\"http:\/\/news.softonic.de\/microsoft-bringt-das-windows-start-menu-doch-erst-2015-mit-windows-9-zuruck\" target=\"_self\" rel=\"noopener noreferrer\">Microsoft Windows Start-Men\u00fc: R\u00fcckkehr doch erst 2015 mit Windows 9<\/a><\/li>\n<\/ul>\n<p><em>Quelle \/ Bild: <a title=\"Microsoft News: Windows 9 Build 6.4.9788 Spotted In Windows Store Logs\" href=\"http:\/\/microsoft-news.com\/windows-9-build-6-4-9788-spotted-in-windows-store-logs\/\" target=\"_self\" rel=\"noopener noreferrer\">Microsoft News<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft testet die neue Windows-Version bereits mit Anwendungen aus dem Windows Store. In den Protokolldateien der Internetseite taucht das Betriebssystem mit dem Code-Namen Threshold unter der Build-Nummer 6.4.9788 auf. Das Unternehmen pr\u00fcft bereits die Kompatibilit\u00e4t mit vorhandenen Apps und k\u00f6nnte eine Vorschau von Windows 9 im weiteren Verlauf des Jahres zeigen. Zu den Neuerungen von &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/de\/windows-9-microsoft-testet-die-neue-version-bereits-mit-windows-store-apps\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Windows 9: Microsoft testet die neue Version mit Windows Store-Apps&#8221;<\/span><\/a><\/p>\n","protected":false},"author":7038,"featured_media":55162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[3383],"tags":[4,107,1721,638,1668],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-55161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-betriebssystem","tag-microsoft","tag-threshold","tag-windows-9","tag-windows-store"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/55161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/users\/7038"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/comments?post=55161"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/posts\/55161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media\/55162"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/media?parent=55161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/categories?post=55161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/tags?post=55161"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/usertag?post=55161"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/vertical?post=55161"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/de\/wp-json\/wp\/v2\/content-category?post=55161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}