{"id":126314,"date":"2015-11-19T15:07:23","date_gmt":"2015-11-19T14:07:23","guid":{"rendered":"http:\/\/onsoftware.softonic.com\/?p=126314"},"modified":"2025-06-13T01:44:10","modified_gmt":"2025-06-12T23:44:10","slug":"call-of-duty-black-ops-3-guia-especialistas","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/call-of-duty-black-ops-3-guia-especialistas\/","title":{"rendered":"Call of Duty: Black Ops 3 &#8211; Gu\u00eda de Especialistas"},"content":{"rendered":"<p><strong>En <a href=\"http:\/\/call-of-duty-black-ops-3.softonic.com\/\">Call of Duty: Black Ops 3<\/a> hay cuatro <\/strong><strong>Especialistas que vienen desbloqueados de un inicio.<\/strong> Se trata de Battery, Prophet, Outrider y Ruin, a los que m\u00e1s adelante se les unir\u00e1n<strong> <\/strong>Seraph, Nomad, Reaper, Spectre y Firebreak (que se desbloquean en los niveles at 22, 28, 34, 40 y 46, respectivamente).<\/p>\n<p>En esta gu\u00eda repasamos los 9 Especialistas de CoD: Black Ops 3 y te explicamos <strong>cu\u00e1l te ir\u00e1 mejor seg\u00fan tu estilo de juego<\/strong>. Eso s\u00ed, siempre recomendamos que los pruebas a todos al menos una vez.<\/p>\n<p>Antes de continuar: si quieres una gu\u00eda m\u00e1s general sobre el <strong>multijugador<\/strong> de CoD 3 Black Ops 3 <a href=\"http:\/\/articulos.softonic.com\/call-of-duty-black-ops-3-trucos-multijugador\">haz clic aqu\u00ed<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126330\" title=\"shoulder-cannon-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/shoulder-cannon-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/shoulder-cannon-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/shoulder-cannon-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Battery<\/h3>\n<p>Entra en plena acci\u00f3n con su potente armadura cin\u00e9tica y su lanzagranadas.<strong> Genial si te gusta estar en el centro de la acci\u00f3n.<\/strong><\/p>\n<h3><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126329\" title=\"bush-wacker-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/bush-wacker-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/bush-wacker-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/bush-wacker-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/strong>Prophet<\/h3>\n<p>Un luchador de <strong>alta tecnolog\u00eda<\/strong> cuya habilidad \u201cGlitch\u201d le permite salir r\u00e1pidamente de las situaciones de peligro. Su arma es Tempest, ideal para los mapas de captura\/control.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126328\" title=\"bow-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/bow-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/bow-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/bow-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Outrider<\/h3>\n<p>Armada con un arco llamado Sparrow, necesitas de algo de planificaci\u00f3n para aprovecharlo, ya que cuando la recargas est\u00e1s indenfenso. <strong>Si eres preciso y lo suficientemente r\u00e1pido<\/strong>, es una genial elecci\u00f3n, especialmente por su modo Vision Pulse que le permite visualizar a los enemigos tras las paredes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126327\" title=\"my-arms-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/my-arms-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/my-arms-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/my-arms-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Ruin<\/h3>\n<p>Es b\u00e1sicamente Jax de Motal Kombat, brazos bi\u00f3nicos incluidos. <strong>Perfecto para luchadores en espacios cerrados que a\u00f1oran las muertes por arma blanca<\/strong>. Sus puntos fuertes son la velocidad \u2013Overdrive le hace ir muy deprisa- y el combate a distancias cortas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126326\" title=\"moody-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/moody-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/moody-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/moody-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Seraph (22)<\/h3>\n<p>Outrider y Seraph atraer\u00e1n a jugadores parecidos. Su potente pistola Annihilator <strong>mata a cualquiera de un simple disparo<\/strong>, pero llama la atenci\u00f3n y ser\u00e1 presa f\u00e1cil. Su habilidad Foco de combate la ayuda a adquirir r\u00e1pidamente scorestreaks.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126325\" title=\"back-to-nature-copy1-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/back-to-nature-copy1-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/back-to-nature-copy1-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/back-to-nature-copy1-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Nomad (28)<\/h3>\n<p>Personaje<strong> ideal para el jugador de equipo que disfruta con los mapas de puntos de control<\/strong>. Con un gran surtido de drones en su arma H.I.V.E., puede seleccionar un per\u00edmetro, mientras que su Rejack le permite revivir r\u00e1pidamente y defender.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126324\" title=\"we-are-boned-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/we-are-boned-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/we-are-boned-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/we-are-boned-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Reaper (34)<\/h3>\n<p><strong>Otra clase defensiva<\/strong>, este robot establece un enjambre de fuego de cobertura con su mini-pistola Scythe y tiene la habilidad de producir clones pasivos que distraen al enemigo con Psicosis.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126323\" title=\"is-it-destiny1-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/is-it-destiny1-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/is-it-destiny1-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/is-it-destiny1-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Spectre (40)<\/h3>\n<p>Si te gusra Ruin te gustar\u00e1 Spectre. <strong>R\u00e1pido, con un gran talento para el cuerpo a cuerpo y una capa de camuflaje<\/strong>. Ideal para los amantes del sigilo y los asesinos r\u00e1pidos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-126322\" title=\"firedup-568x300\" src=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/firedup-568x300-568x300.jpg\" alt=\"\" width=\"568\" height=\"300\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/firedup-568x300.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2015\/11\/firedup-568x300-268x141.jpg 268w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<h3>Firebreak (46)<\/h3>\n<p>Si bien no tiene los explosivos de Battery, cuenta con <strong>un lanzallamas que ofrece ventajas similares en espacios cerrados<\/strong>. Su habilidad Heat Wave puede aturdir a los oponentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Call of Duty: Black Ops 3 hay cuatro Especialistas que vienen desbloqueados de un inicio. Se trata de Battery, Prophet, Outrider y Ruin, a los que m\u00e1s adelante se les unir\u00e1n Seraph, Nomad, Reaper, Spectre y Firebreak (que se desbloquean en los niveles at 22, 28, 34, 40 y 46, respectivamente). En esta gu\u00eda &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/es\/call-of-duty-black-ops-3-guia-especialistas\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Call of Duty: Black Ops 3 &#8211; Gu\u00eda de Especialistas&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1094,"featured_media":126321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":10},"categories":[],"tags":[9793],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-126314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-app-subdomain-redirectioncall-of-duty"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/126314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/1094"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=126314"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/126314\/revisions"}],"predecessor-version":[{"id":374410,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/126314\/revisions\/374410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/126321"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=126314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=126314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=126314"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=126314"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=126314"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=126314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}