{"id":14324,"date":"2011-09-08T08:00:25","date_gmt":"2011-09-08T06:00:25","guid":{"rendered":"http:\/\/onsoftware.softonic.com\/?p=14324"},"modified":"2025-06-13T06:23:43","modified_gmt":"2025-06-13T04:23:43","slug":"10-cosas-que-puedes-tirar-si-tienes-un-movil","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/10-cosas-que-puedes-tirar-si-tienes-un-movil\/","title":{"rendered":"10 cosas que puedes tirar si tienes un m\u00f3vil"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14341 alignright\" title=\"10objetos\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/10objetos.png\" alt=\"\" width=\"145\" height=\"146\" \/>\u00bfCu\u00e1ntos cacharros in\u00fatiles acumulas en casa? Si siempre has pensado en lo bien que estar\u00eda deshacerte de ese esc\u00e1ner gigante y lo bien que quedar\u00eda tu comedor sin la radio de tu abuela, hay soluciones.<\/p>\n<p>Hay formas de <strong>ganar espacio<\/strong> y, una de ellas, es aprovechar tu smartphone. Si no lo crees, te lo demostramos.<\/p>\n<p><!--more--><\/p>\n<ul class=\"nolist\">\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14325\" title=\"scanner\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/scanner.png\" alt=\"\" width=\"90\" height=\"90\" \/>Si tienes uno de esos gigantes <strong>esc\u00e1neres <\/strong>de hace a\u00f1os ocupando media mesa, o lo guardas en un armario porque casi no lo usas, aplicaciones como <a href=\"http:\/\/camscanner.softonic.com\/android\">Camscanner<\/a> pueden ayudarte a salir del paso.\n<p>Su calidad es aceptable y caben en el bolsillo.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14326\" title=\"mando\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/mando.png\" alt=\"\" width=\"90\" height=\"90\" \/>Para <strong>controlar el PC<\/strong>, una tele o la puerta del garaje, hay aplicaciones que te dejar\u00e1n con la boca abierta.\n<p>Te recomendamos echar un vistazo a nuestra secci\u00f3n de <a href=\"http:\/\/www.softonic.com\/s\/mando-a-distancia:movil\">controles remotos<\/a>.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14339\" title=\"radio\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/radio.png\" alt=\"\" width=\"90\" height=\"90\" \/>Con un par de altavoces y tu tel\u00e9fono puedes construir una <a href=\"http:\/\/www.softonic.com\/movil\/radio\"><strong>radio<\/strong><\/a> en condiciones. No hace falta ocupar media estanter\u00eda.\n<p>S\u00f3lo necesitas una buena <strong>conexi\u00f3n a Internet <\/strong>y podr\u00e1s escuchar radios de todo el mundo; mejor que tu viejo transistor.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14328\" title=\"camera\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/camera.png\" alt=\"\" width=\"90\" height=\"90\" \/>No saldr\u00e1n como las que sacabas con tu vieja <strong>c\u00e1mara <\/strong>r\u00e9flex pero, \u00bfhay alguna c\u00e1mara mejor que la que llevas siempre encima?\n<p>Con aplicaciones como <a href=\"http:\/\/instagram.softonic.com\/iphone\">Instagram<\/a> o <a href=\"http:\/\/picplz.softonic.com\/android\">Picplz<\/a> conseguir\u00e1s adem\u00e1s efectos impresionantes.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14329\" title=\"telefono\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/telefono.png\" alt=\"\" width=\"90\" height=\"90\" \/>Est\u00e1 claro: a no ser que tengas mejores precios si llamas desde una l\u00ednea fija, mucha gente tiene el <strong>tel\u00e9fono<\/strong> casi como decoraci\u00f3n.\n<p>Acumula polvo y quita espacio para poner, por ejemplo, un par de cactus o la foto de tu perro. Seguro que ya conoces <a href=\"http:\/\/skype-lite.softonic.com\/android\">Skype<\/a> o <a href=\"http:\/\/skype-lite.softonic.com\/android\">Viber<\/a>.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14330\" title=\"tele\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/tele.png\" alt=\"\" width=\"90\" height=\"90\" \/>Si has decidido cambiar la <strong>televisi\u00f3n <\/strong>por un rinc\u00f3n m\u00e1s r\u00fastico con chimenea, no tienes por qu\u00e9 perderte tu programa preferido.\n<p>En m\u00f3viles con pantallas de alta resoluci\u00f3n, <a href=\"http:\/\/www.softonic.com\/movil\/television-online\">ver la tele<\/a> no es ya tarea imposible.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14331\" title=\"reloj\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/reloj.png\" alt=\"\" width=\"90\" height=\"90\" \/>A no ser que seas un aficionado a los <a href=\"http:\/\/www.softonic.com\/movil\/relojes-y-alarmas\"><strong>relojes<\/strong><\/a>, un reloj de pie ocupa el mismo espacio que una buena l\u00e1mpara o una peque\u00f1a palmera.\n<p>Si est\u00e1s pensando en darle mejor vida al cuco, siempre puedes ver la hora en la pantalla de \u2013casi- cualquier m\u00f3vil.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14332\" title=\"calculadora\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/calculadora1.png\" alt=\"\" width=\"90\" height=\"90\" \/>Para hacer las cuentas de casa o para saber si llegas a fin de mes, las <a href=\"http:\/\/www.softonic.com\/s\/calculadora:movil\"><strong>calculadoras<\/strong><\/a> son una de aquellas herramientas que nunca faltaban en ninguna casa.\n<p>Si puedes vivir con sumas, restas y porcentajes, tu smartphone es, seguramente, m\u00e1s que suficiente.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14333\" title=\"recetas\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/recetas.png\" alt=\"\" width=\"90\" height=\"90\" \/>Libros de miles de p\u00e1ginas, libretas viejas y notas que se pierden entre trapos y cacerolas. \u00bfQu\u00e9 mejor que reunir tus <a href=\"http:\/\/www.softonic.com\/movil\/cocina\"><strong>recetas<\/strong> <\/a>en una sencilla y pr\u00e1ctica aplicaci\u00f3n como<a href=\"http:\/\/canal-cocina.softonic.com\/symbian\"> Canal Cocina<\/a> o <a href=\"http:\/\/recetario.softonic.com\/android\">Recetario<\/a>?\n<p>Puedes ver m\u00e1s en nuestra categor\u00eda de <a href=\"http:\/\/www.softonic.com\/movil\/cocina\">cocina<\/a>.<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14334\" title=\"martillo\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2011\/08\/martillo.png\" alt=\"\" width=\"90\" height=\"90\" \/>Si no tienes un smartphone pero tu m\u00f3vil pesa lo suficiente, siempre puedes usarlo de <strong>pisapapeles<\/strong>.\n<p>Lo mismo si tienes que darle un golpe a un clavo mal puesto, tambi\u00e9n te sirve.<\/li>\n<\/ul>\n<p>\u00bfHas cambiado alguno de estos electrodom\u00e9sticos por el tel\u00e9fono? \u00bfCu\u00e1l es el uso m\u00e1s raro que le has dado a tu m\u00f3vil?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1ntos cacharros in\u00fatiles acumulas en casa? Si siempre has pensado en lo bien que estar\u00eda deshacerte de ese esc\u00e1ner gigante y lo bien que quedar\u00eda tu comedor sin la radio de tu abuela, hay soluciones. Hay formas de ganar espacio y, una de ellas, es aprovechar tu smartphone. Si no lo crees, te lo demostramos.<\/p>\n","protected":false},"author":1028,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-14324","post","type-post","status-publish","format-standard","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/14324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/1028"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=14324"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/14324\/revisions"}],"predecessor-version":[{"id":385334,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/14324\/revisions\/385334"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=14324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=14324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=14324"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=14324"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=14324"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=14324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}