{"id":200735,"date":"2019-10-14T10:59:55","date_gmt":"2019-10-14T10:59:55","guid":{"rendered":"http:\/\/sftarticles.wpenginepowered.com\/es\/?p=200735"},"modified":"2025-06-12T22:48:50","modified_gmt":"2025-06-12T20:48:50","slug":"tutorial-crear-tablas-dinamicas-microsoft-excel","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/tutorial-crear-tablas-dinamicas-microsoft-excel\/","title":{"rendered":"El tutorial completo para crear tablas din\u00e1micas de Microsoft Excel"},"content":{"rendered":"<p><a href=\"https:\/\/microsoft-excel.softonic.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Microsoft Excel<\/strong> <\/a>es uno de los programas m\u00e1s utilizados alrededor del mundo para crear <strong>hojas de c\u00e1lculo<\/strong>. Esto se debe en su mayor medida a su extraordinaria capacidad de manejar y analizar datos, siendo una herramienta perfecta tanto para presentar informaci\u00f3n como para tomar importantes decisiones laborales. Sin embargo, todos los que hemos utilizado Excel en alg\u00fan momento de nuestras vidas conocemos su oscuro secreto: <strong>no es un programa sencillo de dominar<\/strong>.<\/p>\n<p>Una de las funciones m\u00e1s \u00fatiles de Microsoft Excel son sus <strong>tablas din\u00e1micas<\/strong>. \u00c9stas permiten agrupar gran cantidad de informaci\u00f3n, filtrarla y destacar aquellos datos que puedan ser \u00fatiles para el usuario. Esto es de gran importancia e utilidad a la hora, por ejemplo, de analizar una tabla con un n\u00famero&nbsp; desproporcionado de datos en apenas unos segundos. Sin embargo, para muchos <strong>no es un proceso sencillo<\/strong>.<\/p>\n<p>Y es que tal y como os hemos adelantado, Excel no es un programa intuitivo pero no por ello significa que sea imposible o&nbsp; menos \u00fatil. En el art\u00edculo de hoy te vamos a ense\u00f1ar <strong>c\u00f3mo crear y utilizar una tabla din\u00e1mica en Excel<\/strong> as\u00ed como peque\u00f1os trucos para facilitarte este proceso. Esperamos que te sirva de ayuda.<\/p>\n<h2><strong>\u00bfQu\u00e9 es una tabla din\u00e1mica de Excel?<\/strong><\/h2>\n<p>Para muchos \u00e9sta resulta la pregunta del mill\u00f3n, pues todos hemos o\u00eddo hablar de las <strong>tablas din\u00e1micas de Excel<\/strong> pero pocos sabemos realmente qu\u00e9 son. Hoy vamos a sacarte de toda duda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200736\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/Excel_gmegog.jpg\" width=\"700\" height=\"394\"><\/p>\n<p>Las tablas din\u00e1micas de Excel son una herramienta destinada a<strong> analizar los datos de una tabla<\/strong> <strong>previamente creada<\/strong> y visualizar \u00fanicamente aquella informaci\u00f3n considerada relevante. Esto se consigue mediante dos procesos clave llamados sumarizaci\u00f3n y rotaci\u00f3n. La <strong>sumarizaci\u00f3n<\/strong> permite que Excel resuma datos de un mismo tipo mientras que la <strong>rotaci\u00f3n<\/strong> ofrece la posibilidad al usuario de colocar, quitar o mover cualquier campo de la tabla original para que sus datos sean analizador por el programa.<\/p>\n<p>Para explicarlo de forma sencilla, las tablas din\u00e1micas son una herramienta que <strong>nos permite elegir a nuestro antojo o a medida la estructura en que los datos de una tabla original ser\u00e1n tratados<\/strong>. As\u00ed pues podr\u00e1s elegir sus columnas, filas y valores as\u00ed como tambi\u00e9n c\u00f3mo sus datos interact\u00faan entre ellos. Es por esa misma raz\u00f3n que tambi\u00e9n se conocen por su nombre ingl\u00e9s <em>pivot table<\/em>&nbsp;o tablas de pivote.<\/p>\n<h2><strong>\u00bfPara qu\u00e9 sirven las tablas din\u00e1micas de Excel?<\/strong><\/h2>\n<p>Como ya te hemos adelantado, las tablas din\u00e1micas de Excel sirven para <strong>analizar grandes cantidades de datos de una tabla original<\/strong>. Esto se consigue intercambiando columnas por filas o por ejemplo a\u00f1adiendo filtros que de otro modo tardar\u00edamos horas en realizar a mano.<\/p>\n<p>Por poner un <strong>ejemplo sencillo<\/strong>, imagina que tenemos un blog en el que escriben varios editores y has creado una tabla para apuntar cada vez que se hace una publicaci\u00f3n, el editor en cuesti\u00f3n, la tem\u00e1tica del art\u00edculo y el n\u00famero de visitas del art\u00edculo. Gracias a una tabla din\u00e1mica podr\u00e1s recopilar todos esos datos y ver, por ejemplo, qu\u00e9 editor ha conseguido m\u00e1s visitas cada mes o qu\u00e9 tipo de art\u00edculo es el que mejor funciona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200738\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/tabla_dinamica_excel_1_dnak0v.jpg\" width=\"521\" height=\"483\"><\/p>\n<p>Este tipo de informaci\u00f3n no puede verse en la tabla original pues la cantidad de datos recopilados (varias entradas diarias por art\u00edculo) pueden llegar a ser exhorbitados. Es por ello que <strong>las tablas din\u00e1micas resultan tan \u00fatiles<\/strong> realizar informes de empresa.<\/p>\n<h2><strong>\u00bfCu\u00e1ndo debo utilizar una tabla din\u00e1mica?<\/strong><\/h2>\n<p>Las tablas din\u00e1micas (<em>pivot tables<\/em>) deben utilizarse siempre que quieras <strong>analizar los datos de una tabla original<\/strong> <strong>pero desde distintos puntos de vista<\/strong>. Es decir, siempre que quieras comparar alguno de sus valores con otros, ocultando temporalmente aquellos que no necesites,y as\u00ed conseguir una nueva perspectiva de dicha base de datos.<\/p>\n<h2><strong>C\u00f3mo crear una tabla din\u00e1mica en Excel<\/strong><\/h2>\n<p>El primer paso para poder crear una tabla din\u00e1mica en Excel es <strong>tener una hoja de c\u00e1lculo con todos los datos que queramos analizar<\/strong> en sus respectivas filas y columnas. \u00c9sta servir\u00e1 como el origen de datos de la tabla din\u00e1mica de Excel. Una vez tengas esta hoja abierta, selecciona las celdas o la tabla completa que quieras utilizar y haz clic en la opci\u00f3n <strong>Insertar &gt; Tabla din\u00e1mica<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200739\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/tabla_dinamica_excel_2_labcfj.jpg\" alt=\"\" width=\"470\" height=\"400\"><\/p>\n<p>Si has realizado este paso correctamente, aparecer\u00e1 una nueva ventana donde se solicitar\u00e1n varios datos acerca de tu nueva tabla. Ver\u00e1s que el campo <strong>&#8220;Seleccione una tabla o rango&#8221;<\/strong> aparecer\u00e1 ya completado autom\u00e1ticamente con las celdas y columnas que seleccionaste en el paso anterior.<\/p>\n<p>Ahora tan s\u00f3lo queda elegir d\u00f3nde va a crearse el informe de tabla din\u00e1mica. Si eliges <strong>&#8220;Nueva hoja de c\u00e1lculo&#8221;<\/strong> se crear\u00e1 una nueva hoja donde aparecer\u00e1 tu tabla din\u00e1mica. Si por el contrario quieres que aparezca en la misma hoja que tu tabla original, pulsa en <strong>&#8220;Hoja de c\u00e1lculo existente&#8221;<\/strong> e introduce su ubicaci\u00f3n. Tras ello pulsa el bot\u00f3n <strong>&#8220;Aceptar&#8221;<\/strong>.<\/p>\n<p>Una vez hecho, Excel habr\u00e1 creado tu tabla din\u00e1mica con los datos seleccionados. \u00c9sta aparecer\u00e1 en blanco, no te preocupes pues normal, <strong>todav\u00eda tienes que configurarla<\/strong>. Para ello necesitar\u00e1s utilizar el panel derecho de la pantalla donde podr\u00e1s seleccionar y ubicar los datos que quieras manejar y relacionar entre ellos. De ello te hablaremos en detalle en el siguiente punto.<\/p>\n<h3><strong>C\u00f3mo personalizar tu tabla din\u00e1mica<\/strong><\/h3>\n<p>Una vez creada tu tabla din\u00e1mica, es hora de personalizar su comportamiento a la hora de analizar los datos. Para ello deber\u00e1s desplazar cada uno de los campos de tabla din\u00e1mica (puedes encontrarlos en el men\u00fa lateral derecho) y soltarlos en las categor\u00edas <strong>&#8220;Filtros&#8221;<\/strong>, <strong>&#8220;Columnas&#8221;<\/strong>, <strong>&#8220;Filas&#8221;<\/strong> y <strong>&#8220;Valores&#8221;<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200740\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/tabla_dinamica_excel_3_iozb3l.jpg\" width=\"302\" height=\"366\"><\/p>\n<p>Arrastrar un campo a <strong>&#8220;Columnas&#8221;<\/strong> y otro a <strong>&#8220;Filas&#8221;<\/strong> va a comparar ambos datos. Si estamos tratando datos num\u00e9ricos, arrastra el campo hasta la ventana <strong>&#8220;Valores&#8221;<\/strong> para que se realicen operaciones matem\u00e1ticas como la suma de todos los datos de la lista.<\/p>\n<p>Con tu tabla din\u00e1mica ya configurada, recuerda que puedes esconder o filtrar todos los datos que desees movi\u00e9ndolos a secci\u00f3n <strong>&#8220;Filtros&#8221;<\/strong> o simplemente pulsando en la casilla junto a su nombre.<\/p>\n<p>Si lo deseas y para tener as\u00ed una mejor experiencia como usuario, tras configurar tu tabla din\u00e1mica puedes <strong>esconder el panel lateral derecho<\/strong> pulsando en la <strong>&#8220;X&#8221;<\/strong> de la esquina superior derecha de su ventana. Para volver a abrir el panel, simplemente haz clic con el bot\u00f3n derecho sobre la tabla y pulsa en la opci\u00f3n <strong>&#8220;Mostrar&#8221;<\/strong> seguido de <strong>&#8220;Lista de campos&#8221;<\/strong>.<\/p>\n<h3><strong>C\u00f3mo agrupar los datos de tu tabla din\u00e1mica<\/strong><\/h3>\n<p>Es habitual que si tienes una hoja de c\u00e1lculo con muchos campos, desees agrupar o combinar algunos de ellos. Para poder hacer esto es muy importante recordar que <strong>los datos a agrupar deben ser equivalentes<\/strong> (periodos de tiempo, visitas a una p\u00e1gina web, etc.), de lo contrario Excel no a ofrecerte esta opci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200741\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/agrupar_datos_ydgace.jpg\" width=\"480\" height=\"447\"><\/p>\n<p>Si quieres agrupar alguno de los datos de tu tabla, simplemente haz clic con el bot\u00f3n derecho del rat\u00f3n sobre la celda de la columna a combinar y selecciona la opci\u00f3n <strong>&#8220;Agrupar&#8221;<\/strong>. Tras ello ver\u00e1s como los datos de dichas columnas se unir\u00e1n.<\/p>\n<p>En el caso de que posteriormente quieras desagrupar las columnas, simplemente haz clic con el bot\u00f3n derecho del rat\u00f3n sobre ella y selecciona la opci\u00f3n <strong>&#8220;Desagrupar&#8221;<\/strong>. Tu tabla volver\u00e1 a estar exactamente igual que antes de realizar el proceso.<\/p>\n<h3><strong>C\u00f3mo realizar una segmentaci\u00f3n de datos<\/strong><\/h3>\n<p>Si estamos utilizando una tabla con rango de datos muy elevado, es probable que queramos<strong> filtrar gran parte de esa informaci\u00f3n mediante segmentos<\/strong>. Para este tipo de situaciones utilizamos la segmentaci\u00f3n de datos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200742\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/tabla_dinamica_excel_4_kxacpo.jpg\" width=\"691\" height=\"374\"><\/p>\n<p>Para activar la segmentaci\u00f3n de datos, selecciona cualquier celda de tu tabla y selecciona la opci\u00f3n <strong>&#8220;Insertar&#8221;<\/strong> seguido de <strong>&#8220;Segmentaci\u00f3n de datos&#8221;<\/strong>. Tras ello se abrir\u00e1 un cuadro de di\u00e1logo donde debes seleccionar las casillas de los campos que quieres mostrar. Esto crear\u00e1 una segmentaci\u00f3n con los campos seleccionados a modo de ventana flotante que podr\u00e1s mover a tu antojo.<\/p>\n<p>La segmentaci\u00f3n de datos es realmente \u00fatil pues permite <strong>filtrar los elementos de tu tabla din\u00e1mica en apenas unos clics<\/strong>. Simplemente pulsa en aquellas entradas que te interesan y ver\u00e1s como todas las segmentaciones se actualizar\u00e1n autom\u00e1ticamente en la tabla.<\/p>\n<h3><strong>C\u00f3mo crear gr\u00e1ficos din\u00e1micos<\/strong><\/h3>\n<p>Las tablas din\u00e1micas son realmente \u00fatiles para analizar y comparar datos de forma r\u00e1pida y sencilla, aunque en ocasiones una imagen vale m\u00e1s que mil palabras. Es por ello que Excel ofrece la opci\u00f3n de mostrar un <strong>gr\u00e1fico din\u00e1mico<\/strong> de tus datos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200743\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/tabla_dinamica_excel_5_hi7tva.jpg\" width=\"764\" height=\"381\"><\/p>\n<p>Para ello pulsa en <strong>&#8220;Analizar&#8221;<\/strong> seguido de <strong>&#8220;Gr\u00e1fico din\u00e1mico&#8221;<\/strong>. Esto abrir\u00e1 una nueva ventana mostr\u00e1ndote todos los tipos de gr\u00e1fico disponibles ordenados por categor\u00eda. Selecciona el que m\u00e1s se ajuste a tus necesidades y aparecer\u00e1 un gr\u00e1fico con los datos de tu tabla. Para configurar el gr\u00e1fico, utiliza el <strong>panel lateral derecho<\/strong> de la pantalla del mismo modo que lo usas para configurar la tabla din\u00e1mica.<\/p>\n<h3><strong>C\u00f3mo a\u00f1adir nuevos datos a una tabla din\u00e1mica de Excel<\/strong><\/h3>\n<p>Puesto que la tabla din\u00e1mica est\u00e1 asociada a la base de datos original, en todo momento vas a poder a\u00f1adir nuevos datos. Para ello simplemente acude a tu<strong> tabla original<\/strong>, introduce los datos pertinentes y luego visita tu tabla din\u00e1mica. Ya en su hoja, haz clic con el bot\u00f3n derecho sobre la tabla y selecciona<strong> &#8220;Analizar&#8221;<\/strong> seguido de la opci\u00f3n <strong>&#8220;Actualizar&#8221;<\/strong>. La lista de campos de la tabla din\u00e1mica se actualizar\u00e1 al instante con los valores de la hoja de c\u00e1lculo original.<\/p>\n<h2><strong>Alternativas a Excel para utilizar tablas din\u00e1micas<\/strong><\/h2>\n<p>Aunque Excel es un programa excelente para trabajar con bases de datos, tambi\u00e9n tiene un <strong>precio elevado<\/strong> y en ocasiones puede resultar prohibitivo para los usuarios. Por fortuna Microsoft es consciente de ello y ofrece la posibildad de usar Excel de forma gratuita a trav\u00e9s de <strong>Office Online<\/strong>.<\/p>\n<p>Para poder utilizar la <strong>versi\u00f3n gratis de Excel<\/strong> tan s\u00f3lo necesitar\u00e1s tener una cuenta de Microsoft. Conseguir una es muy sencillo y adem\u00e1s es completamente gratis, tan s\u00f3lo debes hacer clic en <a href=\"https:\/\/account.microsoft.com\/account?lang=es-cl\"><strong>este enlace<\/strong><\/a> y completar los datos que aparecen en pantalla.<\/p>\n<p>Una vez con tu cuenta de Microsoft activa, visita la p\u00e1gina oficial de <a href=\"https:\/\/www.office.com\/?omkt=es-es\"><strong>Office Online<\/strong><\/a> e introduce tus datos de inicio de sesi\u00f3n. Tras acceder a la suite de ofim\u00e1tica en l\u00ednea, <strong>selecciona la opci\u00f3n Excel<\/strong> y tendr\u00e1s acceso al procesador de datos de forma gratuita. Si bien esta versi\u00f3n de Excel es mucho m\u00e1s simple que la incluida en la versi\u00f3n de pago de Office, tambi\u00e9n permite realizar tablas din\u00e1micas, comparar datos e incluso mostrar gr\u00e1ficos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200744\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/office_online_olhmfi.jpg\" width=\"1160\" height=\"219\"><\/p>\n<p>Esperamos que nuestra gu\u00eda te haya servido de ayuda para entender un poco m\u00e1s <strong>qu\u00e9 son y c\u00f3mo utilizar las tablas din\u00e1micas de Microsoft Excel<\/strong>. Cualquier duda que tengas sobre el proceso, no dudes en ponerte en contacto con nosotros a trav\u00e9s de la secci\u00f3n de comentarios.<\/p>\n<div class=\"sc-card-starred-link\">\r\n  <div class=\"sc-card-starred-link__body\">\r\n    <div class=\"sc-card-starred-link__row clearfix\">\r\n      <div class=\"sc-card-starred-link__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-starred-link__img\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/9\/2013\/11\/15-May-14-12-53-18-PM-568x285.jpg\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-starred-link__col-title\">\r\n        <p class=\"sc-card-starred-link__title\">10 f\u00f3rmulas de Excel que todo el mundo debe conocer<\/p>\r\n        <a class=\"sc-card-starred-link__button\" href=\"https:\/\/www.softonic.com\/articulos\/10-formulas-excel-nuy-utiles\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">LEE M\u00c1S<\/a>\r\n      <\/div>\r\n    <\/div>\r\n    <a class=\"sc-card-starred-link__link\" href=\"https:\/\/www.softonic.com\/articulos\/10-formulas-excel-nuy-utiles\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><\/a>\r\n  <\/div>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft Excel es uno de los programas m\u00e1s utilizados alrededor del mundo para crear hojas de c\u00e1lculo. Esto se debe en su mayor medida a su extraordinaria capacidad de manejar y analizar datos, siendo una herramienta perfecta tanto para presentar informaci\u00f3n como para tomar importantes decisiones laborales. Sin embargo, todos los que hemos utilizado Excel &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/es\/tutorial-crear-tablas-dinamicas-microsoft-excel\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;El tutorial completo para crear tablas din\u00e1micas de Microsoft Excel&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1051,"featured_media":242805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[9706],"tags":[9745],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-200735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","tag-app-subdomain-redirectionmicrosoft-excel"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/200735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/1051"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=200735"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/200735\/revisions"}],"predecessor-version":[{"id":367677,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/200735\/revisions\/367677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/242805"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=200735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=200735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=200735"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=200735"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=200735"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=200735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}