{"id":201604,"date":"2019-11-21T16:33:04","date_gmt":"2019-11-21T16:33:04","guid":{"rendered":"http:\/\/sftarticles.wpenginepowered.com\/es\/?p=201604"},"modified":"2025-06-12T22:45:56","modified_gmt":"2025-06-12T20:45:56","slug":"windows-10-actualizacion-obligatoria","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/windows-10-actualizacion-obligatoria\/","title":{"rendered":"Windows 10 te obliga a actualizarte aunque no quieras: \u00bfafecta a tu PC?"},"content":{"rendered":"<p><a href=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/windows_logo_gnvnsv-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-201611\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/windows_logo_gnvnsv-1.jpg\" alt=\"\" width=\"500\" height=\"281\"><\/a><\/p>\n<p>Las actualizaciones de Windows 10 est\u00e1n por defecto activadas, pero<a href=\"https:\/\/www.softonic.com\/articulos\/como-desactivar-actualizaciones-windows-10\" target=\"_blank\" rel=\"noopener noreferrer\"> hay una forma muy sencilla de desactivarlas<\/a> para instalarlas cuando queramos. Ahora bien: en breve <strong>Microsoft obligar\u00e1 a ciertos PC a actualizar a una nueva versi\u00f3n de Win10 y no se podr\u00e1 hacer nada para evitarlo.<\/strong><\/p>\n<p>Estas actualizaciones obligadas las recibir\u00e1n todos aquellos PCs que no se hayan actualizado desde<strong> abril de 2018<\/strong>, es decir, desde la versi\u00f3n 1803 de Windows 10.<\/p>\n<p>Esto se debe a&nbsp;&nbsp;el&nbsp;soporte para la versi\u00f3n 1803 de abril de 2018 para Windows 10 ya ha caducado, lo que se traduce en que esta versi\u00f3n del sistema operativo <strong>no recibe parches de seguridad<\/strong>. As\u00ed pues, si un ordenador la tiene y no se actualizase ser\u00eda vulnerable a muchas amenazas.<\/p>\n<p>Lo que no sabemos es a qu\u00e9 versi\u00f3n de Windows 10 se actualizar\u00e1n estos equipos. La \u00faltima disponible es la 1903, conocida como May Update.<\/p>\n<div class=\"sc-card-starred-link\">\r\n  <div class=\"sc-card-starred-link__body\">\r\n    <div class=\"sc-card-starred-link__row clearfix\">\r\n      <div class=\"sc-card-starred-link__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-starred-link__img\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2019\/05\/Windows10-May-2019-Update-1024x576.jpg\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-starred-link__col-title\">\r\n        <p class=\"sc-card-starred-link__title\">Windows 10 May Update 2019: todo lo que debes saber<\/p>\r\n        <a class=\"sc-card-starred-link__button\" href=\"https:\/\/www.softonic.com\/articulos\/windows-10-may-update-2019-todo-lo-que-debes-saber\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Leer m\u00e1s<\/a>\r\n      <\/div>\r\n    <\/div>\r\n    <a class=\"sc-card-starred-link__link\" href=\"https:\/\/www.softonic.com\/articulos\/windows-10-may-update-2019-todo-lo-que-debes-saber\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><\/a>\r\n  <\/div>\r\n<\/div>\n<p>Aunque esta actualizaci\u00f3n forzada ser\u00e1 obligatoria para todos los equipos, Microsoft detalla que permitir\u00e1 al usuari<strong>o decidir en qu\u00e9 hora se descargar\u00e1 a instalar\u00e1<\/strong>. As\u00ed pues, si el usuario est\u00e1 trabajando no deber\u00e1 parar lo que est\u00e1 haciendo y podr\u00e1 programarla para una hora en la que no necesite usar su PC.<\/p>\n<p>\u00bfC\u00f3mo puedes saber si te afecta esta actualizaci\u00f3n autom\u00e1tica? F\u00e1cil: <strong>haz clic en el bot\u00f3n Windows y ve a <em>Configuraci\u00f3n&gt;Sistema&gt;Acerca de<\/em>.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-201609\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/actualizacion-windows_nvmkxu.jpg\" width=\"498\" height=\"401\"><\/p>\n<p>En esta pantalla se mostrar\u00e1 qu\u00e9 versi\u00f3n de Windows 10 tienes intalada. Si te ocurre como en el ejemplo de la imagen pronto el sistema operativo te mostrar\u00e1 una notificaic\u00f3n para que actualices. Si es superior a la versi\u00f3n 1803, no.<\/p>\n<div class=\"sc-card-starred-link\">\r\n  <div class=\"sc-card-starred-link__body\">\r\n    <div class=\"sc-card-starred-link__row clearfix\">\r\n      <div class=\"sc-card-starred-link__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-starred-link__img\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2017\/09\/whatsapp-logo-1024x576.jpg\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-starred-link__col-title\">\r\n        <p class=\"sc-card-starred-link__title\">Gu\u00eda de WhatsApp: los mejores trucos, tutoriales y art\u00edculos<\/p>\r\n        <a class=\"sc-card-starred-link__button\" href=\"https:\/\/www.softonic.com\/articulos\/guia-de-whatsapp\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Leer m\u00e1s<\/a>\r\n      <\/div>\r\n    <\/div>\r\n    <a class=\"sc-card-starred-link__link\" href=\"https:\/\/www.softonic.com\/articulos\/guia-de-whatsapp\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><\/a>\r\n  <\/div>\r\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft lanza una actualizaci\u00f3n obligatoria para evitar brechas de seguridad<\/p>\n","protected":false},"author":2041,"featured_media":200049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[9317],"tags":[9734,9359],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-201604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-app-subdomain-redirectionwindows-10","tag-windows-10"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/201604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/2041"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=201604"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/201604\/revisions"}],"predecessor-version":[{"id":367624,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/201604\/revisions\/367624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/200049"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=201604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=201604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=201604"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=201604"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=201604"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=201604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}