{"id":224105,"date":"2021-05-31T11:04:18","date_gmt":"2021-05-31T11:04:18","guid":{"rendered":"http:\/\/sftarticles.wpenginepowered.com\/es\/?p=224105"},"modified":"2024-08-08T13:12:06","modified_gmt":"2024-08-08T11:12:06","slug":"tutorial-adobe-photoshop-2","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/tutorial-adobe-photoshop-2\/","title":{"rendered":"C\u00f3mo funciona Photoshop: trucos y tutoriales para principiantes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Has hecho una foto que tiene margen de mejora y no quieres mandarla a la \u201cPapelera de reciclaje\u201d. Tranquilo: no est\u00e1s solo. A todos nos ha pasado alguna vez que esa instant\u00e1nea que tanto quer\u00edas resulta que no vale, que no da el nivel adecuado, que est\u00e1 lejos de los est\u00e1ndares de calidad que a ti te gustar\u00edan o que, simplemente, quieres mejorarla con un programa como <strong>Adobe Photoshop<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Adobe Photoshop podemos editar y modificar todas las im\u00e1genes hasta l\u00edmites insospechables. El programa rey de edici\u00f3n para los dise\u00f1adores y fot\u00f3grafos es complejo de utilizar, pero hoy <strong>te vamos a mostrar en esta gu\u00eda algunos consejos b\u00e1sicos sobre Adobe Photoshop<\/strong>.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_optimized,f_auto\/p\/bbdedd58-96bf-11e6-ab2f-00163ed833e7\/1967335692\/adobe-photoshop-cc-logo.png\" alt=\"Adobe Photoshop\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Adobe Photoshop<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/adobe-photoshop.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\">Descarga aqu\u00ed<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--100\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"100\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"10\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\">10<\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\">Adobe Photoshop CC 2015 es el editor gr\u00e1fico m\u00e1s avanzado que existe, capaz de hacer desde simples fotomontajes a complejos dise\u00f1os 3D e ilustraciones<\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/adobe-photoshop.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo funciona Photoshop?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Adobe Photoshop<\/strong> siempre ha sido conocido por ser el <strong>programa de edici\u00f3n de fotos <\/strong>por antonomasia, aunque en realidad, es mucho m\u00e1s que eso. Actualmente, los usos que le puedes dar a este programa son muy variados, abarcando campos tan variopintos como el de la <strong>ilustraci\u00f3n<\/strong>, la <strong>animaci\u00f3n<\/strong> o la <strong>fotograf\u00eda<\/strong>, como hemos mencionado m\u00e1s arriba.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser tan completa, Photoshop puede llegar a <strong>confundir<\/strong> f\u00e1cilmente a los usuarios de primeras y convertirse en algo <strong>abrumador<\/strong>. Antes de comenzar, es necesario que te familiarices con su <strong>interfaz <\/strong>y que conozcas <strong>los apartados m\u00e1s importantes que posee Photoshop<\/strong>, los cuales te desglosamos a continuaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25cf<\/strong> <a href=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-descargar-adobe-photoshop\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-descargar-adobe-photoshop\">C\u00f3mo descargar Adobe Photoshop<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25cf<\/strong> <a href=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-instalar-adobe-photoshop\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3mo instalar Adobe Photoshop<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trucos y consejos para principiantes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando abrimos Photoshop, ante nosotros se nos abre una gran cantidad de utilidades y herramientas con funciones muy variadas. No te preocupes, ya que no es necesario conocerse al dedillo cada opci\u00f3n existente, pero s\u00ed es importante que aprendamos a diferenciar las<strong> \u00e1reas existentes <\/strong>para saber d\u00f3nde buscar cada cosa y lo que podemos hacer en cada una de ellas. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Interfaz de Photoshop<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed podemos ver varias \u00e1reas diferentes compuestas por:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La barra de <strong>men\u00fas<\/strong><\/li><li>La barra de <strong>herramientas<\/strong><\/li><li>El <strong>espacio de trabajo<\/strong><\/li><li>Paneles de <strong>herramientas<\/strong><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/10\/photoshop3-1024x576.jpg\" alt=\"\" class=\"wp-image-239986\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la <strong>barra de men\u00fas<\/strong> manejamos las funciones m\u00e1s esenciales, como <strong>crear un lienzo<\/strong> o <strong>abrir una imagen <\/strong>ya existente. Aqu\u00ed encontraremos tambi\u00e9n campos m\u00e1s espec\u00edficos como <strong>Archivo<\/strong>, <strong>Imagen<\/strong> o <strong>Capas<\/strong>, donde controlamos las propiedades de nuestro proyecto (resoluci\u00f3n, tama\u00f1o de imagen\u2026). Por ejemplo, si quisi\u00e9ramos abrir un archivo existente para editarlo, tendr\u00edamos que dirigirnos a <strong>Archivo<\/strong>, clicar en <strong>Abrir<\/strong> y luego, seleccionar la imagen en cuesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si por el contrario quisi\u00e9ramos crear de cero un lienzo en blanco, deber\u00edamos irnos a <strong>Archivo<\/strong> y luego, seleccionar <strong>Nuevo<\/strong>. Photoshop desplegar\u00e1 un men\u00fa donde podremos personalizar las propiedades de nuestro proyecto como su <strong>tama\u00f1o<\/strong> y <strong>resoluci\u00f3n. <\/strong>Es altamente recomendable que cuando est\u00e9s familiarizado con el programa, te aprendas los <strong>atajos de teclado<\/strong>, ya que agilizar\u00e1n tu proceso y ahorrar\u00e1s mucho tiempo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/10\/photoshop4-1024x576.jpg\" alt=\"\" class=\"wp-image-239987\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En la <strong>barra de herramientas<\/strong> podr\u00e1s observar una lista de utilidades con las que trabajar\u00e1s muy a menudo. De aqu\u00ed podemos destacar las herramientas de <strong>selecci\u00f3n<\/strong> (Mover, Marco, Lazo, Selecci\u00f3n r\u00e1pida), las de <strong>recorte<\/strong> (Recortar, Sector), las de <strong>medida<\/strong> (Cuentagotas, Regla), las de <strong>retoque<\/strong> (Pincel corrector, Parche, Tamp\u00f3n de clonar, Blur, Sobreexponer), las de <strong>pintar<\/strong> (Pincel, L\u00e1piz, Bote de pintura), las de <strong>texto<\/strong> (Texto) y <strong>navegaci\u00f3n<\/strong> (Mano, Zoom). Esta barra es <strong>personalizable<\/strong> y siempre puedes adaptarla con las funcionalidades que m\u00e1s uses en tus proyectos.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/10\/photoshop5.jpg\" alt=\"\" class=\"wp-image-239988\" width=\"389\" height=\"499\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Transformar una imagen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con las transformaciones de im\u00e1genes conseguimos que una captura pueda ampliarse o disminuirse, as\u00ed como hacerle todo tipo de giros o volteos. Es perfecto para cuando, por ejemplo, tenemos que ajustar en un marco una foto de tama\u00f1o superior. Para lograrlo, s\u00f3lo es necesario hacer click derecho encima de la imagen y cliquear en &#8220;Transformaci\u00f3n libre&#8221; (o el comando &#8220;<strong>Control + T<\/strong>&#8220;). Desde este momento, la imagen la puedes modificar como te d\u00e9 la gana. Si quieres que se mantengan las proporciones, recuerda pulsar la tecla Shift mientras la estiras o disminuyes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/images\/w_1024,h_576,c_scale\/v1589024493\/photoshop_transformar_cjniur\/photoshop_transformar_cjniur-1024x576.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ajustar la iluminaci\u00f3n (o modificar el histograma)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un cl\u00e1sico: ajustar la iluminaci\u00f3n de la fotograf\u00eda para hacer que resalte justo donde queremos. Hablando de manera t\u00e9cnica, abrir el histograma. Para realizar esta acci\u00f3n s\u00f3lo es necesario pulsar \u201c<strong>Control + L<\/strong>\u201d. \u00bfQue no tienes mucho manejo con los comandos abreviados? Pues te vas a \u201cImagen\u201d -&gt; \u201cAjustes\u201d -&gt; \u201c<strong>Niveles<\/strong>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/11\/trucosphotoshop2-1024x543-1.jpg\" alt=\"\" class=\"wp-image-240531\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recalcar que manejar el histograma no es nada sencillo, ya que puedes destrozar los diferentes niveles de intensidad con unos simples clicks de rat\u00f3n (y cr\u00e9enos que sabemos de lo que hablamos). Tenemos dos consejos al respecto. Lo primero de esto es que es que pulses en \u201c<strong>Autom\u00e1tico<\/strong>\u201d y que el propio Photoshop se encargue de hacer el resto. En segundo lugar, que crees una capa extra para dejar una tal cual est\u00e1 y otra con la modificaci\u00f3n de color realizada. As\u00ed mismo, tambi\u00e9n puedes realizar pruebas y ver c\u00f3mo queda todo. Mientras no le des a \u201cOK\u201d, todo est\u00e1 permitido (como dir\u00edan en la famosa franquicia Assassin\u2019s Creed).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Utilizar los filtros disponibles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los filtros<\/strong>. \u00bfQui\u00e9n no conoce los filtros a estas alturas de la vida? Herramientas como Instagram o Facebook han popularizado los filtros para las fotograf\u00edas (as\u00ed como aplicaciones derivadas, v\u00e9ase Snapseed o VSCO Cam). Toman por defecto una configuraci\u00f3n y la aplican sobre la instant\u00e1nea en cuesti\u00f3n. Sin m\u00e1s secretos. No es que los filtros sean santo de nuestra devoci\u00f3n (y de nadie que est\u00e9 dentro del mundo audiovisual), pero es una opci\u00f3n m\u00e1s que v\u00e1lida para salvar algunas fotos y optar por ajustes muy r\u00e1pidos en poco tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Photoshop aparece en la parte superior como \u201c<strong>Filtros<\/strong>\u201d. Hay tantos que da para un post por s\u00ed solo. \u00a1Pru\u00e9balos!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Eliminar elementos de las fotos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfRecuerdas que antes te cont\u00e1bamos c\u00f3mo recortar una imagen para sacar aquellos elementos que no te gustan? Pues puede que se d\u00e9 el caso -de hecho, es bastante habitual- que el recorte no te vale, es decir, que necesitas el encuadre entero y no puedes prescindir de nada. Si este es tu caso, llega el momento de saber c<strong>\u00f3mo eliminar elementos de la fotograf\u00eda<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos por partes. Realizar esto conlleva un gran nivel de habilidad si se quiere hacer bien. No obstante, Photoshop sabe que es uno de los recursos m\u00e1s asiduos por parte de los usuarios, de ah\u00ed que en las \u00faltimas versiones ya introdujera un &#8220;truquito&#8221; para hacerlo todo m\u00e1s f\u00e1cil. La \u00fanica clave es saber d\u00f3nde se encuentra este.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello, lo primero que vamos a hacer es coger el <strong>lazo de la barra de herramientas<\/strong> (suele ser el tercer icono) y contornear la parte que queremos hacer desaparecer. Cuando lo hayamos marcado, la selecci\u00f3n aparecer\u00e1 resaltada con unas rayas, momento donde tenemos que ir a <strong>&#8220;Edici\u00f3n&#8221; -&gt; &#8220;Rellenar&#8221; -&gt; &#8220;Seg\u00fan el contenido&#8221;<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/photoshop_rellenar_dejuic.jpg\" alt=\"\" class=\"wp-image-205108\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Photoshop tomar\u00e1 aquellos elementos de la imagen que considera que se pueden sustituir en dicho punto. Avisamos de que <strong>la t\u00e9cnica puede fallar<\/strong> si la imagen contiene muchos puntos en los que hay que fijarse. Por tanto, nuestra recomendaci\u00f3n es que optes por este truco s\u00f3lo en esas instant\u00e1neas <strong>cuyo resultado obtenido es \u00f3ptimo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25cf<\/strong> <a href=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-cambiar-el-fondo-de-una-foto-con-photoshop\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-cambiar-el-fondo-de-una-foto-con-photoshop\">C\u00f3mo cambiar el fondo de una foto con Photoshop<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El tamp\u00f3n de clonar es tu amigo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si justo en el punto anterior te cont\u00e1bamos que la habilidad &#8220;Rellenar&#8221; es perfecta para los que no tienen muchas nociones de edici\u00f3n, para aquellos que ya est\u00e1 en un nivel intermedio, o quieren dar el paso hasta \u00e9l, lo mejor que se puede hacer es <strong>utilizar el tamp\u00f3n de clonar<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este vamos a clonar \u00e1reas que nosotros seleccionemos (el nombre ya desvela bastante, \u00bfno?). Por este motivo, el tamp\u00f3n es perfecto para hacer desaparecer elementos si tenemos una buena fotograf\u00eda o dibujo. Por ejemplo, en este de Dragon Ball con el que estamos haciendo la prueba, con el tamp\u00f3n de clonar hemos conseguido hacer desaparecer la hierba inferior derecha. S\u00f3lo hemos tenido que &#8220;clonar&#8221; partes de la tierra y ponerlas ah\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para clonar elementos basta con mantener pulsada la tecla &#8220;<strong>Alt<\/strong>&#8221; y luego hacer <strong>click izquierdo sobre el \u00e1rea a copiar<\/strong>. Una vez la tengas, suelta la tecla &#8220;Alt&#8221;, vete hasta otra parte de la imagen y dale de nuevo <strong>click izquierdo<\/strong>. Hay que tener en cuenta que <strong>debes ir clonando y &#8220;pegando&#8221; poco a poco<\/strong>, ya que \u00e9l \u00e1rea se mueve en consonancia (por tanto, si a la derecha del elemento seleccionado hay un pie, en cuanto pegues el trozo y muevas el rat\u00f3n a la derecha, el pie tambi\u00e9n aparecer\u00e1; al fin y al cabo, el rat\u00f3n clona a partir de esa \u00e1rea y todo lo que est\u00e1 alrededor de la misma).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/photoshop_tampon_de_clonar_s7ltbf.jpg\" alt=\"\" class=\"wp-image-205109\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Las m\u00e1scaras de clonar r\u00e1pidas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Te hemos ense\u00f1ado a c\u00f3mo rellenar una imagen, que es habilidad principiante; luego hemos pasado al tamp\u00f3n de clonar, que es una ranura media en el aprendizaje; y ahora vamos a pasar a las <strong>m\u00e1scaras de clonar<\/strong>, que las podr\u00edamos insertar en un nivel medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ocasiones necesitas clonar un \u00e1rea muy concreta para llevarla a otro lado. Por ejemplo, en este tutorial vamos a intentar clonar a trav\u00e9s de una m\u00e1scara el pelo de Goku. Para ello, selecciona la varita m\u00e1gica en la barra de herramientas y pulsa sobre el \u00e1rea que desees, en este caso, el pelo del personaje. Cuando lo tengas, dale arriba a &#8220;<strong>Seleccionar y aplicar m\u00e1scara<\/strong>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1040\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/05\/photoshop_mascara_de_clonar_1_hommrq.jpg\" alt=\"\" class=\"wp-image-205114\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, Photoshop te abrir\u00e1 una nueva pantalla con un sinf\u00edn de caracter\u00edsticas diferentes, como si queremos <strong>aplicar transparencia, redondeado, desvanecer la capa, a\u00f1adir contraste y mucho m\u00e1s<\/strong>. Aqu\u00ed depende todo de ti, ya que t\u00fa ser\u00e1s el encargado de ver si los valores que introduces te parecen aceptables. Cuando termines, dale a &#8220;OK&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya tienes hecho todo, por lo que podr\u00e1s mover esa parte en particular de la imagen simplemente arrastrando el rat\u00f3n. La idea es que <strong>la copies en otra capa para tener dos diferentes<\/strong> y ponerla donde quieras en la imagen. Aunque pueda resultar complicado todo esto que te estamos contando, en realidad se hace en unos segundos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ajustar los niveles de color<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Continuamos con nuestros particulares trucos con Photoshop para arreglar una imagen con los \u201cAjustes de color\u201d. El comando r\u00e1pido es \u201c<strong>Ctrl + B<\/strong>\u201d, pero para que sepas d\u00f3nde est\u00e1: \u201cImagen\u201d -&gt; \u201cAjustes\u201d -&gt; \u201c<strong>Equilibrio de color<\/strong>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2017\/12\/trucosphotoshop4.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfProblemas al ajustar el color de una fotograf\u00eda? Pues que al igual que con el histograma, si no sabes controlar los distintos canales de la fotograf\u00eda, <strong>lo m\u00e1s probable es que te la termines cargando<\/strong>. As\u00ed de simple. Puedes de nuevo realizar pruebas de color tocando las tres barras disponibles, ya que mientras no le des a \u201cOK\u201d, el trabajo no se salvar\u00e1 (as\u00ed puedes previsualizar c\u00f3mo va quedando la imagen en cuesti\u00f3n; o bien crear una capa para que no te cargues nada).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El HDR tambi\u00e9n existe<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seguro que has escuchado en m\u00e1s de una y de dos ocasiones el t\u00e9rmino <strong>HDR<\/strong>. Tras estas tres letras se esconde la palabra <strong>High Dymanic Range<\/strong>, que en espa\u00f1ol viene a ser algo as\u00ed como Im\u00e1genes de Alto Rango Din\u00e1mico. En el smartphone, este modo lo que hace es tirar un n\u00famero de fotograf\u00edas en diferentes exposiciones en s\u00f3lo un segundo, combinarlas de manera autom\u00e1tica y dar lugar a una sola definitiva con la mejor calidad posible. Mientras que el modo normal tira una sola fotograf\u00eda, el HDR es la combinaci\u00f3n de varias, por tanto, casi siempre se va a ver mejor (y ponemos el &#8220;casi&#8221;, ya que no es una regla directa).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Adobe Photoshop tambi\u00e9n contamos con un modo HDR para los usuarios. Este se encuentra en <strong>&#8220;Imagen&#8221; -&gt; &#8220;Ajustes&#8221; -&gt; &#8220;HDR&#8221;<\/strong>. A partir de aqu\u00ed, el software abre un desplegable con mucha informaci\u00f3n que puedes manejar a tu libre antojo. Eso s\u00ed, al igual que sucede con el color, vas a necesitar de unos conocimientos previos para que no salte por los aires la configuraci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/images\/v1589029452\/photoshop_hdr_mwyksu\/photoshop_hdr_mwyksu.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Meter el Lorem Ipsum<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos con un truco sencill\u00edsimo, pero que es perfecto si est\u00e1s aprendiendo el maravilloso mundo del dise\u00f1o (esto no va a servir tanto para fotograf\u00eda, lo sentimos). Como bien sabr\u00e1s si te est\u00e1s dedicando a este universo, el <strong>Lorem Ipsum es la madre de todos<\/strong>, ya que permite introducir un texto generado autom\u00e1ticamente para ver c\u00f3mo queda nuestra maquetaci\u00f3n. Si hasta la fecha te dedicas a copiarlo de una web y pegarlo en Photoshop, venimos a decirte que hay una manera sencill\u00edsima de ir m\u00e1s r\u00e1pido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando tengas creado el hueco de texto dentro de Adobe Photoshop, ve hasta la pesta\u00f1a de &#8220;<strong>Texto<\/strong>&#8221; y busca la casilla de &#8220;<strong>Pegar Lorem Ipsum<\/strong>&#8220;. Cuando le des ah\u00ed, el fant\u00e1stico texto se pegar\u00e1 de manera autom\u00e1tica. No hay m\u00e1s misterios. Vas a ahorrar un fant\u00e1stico tiempo, estamos seguros de ello.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/10\/photoshop-1024x576.jpg\" alt=\"\" class=\"wp-image-239981\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Desenfocar el fondo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Desenfocar el fondo es uno de los consejos m\u00e1s repetidos, sobre todo, cuando tiramos una foto con el tel\u00e9fono m\u00f3vil y queremos resaltar alguna parte en concreto de la imagen. Al fin y al cabo, es uno de esos trucos muy simples y sencillos de ejecutar, pero cuyo resultado es muy bueno y consigue su cometido de manera notable: que<strong> lo que quieres resaltar en escena aparezca como si estuviera en primer plano<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para realizar este procedimiento, pulsa en la palabra &#8220;Filtro&#8221; y luego ve hasta &#8220;Galer\u00eda de efectos desenfocar&#8221;. Justo aqu\u00ed, dale a &#8220;<strong>Desenfocar iris<\/strong>&#8221; y observa bien que en pantalla aparecer\u00e1 una especie de c\u00edrculo que puedes modificar para convertir en otras formas geom\u00e9tricas. La gracia est\u00e1 en que el centro siempre aparecer\u00e1 enfocado, mientras que los exteriores estar\u00e1n con un aspecto borroso. Tan s\u00f3lo debes jugar con estas l\u00edneas y elegir las transparencia que deseas en tu imagen. Es f\u00e1cil y m\u00e1s completo que con el smartphone, como puedes observar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/images\/v1589033875\/photoshop_desenfocar_iris_zfsqxj\/photoshop_desenfocar_iris_zfsqxj.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25cf<\/strong> <a href=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-difuminar-en-photoshop\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/como-difuminar-en-photoshop\">C\u00f3mo difuminar en Photoshop<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deformaci\u00f3n de perspectiva<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este truco de Adobe Photoshop es f\u00e1cil de encontrar, pero muy dif\u00edcil de ejecutar. Es necesario tener experiencia con el programa de edici\u00f3n de im\u00e1genes, ya que lo que vamos a hacer es <strong>modificar la perspectiva de la imagen<\/strong>, en concreto de una parte en concreto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para lograrlo, tan s\u00f3lo debemos dar en &#8220;<strong>Edici\u00f3n<\/strong>&#8221; y luego en &#8220;<strong>Deformaci\u00f3n de perspectiva<\/strong>&#8220;. A partir de aqu\u00ed, la imagen muestra una ret\u00edcula a la que podemos dar forma. Tienes que elegir una selecci\u00f3n exacta y luego cliquear en &#8220;Aceptar&#8221; (tecla Intro). Cuando hagas esto, la selecci\u00f3n en concreto podr\u00e1s moverla y cambiarle la forma. Es perfecto para realizar con edificios o fotograf\u00edas donde la sensaci\u00f3n de segundo plano puede tener m\u00e1s fortaleza y sentido.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2021\/10\/photoshop2-1024x576.jpg\" alt=\"\" class=\"wp-image-239983\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Arreglando las imperfecciones<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Oye, t\u00fa que te dedicas a esto, \u00bfpuedes hacer que parezca m\u00e1s joven en una fotograf\u00eda?&#8221;. A los que trabajamos con Photoshop, si nos dieran un euro por cada vez que hemos escuchado esto, ahora mismo tendr\u00edamos para comprarnos una isla en el Caribe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arreglar las imperfecciones y otros elementos de una instant\u00e1nea es algo de lo m\u00e1s habitual, de ah\u00ed que sea tambi\u00e9n una de las solicitudes m\u00e1s corrientes. Para poder &#8220;arreglar&#8221; una foto de este tipo se pueden usar muchas herramientas, pero la mejor que puedes utilizar en un primer momento es la de &#8220;<strong>Pincel corrector<\/strong>&#8220;. En la barra aparece con una forma de tirita aproximadamente, y lo que hace es parecido a lo del tamp\u00f3n de clonar, con la diferencia de que rellena el hueco con lo que esta cree conveniente respecto a colores y \u00e1reas (en el tamp\u00f3n lo eliges t\u00fa, no lo olvides).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/images\/v1589034395\/photoshop_pincel_corrector_p4jgfp\/photoshop_pincel_corrector_p4jgfp.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Lo b\u00e1sico para todos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Y hasta aqu\u00ed el tutorial con algunos trucos muy b\u00e1sicos para sacarle el m\u00e1ximo partido a <strong>Adobe Photoshop<\/strong>. Hemos intentado ir paso a paso, explicando todos los pormenores de cada t\u00e9cnica, ya sea a trav\u00e9s de los atajos r\u00e1pidos o mediante los desplegables en la parte superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como \u00faltimo consejo, recuerda que el retoque de im\u00e1genes no se aprende en cuesti\u00f3n de unas horas, d\u00edas o de forma r\u00e1pida, sino que es un proceso largo y duro de aprendizaje. Ten paciencia, practica mucho y no dudes en ning\u00fan momento a la hora de toquetear con el programa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25cf<\/strong> <a href=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/guia-basica-photoshop\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/adobe-photoshop.softonic.com\/articulos\/guia-basica-photoshop\">Gu\u00eda b\u00e1sica para empezar a usar Photoshop como un profesional<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25cf<\/strong> <a href=\"https:\/\/www.softonic.com\/articulos\/atajos-teclado-adobe-photoshop\" target=\"_blank\" rel=\"noreferrer noopener\">Los\u200c \u200catajos\u200c \u200cque\u200c \u200cdebes\u200c \u200cconocer\u200c \u200cde\u200c \u200cAdobe\u200c \u200cPhotoshop\u200c<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Has hecho una foto que tiene margen de mejora y no quieres mandarla a la \u201cPapelera de reciclaje\u201d. Tranquilo: no est\u00e1s solo. A todos nos ha pasado alguna vez que esa instant\u00e1nea que tanto quer\u00edas resulta que no vale, que no da el nivel adecuado, que est\u00e1 lejos de los est\u00e1ndares de calidad que a &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/es\/tutorial-adobe-photoshop-2\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;C\u00f3mo funciona Photoshop: trucos y tutoriales para principiantes&#8221;<\/span><\/a><\/p>\n","protected":false},"author":9091,"featured_media":240885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[9743,9706],"tags":[9681],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-224105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guides","category-how-to","tag-app-subdomain-redirectionadobe-photoshop"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/224105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/9091"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=224105"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/224105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/240885"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=224105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=224105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=224105"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=224105"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=224105"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=224105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}