{"id":22462,"date":"2012-06-11T11:20:06","date_gmt":"2012-06-11T09:20:06","guid":{"rendered":"http:\/\/onsoftware.softonic.com\/?p=22462"},"modified":"2025-06-13T06:09:25","modified_gmt":"2025-06-13T04:09:25","slug":"centro-aplicaciones-facebook","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/centro-aplicaciones-facebook\/","title":{"rendered":"El nuevo centro de aplicaciones de Facebook ya est\u00e1 aqu\u00ed"},"content":{"rendered":"<p><a href=\"http:\/\/onsoftware.softonic.com\/centro-aplicaciones-facebook\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22464\" title=\"Centro de aplicaciones de Facebook\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2012\/06\/centro-aplicaciones-fb1.png\" alt=\"Centro de aplicaciones de Facebook\" width=\"600\" height=\"218\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/centro-aplicaciones-fb1.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/centro-aplicaciones-fb1-256x93.png 256w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Facebook tiene miles de aplicaciones funcionando en su plataforma, pero encontrarlas hasta ahora era pr\u00e1cticamente imposible. Desde que hace unos meses el anterior apartado de juegos y aplicaciones desapareciera, no exist\u00eda ning\u00fan listado oficial de las mismas.<\/p>\n<p>Totalmente renovado, <strong>el <a href=\"https:\/\/www.facebook.com\/appcenter\">centro de aplicaciones<\/a> ha vuelto<\/strong>. Con\u00f3celo a fondo a continuaci\u00f3n.<!--more--><\/p>\n<h3>\u00bfAplicaciones? \u00bfpero eso que es?<\/h3>\n<p>La definici\u00f3n de la palabra aplicaci\u00f3n es cada d\u00eda m\u00e1s dif\u00edcil al utilizarse en muy distintos contextos: <a href=\"http:\/\/www.softonic.com\/\">aplicaciones para Windows<\/a>, <a href=\"http:\/\/www.softonic.com\/movil\"><em>apps<\/em> para el m\u00f3vil<\/a>, <a href=\"http:\/\/www.softonic.com\/aplicaciones-web\">aplicaciones web<\/a>, aplicaciones para otras aplicaciones web&#8230;<\/p>\n<p>En el caso de Facebook, no hay gran complicaci\u00f3n. Siempre y cuando necesite <strong>conectarse a Facebook<\/strong> para acceder a tu cuenta, se trata de una aplicaci\u00f3n. Por tanto, esto incluye <a href=\"http:\/\/onsoftware.softonic.com\/los-mejores-juegos-de-facebook\">juegos para Facebook<\/a> como <a href=\"http:\/\/farmville.softonic.com\/aplicaciones-web\">FarmVille<\/a>, aplicaciones para Windows como <a href=\"http:\/\/onsoftware.softonic.com\/facebook-messenger-para-windows-7\">Facebook Messenger<\/a> o cualquier p\u00e1gina web con la funci\u00f3n de Facebook Connect, \u00a1incluso Softonic!<\/p>\n<h3>P\u00e1gina principal: categor\u00edas y aplicaciones destacadas<\/h3>\n<p>Nada m\u00e1s entrar en el <a href=\"https:\/\/www.facebook.com\/appcenter\">Centro de aplicaciones<\/a>, lo primero que ves es un peque\u00f1o resumen con un poco de todo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22466\" title=\"Centro de aplicaciones - pantalla principal\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2012\/06\/Centro-de-aplicaciones-pantalla-principal.png\" alt=\"Centro de aplicaciones - pantalla principal\" width=\"600\" height=\"377\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Centro-de-aplicaciones-pantalla-principal.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Centro-de-aplicaciones-pantalla-principal-256x160.png 256w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>En la <strong>columna de la izquierda<\/strong>, justo debajo del nombre, se encuentra el principal filtro de aplicaciones: todas, aplicaciones web y aplicaciones para tel\u00e9fonos m\u00f3viles.<\/p>\n<p><strong>Web <\/strong>muestra aplicaciones que puedes <strong>disfrutar en tu navegador web<\/strong>. Incluye tanto juegos y aplicaciones que se ejecutan dentro de Facebook (<a href=\"https:\/\/www.facebook.com\/appcenter\/thesimssocial?fb_source=appcenter\">Sims Social<\/a>, <a href=\"https:\/\/www.facebook.com\/appcenter\/playcastleville?fb_source=appcenter\">CastleVille<\/a>&#8230;) como p\u00e1ginas web que se nutren de Facebook para su sistema de usuarios (<a href=\"https:\/\/www.facebook.com\/appcenter\/flixstertomatoes?fb_source=appcenter\">Rotten Tomatoes<\/a>, <a href=\"https:\/\/www.facebook.com\/appcenter\/flixster?fb_source=appcenter\">Flixster<\/a>&#8230;) Para empezar a usar la aplicaci\u00f3n, pulsa <strong>Jugar<\/strong> o <strong>Visitar <\/strong>el sitio web, seg\u00fan corresponda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22481\" title=\"Jugar\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2012\/06\/Jugar.png\" alt=\"Jugar\" width=\"600\" height=\"166\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Jugar.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Jugar-256x70.png 256w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>Celular<\/strong> muestra aplicaciones y juegos para tel\u00e9fonos m\u00f3viles que se conectan a Facebook. Es el caso de los conocidas <em>apps <\/em><a href=\"http:\/\/onsoftware.softonic.com\/trucos-para-apalabrados\">Apalabrados<\/a> y <a href=\"http:\/\/onsoftware.softonic.com\/que-es-pinterest\">Pinterest<\/a>. Al visitar apps para tel\u00e9fonos m\u00f3vil desde tu PC tienes la posibilidad de <strong>enviar el enlace directamente a tu tel\u00e9fono <\/strong>(siempre y cuando tenga la <em>app <\/em>de Facebook instalada)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22480\" title=\"DrawSmt\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2012\/06\/DrawSmt.png\" alt=\"DrawSmt\" width=\"600\" height=\"168\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/DrawSmt.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/DrawSmt-256x71.png 256w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Adem\u00e1s, tambi\u00e9n se incluyen las distintas <strong>categor\u00edas <\/strong>en las que se han clasificado las aplicaciones: juegos, entretenimiento, Facebook, estilo de vida, m\u00fasica, etc.\u00a0 Juegos, a su vez, se subdivide en los distintos g\u00e9neros (acci\u00f3n, deportes, etc.) tras hacer clic.<\/p>\n<h3>Listados de aplicaciones<\/h3>\n<p>Cada categor\u00eda muestra un listado con informaci\u00f3n sobre las aplicaciones y cuatro pesta\u00f1as que las ordenar\u00e1n de modo distinto:<\/p>\n<ul>\n<li><strong>Mejor calificadas<\/strong> muestra las aplicaciones m\u00e1s usadas con mejor nota<\/li>\n<li><strong>Recomendadas<\/strong> te recomienda aplicaciones a partir de las aplicaciones que ya usas<\/li>\n<li><strong>Tendencias <\/strong>muestra las aplicaciones que est\u00e1n creciendo r\u00e1pidamente en usuarios<\/li>\n<li><strong>Amigos <\/strong>incluye aplicaciones que tus amigos de Facebook han usado recientemente<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22482\" title=\"Listado\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2012\/06\/Listado1.png\" alt=\"Listado\" width=\"599\" height=\"511\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Listado1.png 599w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Listado1-256x218.png 256w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/p>\n<p>Un icono de un tel\u00e9fono m\u00f3vil sobre la imagen de la aplicaci\u00f3n marca las aplicaciones que s\u00f3lo est\u00e1n disponibles para tel\u00e9fono m\u00f3vil.<\/p>\n<h3>P\u00e1gina de la aplicaci\u00f3n<\/h3>\n<p>Esta p\u00e1gina incluye la informaci\u00f3n sobre la aplicaci\u00f3n, una corta descripci\u00f3n, su nota y algunas capturas de pantalla.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22483\" title=\"Diamond Dash\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2012\/06\/Diamond-Dash.png\" alt=\"Diamond Dash\" width=\"600\" height=\"456\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Diamond-Dash.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/2\/2012\/06\/Diamond-Dash-256x194.png 256w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>En el lateral derecho adem\u00e1s se incluyen enlaces interesantes que te permiten visitar la p\u00e1gina de la aplicaci\u00f3n, eliminarla o, por supuesto, empezar a usarla o enviar al tel\u00e9fono.<\/p>\n<h3>\u00bfEn qu\u00e9 puede mejorar el Centro de Aplicaciones de Facebook?<\/h3>\n<p>Al Centro de Aplicaciones le falta madurar un poco en algunas de sus funciones. Nosotros destacamos las siguientes:<\/p>\n<ul>\n<li><strong>No hay cuadro de b\u00fasqueda:<\/strong> Incre\u00edble pero cierto, no hay buscador.<\/li>\n<li><strong>Los listados son pesados de cargar y no tienen paginaci\u00f3n:<\/strong> El &#8220;<em>scroll infinito<\/em>&#8221; hace dif\u00edcil rebuscar m\u00e1s en los resultados y evitar las recomendaciones &#8220;de siempre&#8221;.<\/li>\n<li><strong>No tiene opiniones de usuarios:<\/strong> Desde que las <em>reviews <\/em>-con texto- de los usuarios desaparecieran hace unos meses, no se han vuelto a ver. \u00bfVolver\u00e1n alg\u00fan d\u00eda?<\/li>\n<li><strong>Enviar al tel\u00e9fono no distingue qu\u00e9 tel\u00e9fono tienes: <\/strong>As\u00ed, puedes enviar a tu tel\u00e9fono Android una <em>app <\/em>s\u00f3lo para iPhone. \u00bfEl resultado? &#8220;Programa no encontrado&#8221; en <a href=\"http:\/\/onsoftware.softonic.com\/google-play-reemplaza-a-android-market\">Google Play<\/a>.<\/li>\n<li><strong>Categor\u00edas confusas:<\/strong> Herramientas de software incluye contenido tan dispar como <a href=\"http:\/\/badoo.softonic.com\/aplicaciones-web\">Badoo<\/a>, <a href=\"http:\/\/bing.softonic.com\/aplicaciones-web\">Bing<\/a> o <a href=\"http:\/\/quora.softonic.com\/aplicaciones-web\">Quora<\/a>&#8230;<\/li>\n<li><strong>La traducci\u00f3n al espa\u00f1ol es incompleta:<\/strong> Varios apartados no se han traducido todav\u00eda, mostr\u00e1ndose en ingl\u00e9s.<\/li>\n<\/ul>\n<h3>\u00bfHas probado Facebook App Center? \u00bfQu\u00e9 te parece?<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Facebook tiene miles de aplicaciones funcionando en su plataforma, pero encontrarlas hasta ahora era pr\u00e1cticamente imposible. Desde que hace unos meses el anterior apartado de juegos y aplicaciones desapareciera, no exist\u00eda ning\u00fan listado oficial de las mismas. Totalmente renovado, el centro de aplicaciones ha vuelto. Con\u00f3celo a fondo a continuaci\u00f3n.<\/p>\n","protected":false},"author":1008,"featured_media":22464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[],"tags":[9686],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-22462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-app-subdomain-redirectionfacebook"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/22462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/1008"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=22462"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/22462\/revisions"}],"predecessor-version":[{"id":384880,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/22462\/revisions\/384880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/22464"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=22462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=22462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=22462"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=22462"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=22462"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=22462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}