{"id":280156,"date":"2023-03-30T18:07:41","date_gmt":"2023-03-30T16:07:41","guid":{"rendered":"http:\/\/sftarticles.wpenginepowered.com\/es\/?p=280156"},"modified":"2025-06-12T20:37:44","modified_gmt":"2025-06-12T18:37:44","slug":"fortnite-recompensas-evento-primavera-2023","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/fortnite-recompensas-evento-primavera-2023\/","title":{"rendered":"Fortnite: recompensas evento primavera 2023"},"content":{"rendered":"\n<p>Tenemos m\u00e1s novedades con <strong><a href=\"https:\/\/fortnite.softonic.com\/?ex=CS-987.2\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"Fortnite\">Fortnite<\/a><\/strong> despu\u00e9s de su \u00faltima actualizaci\u00f3n (versi\u00f3n 24.10). El videojuego de <strong>Epic Games<\/strong> ya tiene disponibles las recompensas del <strong>evento de primavera 2023<\/strong>, que recibe por nombre <strong>Fuga Primaveral<\/strong>. Esta acci\u00f3n durar\u00e1 unas dos semanas (hasta el 11 de abril, para ser exactos) y nos volver\u00e1 a ofrecer jugosos regalos.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/0725c9ce-2e53-43a3-b740-39e0f5c20693\/2385420064\/fortnite-unnamed.png\" alt=\"Fortnite\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Fortnite<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/fortnite.softonic.com\/?ex=CS-987.2\" target=\"_self\" rel=\"noopener noreferrer\">DESCARGAR<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\">Battle royale gratuito en constante evoluci\u00f3n<\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/fortnite.softonic.com\/?ex=CS-987.2\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p>Cada d\u00eda se a\u00f1adir\u00e1 <strong>una nueva misi\u00f3n<\/strong> a partir de las <strong>15:00 horas<\/strong> de Espa\u00f1a. Conforme vayamos cumpliendo estas misiones a diario, el juego nos dar\u00e1 PE y algunos obsequios, ya que habr\u00e1 d\u00edas concretos donde tambi\u00e9n obtendremos premios. El listado es el siguiente:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Recompensa de misi\u00f3n d\u00eda 1<\/strong>: el accesorio mochilero Portaprimaveras.<\/li><li><strong>Recompensa de misi\u00f3n d\u00eda 7<\/strong>: grafiti Rompec\u00e1scaras.<\/li><li><strong>Recompensa de misi\u00f3n d\u00eda 9<\/strong>: pantalla de carga Collage de salchichas.<\/li><li><strong>Recompensa de misi\u00f3n d\u00eda 12<\/strong>: icono de estandarte Fuga primaveral.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/2\/2023\/03\/fortnite-fuga-primaveral-1-1024x576.jpg\" alt=\"\" class=\"wp-image-280165\" \/><\/figure>\n\n\n\n<p>Estos son los premios que se logran s\u00f3lo en d\u00edas determinados. Ahora bien, por completar <strong>12 misiones<\/strong> de Fuga Primaveral recibiremos el <strong>pico Eclosionador primaveral<\/strong>, mientras que si hacemos un total de<strong> 22 misiones<\/strong> obtendremos el <strong>ala delta Planeador primaveral<\/strong>.<\/p>\n\n\n\n<p>Por otro lado, mientras dure el evento de primavera habr\u00e1 <strong>dos nuevos tipos de pollos y tres nuevos tipos de huevos en la isla<\/strong>. Las gallinas verdes y moradas ponen huevos especiales que nos dar\u00e1n beneficios al interactuar con ellos. Son los siguientes:\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Huevos curativos<\/strong>: estos huevos verdes permiten recuperar salud y obtener escudo de forma progresiva.<\/li><li><strong>Huevos de salto<\/strong>: estos huevos azules permiten recuperar salud y otorgan un efecto de gravedad cero.<\/li><li><strong>Huevos dorados<\/strong>: t\u00e9cnicamente no se pueden consumir, pero si interactuamos con ellos nos dar\u00e1n barras (a diferencia de los huevos curativos y de los huevos de salto, no pod\u00e9is a\u00f1adir los huevos dorados a vuestro inventario).<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"COMO CONSEGUIR GRATIS TODAS LAS RECOMPENSAS DE FUGA PRIMAVERAL EN FORTNITE - MISIONES O DESAFIOS\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/72IV61MF91k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Para finalizar, el\u00a0<strong>lanzahuevos<\/strong>\u00a0estar\u00e1 disponible para recoger por el suelo, en cofres y en entregas de suministros (tambi\u00e9n es probable que los venda alg\u00fan personaje). Podremos conseguir uno utilizando el nuevo\u00a0<strong>aumento de realidad Eclosi\u00f3n primaveral<\/strong>.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/0725c9ce-2e53-43a3-b740-39e0f5c20693\/2385420064\/fortnite-unnamed.png\" alt=\"Fortnite\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Fortnite<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/fortnite.softonic.com\/?ex=CS-987.2\" target=\"_self\" rel=\"noopener noreferrer\">DESCARGAR<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\">Battle royale gratuito en constante evoluci\u00f3n<\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/fortnite.softonic.com\/?ex=CS-987.2\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p><em><em><em><em>Algunos de los enlaces a\u00f1adidos en el art\u00edculo forman parte de campa\u00f1as de afiliaci\u00f3n y pueden representar beneficios para Softonic.<\/em><\/em><\/em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las misiones estar\u00e1n disponibles hasta el pr\u00f3ximo 11 de abril.<\/p>\n","protected":false},"author":9091,"featured_media":280163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[9320,9317],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-280156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/280156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/9091"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=280156"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/280156\/revisions"}],"predecessor-version":[{"id":365345,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/280156\/revisions\/365345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/280163"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=280156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=280156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=280156"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=280156"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=280156"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=280156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}