{"id":305674,"date":"2023-09-07T11:37:48","date_gmt":"2023-09-07T09:37:48","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=305674"},"modified":"2025-06-12T19:09:13","modified_gmt":"2025-06-12T17:09:13","slug":"modem-apple-2025-rumores-kuo","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/modem-apple-2025-rumores-kuo\/","title":{"rendered":"Llevamos a\u00f1os esperando el m\u00f3dem 5G de Apple: nuevos rumores le ponen fecha (parece que definitiva)"},"content":{"rendered":"\n<p>Desde hace tiempo, Apple ha estado en el centro de los <strong>rumores acerca de su propio m\u00f3dem 5G para los iPhone<\/strong>. La compra de la divisi\u00f3n de m\u00f3dems de Intel por parte de Apple y con el posterior enfrentamiento legal con el actual proveedor, Qualcomm, por citar solo dos ejemplos, han sido elementos de la historia del desarrollo de estos cruciales componentes. Una en la que cada vez los rumores posponen m\u00e1s y m\u00e1s una fecha de llegada que parece que no alcanzamos.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-m\/p\/aa0ea39a-3047-47be-9b3a-938ac771524a\/234379927\/ios-17-download-ios-17.jpg\" alt=\"iOS 17\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">iOS 17<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/ios-17.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\">Descargar<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/ios-17.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Sin m\u00e1s retrasos, esperemos<\/h2>\n\n\n\n<p>Ahora, <a href=\"https:\/\/medium.com\/@mingchikuo\/qualcomm-is-the-main-loser-from-huaweis-adoption-of-kirin9000s-and-new-kirin-chips-e96080908f5c\">informaciones publicadas<\/a> por el conocido analista de la cadena de suministro Ming-Chi Kuo, <strong>sugieren que podr\u00edamos ver este cambio en 2025<\/strong>. Kuo previamente hab\u00eda se\u00f1alado que el iPhone SE de cuarta generaci\u00f3n, planteado para 2024, ser\u00eda el primer dispositivo en incorporar el m\u00f3dem 5G dise\u00f1ado por Apple. Sin embargo, ante la <a href=\"https:\/\/www.softonic.com\/articulos\/iphone-se-4-rumores\">dilaci\u00f3n en la producci\u00f3n de dicho modelo<\/a> hasta 2025, esta afirmaci\u00f3n se ha vuelto incierta. Los rumores son conflictivos, y aunque la expectativa sigue viva, la realidad del lanzamiento del dispositivo y la inclusi\u00f3n del m\u00f3dem en cuesti\u00f3n sigue siendo estando poco clara.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Privacy | App Tracking Transparency | Apple\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/Ihw_Al4RNno?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La estrategia de Apple no es nueva, eso s\u00ed. <strong>La compa\u00f1\u00eda lleva m\u00e1s de cinco a\u00f1os planificando la creaci\u00f3n de su propio m\u00f3dem<\/strong> y, en un movimiento estrat\u00e9gico, en 2019 adquiri\u00f3 la mayor\u00eda del negocio de m\u00f3dems para smartphones de Intel. Esta adquisici\u00f3n dej\u00f3 entrever la seriedad de la intenci\u00f3n de Apple de alejarse de proveedores externos para esta pieza tecnol\u00f3gica clave. Algo que ya ha hecho en muchos otros componentes como los chips, sin ir m\u00e1s lejos.<\/p>\n\n\n\n<p>De mantenerse las predicciones basadas en el marco temporal de 2025, los modelos <a href=\"https:\/\/www.softonic.com\/articulos\/iphone-15\">iPhone 15<\/a> y iPhone 16 deber\u00edan seguir con m\u00f3dems suministrados por Qualcomm. El cambio deber\u00eda darse para modelos futuros, como el iPhone SE y el iPhone 17, siempre que se superen los desaf\u00edos de desarrollo y se cumpla el calendario.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-m\/p\/aa0ea39a-3047-47be-9b3a-938ac771524a\/234379927\/ios-17-download-ios-17.jpg\" alt=\"iOS 17\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">iOS 17<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/ios-17.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\">Descargar<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/ios-17.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p>Pero, \u00bfqu\u00e9 significa esto para el consumidor final? Aunque todav\u00eda no est\u00e1 claro qu\u00e9 beneficios ofrecer\u00e1 un m\u00f3dem 5G dise\u00f1ado por Apple sobre los m\u00f3dems de Qualcomm, lo que es evidente es la estrategia de Apple de reducir su dependencia de otros proveedores. La llegada del m\u00f3dem 5G de Apple levanta expectaci\u00f3n no solo por la innovaci\u00f3n que pueda representar, sino tambi\u00e9n por lo que simboliza en t\u00e9rminos de independencia tecnol\u00f3gica para la compa\u00f1\u00eda. A medida que se acerca 2025, <strong>estaremos atentos a c\u00f3mo se desvelan estos rumores<\/strong> y cu\u00e1l ser\u00e1 el pr\u00f3ximo paso en la evoluci\u00f3n tecnol\u00f3gica de Apple.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que se acerca 2025, estaremos atentos a c\u00f3mo se desvelan estos rumores y cu\u00e1l ser\u00e1 el pr\u00f3ximo paso en la evoluci\u00f3n tecnol\u00f3gica de Apple.<\/p>\n","protected":false},"author":9262,"featured_media":305679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":3},"categories":[9317],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-305674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/305674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/9262"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=305674"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/305674\/revisions"}],"predecessor-version":[{"id":361783,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/305674\/revisions\/361783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/305679"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=305674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=305674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=305674"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=305674"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=305674"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=305674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}