{"id":310868,"date":"2023-10-18T20:11:57","date_gmt":"2023-10-18T18:11:57","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=310868"},"modified":"2025-06-12T18:47:00","modified_gmt":"2025-06-12T16:47:00","slug":"google-chrome-te-empezara-a-corregir-erratas-en-android-e-ios","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/google-chrome-te-empezara-a-corregir-erratas-en-android-e-ios\/","title":{"rendered":"Google Chrome te empezar\u00e1 a corregir erratas en Android e iOS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Google Chrome, <strong>el navegador m\u00e1s utilizado en la actualidad<\/strong>, sigue dando pasos en materia de ayudas y accesibilidad a los usuarios. Es por eso que, si ves que tu m\u00f3vil Android o iOS comienza a <strong>realizarte correcciones mientras usas el navegador<\/strong>, es porque Google ha comenzado a activar las <strong>recomendaciones de palabras<\/strong> si, por alg\u00fan motivo, te has equivocado escribiendo tu b\u00fasqueda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Google, una de las compa\u00f1\u00edas m\u00e1s poderosas de la actualidad<\/strong>, sigue dedicando mucho de su tiempo y recursos a avanzar a nivel social. Muchas veces, <strong>las discapacidades tambi\u00e9n suponen una barrera digital<\/strong>, y el objetivo actual de Google es el de <strong>derribar estos obst\u00e1culos que las personas puedan encontrar<\/strong> utilizando sus servicios.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/f875d630-96d4-11e6-b152-00163ed833e7\/2845731368\/chrome-logo\" alt=\"Google Chrome\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Google Chrome<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-sponsored\" href=\"https:\/\/chrome.softonic.com\/android\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Descargar<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-sponsored\" href=\"https:\/\/chrome.softonic.com\/android\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Google y sus recomendaciones de correcciones<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tal y como explica <a href=\"https:\/\/blog.google\/outreach-initiatives\/accessibility\/making-daily-tasks-accessible\/\" title=\"\">Google en su blog de manera oficial<\/a>, <strong>la accesibilidad se ha convertido en una de las metas prioritarias<\/strong> de la compa\u00f1\u00eda. Es por ello que, ahora, estas recomendaciones, que ya exist\u00edan en la versi\u00f3n de navegador web de Google Chrome, tambi\u00e9n <strong>estar\u00e1n operativas en los tel\u00e9fonos m\u00f3viles<\/strong>, un dispositivo con mayor uso por parte de los usuarios en todo el mundo. Se trata de una ayuda \u00fatil para el usuario de a pie, pero resulta <strong>todav\u00eda m\u00e1s valioso para los usuarios discapacitados<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y no solo eso, <strong>Google ha sacado a la luz<\/strong> toda <a href=\"https:\/\/www.softonic.com\/articulos\/estas-nuevas-funciones-de-google-permitiran-que-muchas-mas-personas-usen-sus-apps\" title=\"\">una serie de mejoras en materia de accesibilidad<\/a> que ofrecer\u00e1n <strong>ayudas de todo tipo a los usuarios<\/strong>. Adem\u00e1s, Google ha mostrado <a href=\"https:\/\/www.youtube.com\/watch?v=S61kr6CvsD8\" title=\"\">este llamativo comercial<\/a> para remarcar su inter\u00e9s en mejorar la <strong>accesibilidad para los usuarios con m\u00e1s dificultades<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Magnifier on Google Pixel\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/S61kr6CvsD8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La resaca post estreno de los nuevos Pixel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque estos avances tienen un gran valor porque la accesibilidad deber\u00eda ser un reto para todas las compa\u00f1\u00edas tecnol\u00f3gicas de la actualidad, el momento m\u00e1s esperado de Google en este mes de octubre fue el de la presentaci\u00f3n de su nueva l\u00ednea de smartphones. Los nuevos Pixel 8, que <a href=\"https:\/\/www.softonic.com\/articulos\/que-novedades-trae-el-pixel-8-todo-sobre-el-nuevo-smartphone-de-google\" title=\"\">se mostraron a todos los p\u00fablicos el pasado 4 de octubre<\/a>, se mostraron como un dispositivo lleno de ayudas y asistencia <strong>por parte de su software y su Inteligencia Artificial<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viendo <strong>el camino de la compa\u00f1\u00eda<\/strong>, queda muy claro que, ya sea a trav\u00e9s del software de sus dispositivos m\u00f3viles, o con los servicios que brinda a trav\u00e9s de su navegador y otras herramientas, <strong>Google busca seguir facilitando la vida de las personas<\/strong> que usan habitualmente sus aplicaciones o dispositivos. \u00bfCu\u00e1les ser\u00e1n las siguientes novedades que lleguen en cuanto a calidad de vida o accesibilidad? <strong>Google proveer\u00e1<\/strong>.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/f875d630-96d4-11e6-b152-00163ed833e7\/2845731368\/chrome-logo\" alt=\"Google Chrome\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Google Chrome<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-sponsored\" href=\"https:\/\/chrome.softonic.com\/android\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Descargar<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-sponsored\" href=\"https:\/\/chrome.softonic.com\/android\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><\/a>\r\n  <\/div>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Google Chrome, el navegador m\u00e1s utilizado en la actualidad, sigue dando pasos en materia de ayudas y accesibilidad a los usuarios. Es por eso que, si ves que tu m\u00f3vil Android o iOS comienza a realizarte correcciones mientras usas el navegador, es porque Google ha comenzado a activar las recomendaciones de palabras si, por alg\u00fan &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/es\/google-chrome-te-empezara-a-corregir-erratas-en-android-e-ios\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Google Chrome te empezar\u00e1 a corregir erratas en Android e iOS&#8221;<\/span><\/a><\/p>\n","protected":false},"author":9285,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[9317],"tags":[9352],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-310868","post","type-post","status-publish","format-standard","hentry","category-news","tag-google-chrome"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/310868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/9285"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=310868"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/310868\/revisions"}],"predecessor-version":[{"id":360790,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/310868\/revisions\/360790"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=310868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=310868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=310868"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=310868"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=310868"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=310868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}