{"id":335476,"date":"2024-07-05T09:14:46","date_gmt":"2024-07-05T07:14:46","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=335476"},"modified":"2025-06-12T16:45:22","modified_gmt":"2025-06-12T14:45:22","slug":"instalador-macos-sequoia","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/instalador-macos-sequoia\/","title":{"rendered":"C\u00f3mo crear un instalador de macOS Sequoia para hacer una instalaci\u00f3n desde cero"},"content":{"rendered":"\n<p>Crear un instalador USB de <a href=\"https:\/\/softonic.com\/articulos\/apple-anuncia-macos-sequoia-estas-son-algunas-de-sus-funciones-mas-interesantes\/\">macOS Sequoia<\/a> es un recurso muy \u00fatil si necesitamos instalar el sistema operativo en m\u00faltiples ordenadores o sin depender de una conexi\u00f3n a internet. Este m\u00e9todo es especialmente \u00fatil, adem\u00e1s, para <strong>hacer una instalaci\u00f3n limpia del nuevo sistema operativo de Apple<\/strong>. Veamos, en solo cuatro pasos, c\u00f3mo crear un instalador de macOS Sequoia.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-m\/p\/4f8a82c0-9e07-4a98-b270-d71d12abace2\/707471428\/ios-18-download-ios18.jpg\" alt=\"iOS 18\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">iOS 18<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/ios-18.en.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\">Descargar<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/ios-18.en.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Paso 1: Seleccionar el dispositivo USB adecuado<\/h2>\n\n\n\n<p>Para comenzar, <strong>necesitamos una unidad flash USB con al menos 16 GB de capacidad<\/strong>, aunque se recomienda usar una de 32 GB para asegurar espacio suficiente. Es importante que la unidad est\u00e9 vac\u00eda o que no contenga datos que necesitemos, ya que el proceso borrar\u00e1 todo su contenido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Paso 2: Descargar el instalador de macOS Sequoia<\/h2>\n\n\n\n<p>El <strong>instalador de macOS puede obtenerse directamente desde la app Terminal<\/strong> del Mac. Abrimos la app busc\u00e1ndonoslas &#8220;Terminal&#8221; en Spotlight y pegamos el siguiente comando:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>softwareupdate --list-full-installers<\/code><\/pre>\n\n\n\n<p>Luego <strong>buscamos el instalador de macOS Sequoia m\u00e1s reciente<\/strong> y lo descargamos utilizando el siguiente comando, reemplazando <code>15.0<\/code> por la versi\u00f3n m\u00e1s reciente si es necesario:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>softwareupdate --fetch-full-installer --full-installer-version 15.0<\/code><\/pre>\n\n\n\n<p>Este paso descargar\u00e1 el instalador en nuestra carpeta de Aplicaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Paso 3: Preparar la unidad USB<\/h2>\n\n\n\n<p><strong>Conectamos el USB y abrimos la app Utilidad de Discos<\/strong>, ubicada en <em>Aplicaciones<\/em> &gt; <em>Utilidades<\/em> &gt; <em>Utilidad de Discos<\/em>. Una vez ah\u00ed, seleccionamos la unidad en la barra lateral izquierda y tocamos en Borrar. Elegimos el formato APFS o Mac OS Extendido (Journaled) y confirmamos la operaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Paso 4: Crear el instalador en la unidad USB<\/h2>\n\n\n\n<p>Abrimos la app <em>Finder<\/em> entramos en la carpeta <em>Aplicaciones<\/em> y buscamos el instalador que acabamos de descargar. Hacemos un clic secundario sobre &#8220;Instalar macOS 15 beta&#8221; y elegimos <em>Mostrar contenido del paquete<\/em>. Luego entramos en la carpeta Contents y posteriormente en Resources.<\/p>\n\n\n\n<p>En una ventana de terminal, escribimos <code>sudo<\/code> y arrastramos el archivo <code>createinstallmedia<\/code> al terminal. Luego, escribimos <code>--volume<\/code> seguido de un espacio.<\/p>\n\n\n\n<p>Arrastramos la unidad USB desde Finder a la ventana del terminal para completar el comando, que <strong>deber\u00eda quedar similar a este<\/strong>:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>sudo \/Applications\/Install\\ macOS\\ 15\\ beta.app\/Contents\/Resources\/createinstallmedia --volume \/Volumes\/NOMBRE_DE_TU_USB<\/code><\/pre>\n\n\n\n<p>Presionamos Enter (\u21b5), introducimos la contrase\u00f1a de administrador cuando se nos solicite, confirmamos presionando la <code>y<\/code> y presionamos Enter (\u21b5) nuevamente para iniciar el proceso.<\/p>\n\n\n\n<p>Una vez que el terminal indique que el proceso ha finalizado, <strong>nuestra unidad USB con el instalador de macOS Sequoia estar\u00e1 lista<\/strong>.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-m\/p\/4f8a82c0-9e07-4a98-b270-d71d12abace2\/707471428\/ios-18-download-ios18.jpg\" alt=\"iOS 18\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">iOS 18<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/ios-18.en.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\">Descargar<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        <svg class=\"rating-score__content\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" x=\"0\" y=\"0\" viewbox=\"0 0 50 50\" enable-background=\"new 0 0 50 50\" xml:space=\"preserve\"><path class=\"rating-score__background rating-score--good\" fill=\"none\" stroke-width=\"6\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><path class=\"rating-score__value rating-score__value--0\" fill=\"none\" stroke-width=\"6\" stroke-dashoffset=\"0\" stroke-miterlimit=\"10\" d=\"M40 40c8.3-8.3 8.3-21.7 0-30s-21.7-8.3-30 0 -8.3 21.7 0 30\"><\/path><text class=\"rating-score__number\" content=\"\" text-anchor=\"middle\" transform=\"matrix(1 0 0 1 25 31.0837)\" data-auto=\"app-user-score\"><\/text><\/svg>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\" onerror=\"this.style.display='none'\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/ios-18.en.softonic.com\/iphone\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p>Con esto podremos <strong>realizar m\u00faltiples instalaciones sin necesidad de descargas repetidas<\/strong>, ideal para entornos con internet limitado o para asegurar una instalaci\u00f3n limpia y eficiente del sistema operativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crear un instalador USB de macOS Sequoia es un recurso muy \u00fatil si necesitamos instalar el sistema operativo en m\u00faltiples ordenadores o sin depender de una conexi\u00f3n a internet. Este m\u00e9todo es especialmente \u00fatil, adem\u00e1s, para hacer una instalaci\u00f3n limpia del nuevo sistema operativo de Apple. Veamos, en solo cuatro pasos, c\u00f3mo crear un instalador &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/es\/instalador-macos-sequoia\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;C\u00f3mo crear un instalador de macOS Sequoia para hacer una instalaci\u00f3n desde cero&#8221;<\/span><\/a><\/p>\n","protected":false},"author":9262,"featured_media":335477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[9317],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-335476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/335476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/9262"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=335476"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/335476\/revisions"}],"predecessor-version":[{"id":359089,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/335476\/revisions\/359089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/335477"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=335476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=335476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=335476"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=335476"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=335476"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=335476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}