{"id":422411,"date":"2026-07-15T08:03:36","date_gmt":"2026-07-15T06:03:36","guid":{"rendered":"https:\/\/cms-articles.softonic.io\/es\/?p=422411"},"modified":"2026-07-15T08:03:39","modified_gmt":"2026-07-15T06:03:39","slug":"hardware-openai-filtracion","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/es\/hardware-openai-filtracion\/","title":{"rendered":"No es un m\u00f3vil ni un reloj: sabemos qu\u00e9 ser\u00e1 el primer gadget de OpenAI"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde mayo de 2025, sabemos que OpenAI est\u00e1 a punto de dar su primer paso en el mundo del hardware, pero desconocemos, por lo menos hasta ahora, cu\u00e1l es el tipo de dispositivo con el que lo har\u00e1. A este respecto, Bloomberg&nbsp;<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2026-07-14\/openai-s-first-device-will-be-moveable-screenless-speaker-built-as-ai-companion\">afirma<\/a>&nbsp;que la compa\u00f1\u00eda prepara&nbsp;<strong>un dispositivo que combina altavoz port\u00e1til, c\u00e1mara y sensores<\/strong>. Un enfoque que se aparta de los m\u00f3viles y relojes inteligentes, que ya se descartaron en su d\u00eda, para centrarse de lleno en la inteligencia artificial desde un formato poco habitual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un dispositivo port\u00e1til con c\u00e1mara y sensores<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque sabemos poco, Bloomberg nos habla de un dispositivo&nbsp;<strong>compacto, f\u00e1cil de transportar y equipado con una c\u00e1mara y varios sensores<\/strong>. Gracias a esta combinaci\u00f3n, OpenAI busca superar a la interacci\u00f3n que tenemos hoy en d\u00eda con los altavoces inteligentes actuales. La c\u00e1mara permitir\u00e1 entender el contexto visual, como nuestra ubicaci\u00f3n o los objetos que tenemos delante, mientras que los sensores \u2014todav\u00eda habr\u00e1 que ver cu\u00e1les\u2014 deber\u00edan captar informaci\u00f3n extra para ofrecer respuestas m\u00e1s \u00fatiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La idea es ir m\u00e1s all\u00e1 de los altavoces fijos manteniendo, hasta cierto punto, el mismo tipo de interacci\u00f3n. Por supuesto, quedan muchos detalles por resolver, por ejemplo si ser\u00e1 posible usar el dispositivo con auriculares, pues no siempre queremos que las personas de nuestro entorno escuchen las respuestas de ChatGPT.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En todo caso, siempre seg\u00fan las filtraciones, OpenAI se ha decidido por un dispositivo cuyo punto de inter\u00e9s ser\u00e1 la interacci\u00f3n continua. Una interacci\u00f3n&nbsp;<a href=\"https:\/\/www.softonic.com\/articulos\/nuevo-chat-voz-chatgpt\">muy natural a trav\u00e9s de la voz<\/a>&nbsp;que buscar\u00eda minimizar la necesidad de consultar nuestro tel\u00e9fono. El tiempo dir\u00e1 si a\u00f1adir un dispositivo m\u00e1s a nuestra colecci\u00f3n es la mejor estrategia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde mayo de 2025, sabemos que OpenAI est\u00e1 a punto de dar su primer paso en el mundo del hardware, pero desconocemos, por lo menos hasta ahora, cu\u00e1l es el tipo de dispositivo con el que lo har\u00e1. A este respecto, Bloomberg&nbsp;afirma&nbsp;que la compa\u00f1\u00eda prepara&nbsp;un dispositivo que combina altavoz port\u00e1til, c\u00e1mara y sensores. Un enfoque &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/es\/hardware-openai-filtracion\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;No es un m\u00f3vil ni un reloj: sabemos qu\u00e9 ser\u00e1 el primer gadget de OpenAI&#8221;<\/span><\/a><\/p>\n","protected":false},"author":9262,"featured_media":422412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[9317],"tags":[],"usertag":[],"vertical":[],"content-category":[14053],"class_list":["post-422411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","content-category-ia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/422411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/users\/9262"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/comments?post=422411"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/422411\/revisions"}],"predecessor-version":[{"id":422413,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/posts\/422411\/revisions\/422413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media\/422412"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/media?parent=422411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/categories?post=422411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/tags?post=422411"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/usertag?post=422411"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/vertical?post=422411"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/es\/wp-json\/wp\/v2\/content-category?post=422411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}