{"id":102392,"date":"2014-09-17T17:11:33","date_gmt":"2014-09-17T15:11:33","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=102392"},"modified":"2025-06-12T11:39:39","modified_gmt":"2025-06-12T10:39:39","slug":"changer-icones-android","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/changer-icones-android\/","title":{"rendered":"Comment changer les ic\u00f4nes sur Android"},"content":{"rendered":"<p>Il est tr\u00e8s facile de changer les ic\u00f4nes de ses applications Android en passant par un lanceur alternatif. Je vous explique comment <strong>personnaliser <\/strong>votre smartphone avec le lanceur Nova Launcher.<\/p>\n<p>J&#8217;adore Android pour la <strong>libert\u00e9<\/strong> qu&#8217;il offre \u00e0 ses utilisateurs. En installant <a title=\" 5 applis Android qui me rendent plus efficace au bureau 5 applis Android qui me rendent plus efficace au bureau\" href=\"http:\/\/articles.softonic.fr\/astuces-apps-productivite-android?ab=1\" target=\"_self\" rel=\"noopener noreferrer\">quelques applications<\/a>, j&#8217;ai pu personnaliser mon smartphone et l&#8217;adapter \u00e0 mes pr\u00e9f\u00e9rences. Aujourd&#8217;hui je vous explique comment changer les <strong>ic\u00f4nes <\/strong>de vos applications en utilisant l&#8217;excellent Nova Launcher.<\/p>\n<h3>Installer Nova Launcher<\/h3>\n<p><strong>1.<\/strong> T\u00e9l\u00e9chargez et installez Nova Launcher. Pour en savoir plus sur le t\u00e9l\u00e9chargement et l&#8217;installation des applications Android, consultez <a title=\"T\u00e9l\u00e9charger des applications Android\" href=\"https:\/\/support.google.com\/googleplay\/answer\/113409?hl=fr\" target=\"_blank\" rel=\"noopener noreferrer\">la page d&#8217;aide de Google<\/a>.<\/p>\n<p><strong>T\u00e9l\u00e9charger <\/strong><a title=\"Nova Launcher\" href=\"http:\/\/nova-launcher.softonic.fr\/android\" target=\"_self\" rel=\"noopener noreferrer\">Nova Launcher <\/a><\/p>\n<p><strong>2. <\/strong>Lancez Nova Launcher. L&#8217;application va se lancer \u00e0 la place du lanceur par d\u00e9faut de votre smartphone.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-102508 aligncenter\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/14-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/14.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/14-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/14-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/14-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><strong>3.<\/strong> Pour choisir Nova Launcher comme nouveau lanceur par d\u00e9faut, appuyez sur le bouton <em>Accueil <\/em>de votre smartphone: <img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-102530 alignnone\" title=\"Accueil Android\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/18g37wx5p0g0kjpg-129x94.jpg\" alt=\"Accueil Android\" width=\"38\" height=\"27\" \/><\/p>\n<p><strong>4.<\/strong> Une fen\u00eatre vous invite \u00e0 pr\u00e9sent \u00e0 choisir un lanceur. Appuyez sur <em>Nova Launcher,<\/em> puis sur <em>Toujours<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-102510\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/23-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/23.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/23-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/23-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/23-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><strong>Attention:<\/strong> vous pourrez toujours retrouver le lanceur install\u00e9 par d\u00e9faut sur votre smartphone en d\u00e9sinstallant Nova Launcher ou en changeant les actions par d\u00e9faut de l&#8217;application dans les r\u00e9glages.<\/p>\n<h3>Remplacer une ic\u00f4ne<\/h3>\n<p><strong>1.<\/strong> T\u00e9l\u00e9chargez et installez le pack d&#8217;ic\u00f4nes de votre choix depuis le <a title=\"Google Play ic\u00f4nes\" href=\"https:\/\/play.google.com\/store\/search?q=icons&amp;c=apps&amp;hl=fr\" target=\"_blank\" rel=\"noopener noreferrer\">Google Play<\/a>.<\/p>\n<p><strong>2.<\/strong> Laissez votre doigt appuy\u00e9 sur l&#8217;ic\u00f4ne de l&#8217;application que vous souhaitez remplacer. Une fen\u00eatre appara\u00eet. Appuyez sur <em>Edit.<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-102517\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/32-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/32.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/32-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/32-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/32-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/em><strong>3.<\/strong><em> <\/em> Appuyez sur l&#8217;ic\u00f4ne de l&#8217;application pour modifier cette derni\u00e8re.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-102519\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/42-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/42.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/42-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/42-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/42-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p><strong>4. <\/strong>Chaque collection d&#8217;ic\u00f4nes install\u00e9es appara\u00eet dans un onglet diff\u00e9rent. D\u00e9placez-vous jusqu&#8217;\u00e0 la collection de votre choix en effectuant des glissements lat\u00e9raux ou en appuyant directement sur le titre de la collection en question.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-102524\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/521-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/521.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/521-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/521-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/521-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><strong>5. <\/strong>D\u00e9filez jusqu&#8217;\u00e0 l&#8217;ic\u00f4ne de votre choix et appuyez dessus pour la s\u00e9lectionner.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-102527\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/61-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/61.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/61-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/61-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/61-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><strong>6.<\/strong> Appuyez sur le bouton situ\u00e9 dans le coin sup\u00e9rieur gauche de la fen\u00eatre pour valider votre choix.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-102528\" title=\"Changer icones Android Nova Launcher\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/09\/71-568x320.png\" alt=\"Changer icones Android Nova Launcher\" width=\"568\" height=\"320\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/71.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/71-268x150.png 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/71-300x169.png 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/09\/71-238x134.png 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>La <strong>personnalisation <\/strong>esth\u00e9tique d&#8217;Android n&#8217;a plus de secrets pour vous \u00e0 pr\u00e9sent. Il ne vous reste plus qu&#8217;\u00e0 t\u00e9l\u00e9charger les packs d&#8217;ic\u00f4nes de votre choix pour faire de votre smartphone le reflet de votre personnalit\u00e9.<\/p>\n<p>Et si vous souhaitez utiliser la personnalisation d&#8217;Android \u00e0 des fins moins futiles, <strong>je vous recommande<\/strong> <a title=\"5 applis Android qui me rendent plus efficace au bureau\" href=\"http:\/\/articles.softonic.fr\/astuces-apps-productivite-android?ab=1\" target=\"_self\" rel=\"noopener noreferrer\">5 applications qui augmentent ma productivit\u00e9 tous les jours<\/a>.<\/p>\n<p><em>Suivez-moi sur Twitter: <a href=\"https:\/\/twitter.com\/SamSoftonic\" target=\"_blank\" rel=\"noopener noreferrer\">@SamSoftonic<\/a> <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est tr\u00e8s facile de changer les ic\u00f4nes de ses applications Android en passant par un lanceur alternatif. Je vous explique comment personnaliser votre smartphone avec le lanceur Nova Launcher. J&#8217;adore Android pour la libert\u00e9 qu&#8217;il offre \u00e0 ses utilisateurs. En installant quelques applications, j&#8217;ai pu personnaliser mon smartphone et l&#8217;adapter \u00e0 mes pr\u00e9f\u00e9rences. Aujourd&#8217;hui &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/fr\/changer-icones-android\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Comment changer les ic\u00f4nes sur Android&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8021,"featured_media":102401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[16774,1],"tags":[1250,13421,3136,11870,106,11804,10918,13422,9599,13423,115,85],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-102392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","category-uncategorized","tag-changer","tag-changer-icone","tag-customisation","tag-icone","tag-icones","tag-lanceur","tag-launcher","tag-nova","tag-nova-launcher","tag-personalisation","tag-personnaliser","tag-theme"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/102392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8021"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=102392"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/102392\/revisions"}],"predecessor-version":[{"id":163215,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/102392\/revisions\/163215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media\/102401"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=102392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=102392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=102392"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=102392"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=102392"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=102392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}