{"id":12346,"date":"2011-03-16T12:13:28","date_gmt":"2011-03-16T10:13:28","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=12346"},"modified":"2025-06-12T13:25:36","modified_gmt":"2025-06-12T12:25:36","slug":"un-nouveau-logo-pour-google-chrome","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/un-nouveau-logo-pour-google-chrome\/","title":{"rendered":"Un nouveau logo pour Google Chrome"},"content":{"rendered":"<p><a href=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2011\/03\/chrome_logos.jpg\" rel=\"attachment wp-att-12349\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2011\/03\/chrome_logos.jpg\" alt=\"\" width=\"600\" height=\"260\" class=\"aligncenter size-full wp-image-12349\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2011\/03\/chrome_logos.jpg 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2011\/03\/chrome_logos-290x125.jpg 290w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Plus plat, plus g\u00e9om\u00e9trique, moins brillant: voici donc le nouveau logo qui devrait accompagner la version 11.0.696.12 de Google Chrome, <a href=\"http:\/\/googlechromereleases.blogspot.com\/2011\/03\/dev-channel-update_15.html\">actuellement en d\u00e9veloppement<\/a>. On s&#8217;y attendait depuis une dizaine de jours puisque <a href=\"http:\/\/www.chromium.org\/\">Chromium<\/a>, le navigateur internet libre sur lequel est bas\u00e9 Google Chrome, avait vu son ic\u00f4ne bleut\u00e9e redessin\u00e9e de la m\u00eame mani\u00e8re d\u00e9but mars.<\/p>\n<p><a href=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2011\/03\/chromium_logos.jpg\" rel=\"attachment wp-att-12350\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2011\/03\/chromium_logos.jpg\" alt=\"\" width=\"460\" height=\"200\" class=\"aligncenter size-full wp-image-12350\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2011\/03\/chromium_logos.jpg 460w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2011\/03\/chromium_logos-290x126.jpg 290w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/><\/a><\/p>\n<p>Un changement d&#8217;identit\u00e9 uniquement esth\u00e9tique, mais cette refonte profonde du logo correspond \u00e0 l&#8217;arriv\u00e9e prochaine de nouvelles fonctionnalit\u00e9s tr\u00e8s pratiques comme la possibilit\u00e9 de s\u00e9lectionner plusieurs onglets \u00e0 la fois, des titres abr\u00e9g\u00e9s pour ces derniers afin de mieux les distinguer ou encore, au niveau technique, l&#8217;am\u00e9lioration du moteur JavaScript 8.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus plat, plus g\u00e9om\u00e9trique, moins brillant: voici donc le nouveau logo qui devrait accompagner la version 11.0.696.12 de Google Chrome, actuellement en d\u00e9veloppement. On s&#8217;y attendait depuis une dizaine de jours puisque Chromium, le navigateur internet libre sur lequel est bas\u00e9 Google Chrome, avait vu son ic\u00f4ne bleut\u00e9e redessin\u00e9e de la m\u00eame mani\u00e8re d\u00e9but mars. &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/fr\/un-nouveau-logo-pour-google-chrome\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Un nouveau logo pour Google Chrome&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8009,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[1438,558,204],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-12346","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-chrome-11","tag-google-chrome","tag-navigateur"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/12346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8009"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=12346"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/12346\/revisions"}],"predecessor-version":[{"id":168437,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/12346\/revisions\/168437"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=12346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=12346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=12346"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=12346"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=12346"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=12346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}