{"id":13389,"date":"2011-04-20T16:05:05","date_gmt":"2011-04-20T14:05:05","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=13389"},"modified":"2025-06-12T13:24:32","modified_gmt":"2025-06-12T12:24:32","slug":"jeu-flash-du-mercredi-cat-astro-phi","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/jeu-flash-du-mercredi-cat-astro-phi\/","title":{"rendered":"Jeu Flash du mercredi: Cat Astro Phi"},"content":{"rendered":"<p><a href=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2011\/04\/gameboy.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2011\/04\/gameboy.png\" alt=\"\" width=\"600\" height=\"319\" class=\"aligncenter size-full wp-image-13390\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2011\/04\/gameboy.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2011\/04\/gameboy-290x154.png 290w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Cat Astro Phi<\/strong> est un petit jeu d&#8217;aventure \u00e0 l&#8217;ancienne qui se joue directement dans le navigateur. Dans un style monochrome fa\u00e7on \u00e9cran de Game Boy 1\u00e8re g\u00e9n\u00e9ration, le jeu vous met dans la peau d&#8217;un astronaute dont le chat a \u00e9t\u00e9 \u00e9ject\u00e9 du vaisseau. A vous de retrouver votre compagnon en explorant la plan\u00e8te hostile o\u00f9 il a atterri.<\/p>\n<p>Le jeu en lui-m\u00eame n&#8217;offre pas \u00e9norm\u00e9ment de surprise: on se d\u00e9place dans des niveaux en vue de dessus et il faut trouver la sortie en r\u00e9cup\u00e9rant des cartes d&#8217;acc\u00e8s et en poussant des blocs. Vous pouvez \u00e9galement trouver des armes qui vous aideront \u00e0 \u00e9liminer les aliens qui peuplent ces lieux.<\/p>\n<p>Les graphismes sont tr\u00e8s r\u00e9ussis et on a vraiment le sentiment de jouer \u00e0 un jeu sur la premi\u00e8re console portable de Nintendo. Un effort tout particulier a \u00e9galement \u00e9t\u00e9 apport\u00e9 \u00e0 la musique.<\/p>\n<p>Vous pouvez jouer \u00e0 <strong>Cat Astro Phi<\/strong> sur <a href=\"http:\/\/www.newgrounds.com\/portal\/view\/555641\">cette page<\/a>, mais votre navigateur web doit \u00eatre \u00e9quip\u00e9 de Flash Player.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cat Astro Phi est un petit jeu d&#8217;aventure \u00e0 l&#8217;ancienne qui se joue directement dans le navigateur. Dans un style monochrome fa\u00e7on \u00e9cran de Game Boy 1\u00e8re g\u00e9n\u00e9ration, le jeu vous met dans la peau d&#8217;un astronaute dont le chat a \u00e9t\u00e9 \u00e9ject\u00e9 du vaisseau. A vous de retrouver votre compagnon en explorant la plan\u00e8te &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/fr\/jeu-flash-du-mercredi-cat-astro-phi\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Jeu Flash du mercredi: Cat Astro Phi&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8009,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-13389","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/13389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8009"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=13389"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/13389\/revisions"}],"predecessor-version":[{"id":168391,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/13389\/revisions\/168391"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=13389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=13389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=13389"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=13389"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=13389"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=13389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}