{"id":139043,"date":"2024-06-05T11:15:58","date_gmt":"2024-06-05T09:15:58","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=333726"},"modified":"2025-06-12T11:01:33","modified_gmt":"2025-06-12T10:01:33","slug":"une-troisieme-faction-est-elle-sur-le-point-darriver-dans-helldivers-2","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/une-troisieme-faction-est-elle-sur-le-point-darriver-dans-helldivers-2\/","title":{"rendered":"Une troisi\u00e8me faction est-elle sur le point d&#8217;arriver dans Helldivers 2 ?"},"content":{"rendered":"\n<p>Personne n&#8217;attendait \u00e0 grand-chose de Helldivers 2. Au final, il s&#8217;agit de l&#8217;un des jeux les plus r\u00e9ussis de l&#8217;ann\u00e9e et \u00e0 raison. <strong>Artistiquement impeccable et m\u00e9caniquement excellent, un point nous donne toujours envie d&#8217;y retourner quoi qu&#8217;il arrive : sa narration<\/strong>. Ses d\u00e9veloppeurs parviennent \u00e0 raconter une histoire passionnante dont les joueurs font partie int\u00e9grante. Et cette histoire va peut-\u00eatre prendre un tournant important.<\/p>\n\n\n\n<p>Depuis la Super Terre, pendant le week-end, un nouvel ordre a \u00e9t\u00e9 envoy\u00e9 \u00e0 tous les helldivers. <strong>Ils devaient descendre sur Meridia pour \u00e9liminer une super colonie de terminides ravageant la plan\u00e8te<\/strong>. Une action extr\u00eamement urgente, \u00e9tant donn\u00e9 que cette plan\u00e8te \u00e9tait autrefois une paisible plan\u00e8te mar\u00e9cageuse.<\/p>\n\n\n<div class=\"sc-card-affiliation\">\r\n  <div class=\"sc-card-affiliation__content\">\r\n    <a href=\"https:\/\/www.instant-gaming.com\/fr\/9575-acheter-steam-helldivers-2-pc-jeu-steam-europe\/?igr=softonic1\" class=\"sc-card-affiliation__badge\" target=\"_blank\" rel=\"noopener noreferrer\">-28%<\/a>\r\n    <div class=\"sc-card-affiliation__image\">\r\n      <a href=\"https:\/\/www.instant-gaming.com\/fr\/9575-acheter-steam-helldivers-2-pc-jeu-steam-europe\/?igr=softonic1\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n                <img decoding=\"async\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/86f8271e-d1af-4716-9964-753f69141f89\/1032133425\/arrowheads-helldivers-2-download-arrowheads-helldivers-2.jpg\">\r\n            <\/a>\r\n    <\/div>\r\n\r\n    <div class=\"sc-card-affiliation__body\">\r\n      <div class=\"sc-card-affiliation__text\">\r\n        <h3>\r\n                    <a href=\"https:\/\/www.instant-gaming.com\/fr\/9575-acheter-steam-helldivers-2-pc-jeu-steam-europe\/?igr=softonic1\" target=\"_blank\" rel=\"noopener noreferrer\">Helldivers 2<\/a>\r\n                <\/h3>\r\n        <p class=\"sc-card-affiliation__supplier\">\r\n          De: <strong>Instant-Gaming<\/strong>\r\n        <\/p>\r\n        <p class=\"sc-card-affiliation__price\">\r\n          28.68\u20ac <strike>40\u20ac<\/strike>\r\n        <\/p>\r\n      <\/div>\r\n      <div class=\"sc-card-affiliation__cta\">\r\n        <a href=\"https:\/\/www.instant-gaming.com\/fr\/9575-acheter-steam-helldivers-2-pc-jeu-steam-europe\/?igr=softonic1\" target=\"_blank\" class=\"sc-card-affiliation__button\" rel=\"noopener noreferrer\">Acheter<\/a>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p>La r\u00e9alit\u00e9 de la descente \u00e0 Meridia a \u00e9t\u00e9 bien plus terrible que pr\u00e9vu. En plus d&#8217;une quantit\u00e9 massive de terminides, les extraterrestres ont cr\u00e9\u00e9 des tours de spores partout sur la plan\u00e8te, visibles de loin. <strong>Il s&#8217;agissait d&#8217;un objectif optionnel pour les plus courageux. Avec des nids partout et des terminides apparaissant constamment, il semblait que la mission ne pouvait pas \u00eatre plus difficile<\/strong>. Sauf qu&#8217;\u00e0 la fin de la mission, des terminides volants ont harcel\u00e9 impitoyablement les helldivers jusqu&#8217;\u00e0 ce qu&#8217;ils meurent ou parviennent \u00e0 s&#8217;\u00e9chapper. Une victoire pyrrhique, si tant est que l&#8217;on puisse consid\u00e9rer cela comme une victoire.<\/p>\n\n\n\n<p>Tout cela est le r\u00e9sultat d&#8217;un ordre pr\u00e9c\u00e9dent de la Super Terre. <strong>Apr\u00e8s que les helldivers aient lanc\u00e9 des termicides sur de nombreuses plan\u00e8tes, les hordes terminides se sont adapt\u00e9es<\/strong>. Mutant en formes grotesques, ce termicide a permis aux terminides de cr\u00e9er la super colonie de Meridia. Aucune l\u00e9gion de helldivers n&#8217;a r\u00e9ussi \u00e0 l&#8217;an\u00e9antir.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Helldivers 2: &quot;COMIENZA LA LUCHA POR LA LIBERTAD&quot; - Tr\u00e1iler de LANZAMIENTO | PlayStation Espa\u00f1a\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/-Lc2sLpWD3E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Pour autant, il ne s&#8217;agissait pas d&#8217;une mission de lib\u00e9ration, mais de destruction. <strong>Gr\u00e2ce aux actes des helldivers, ils ont r\u00e9ussi \u00e0 lib\u00e9rer suffisamment de fluide sombre pour cr\u00e9er un trou noir qui a compl\u00e8tement d\u00e9vor\u00e9 la plan\u00e8te Meridia<\/strong>, mettant fin aux spores de terminides \u00e0 des milliards de kilom\u00e8tres \u00e0 la ronde. Ceci a eu deux  cons\u00e9quences. La quantit\u00e9 de terminides a consid\u00e9rablement diminu\u00e9 dans les galaxies voisines et la certitude terrifiante que rien n&#8217;est fini.<\/p>\n\n\n\n<p>Un trou noir s&#8217;est form\u00e9 l\u00e0 o\u00f9 Meridia se situait autrefois, r\u00e9sultat du fluide sombre. <strong>Un composant chimique synth\u00e9tique cr\u00e9\u00e9 par Les Illumin\u00e9s, la troisi\u00e8me faction extraterrestre des premiers Helldivers<\/strong>. Cela a donn\u00e9 lieu \u00e0 de nombreuses th\u00e9ories de la part des joueurs. Il est possible qu&#8217;ils attirent l&#8217;attention de cette civilisation en utilisant leurs propres armes, ou que le trou noir soit en r\u00e9alit\u00e9 un trou de ver qui a envoy\u00e9 des millions de terminides dans sa direction. Quoi qu&#8217;il en soit, une chose est claire : les Illumin\u00e9s sont l\u00e0. Et ils sont bien plus dangereux que n&#8217;importe quelle quantit\u00e9 de terminides et d&#8217;automates.<\/p>\n\n\n\n<p><em>Certains des liens ajout\u00e9s dans l&#8217;article sont issus de campagnes d&#8217;affiliation et peuvent constituer un revenu pour Softonic.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jusqu&#8217;\u00e0 pr\u00e9sent, seules deux factions ont \u00e9t\u00e9 pr\u00e9sent\u00e9es dans Helldivers 2, mais apr\u00e8s la catastrophe de Meridia, il semblerait que la troisi\u00e8me faction soit proche.<\/p>\n","protected":false},"author":9268,"featured_media":139046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[16764,16761],"tags":[17232,17324],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-139043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming","category-news","tag-helldivers-2","tag-iluminados"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/139043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/9268"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=139043"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/139043\/revisions"}],"predecessor-version":[{"id":161387,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/139043\/revisions\/161387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media\/139046"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=139043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=139043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=139043"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=139043"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=139043"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=139043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}