{"id":139861,"date":"2024-06-19T17:05:18","date_gmt":"2024-06-19T15:05:18","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=334588"},"modified":"2025-06-12T10:58:27","modified_gmt":"2025-06-12T09:58:27","slug":"le-premier-resident-evil-pourrait-arriver-sur-pc","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/le-premier-resident-evil-pourrait-arriver-sur-pc\/","title":{"rendered":"Le premier Resident Evil pourrait arriver sur PC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Capcom n&#8217;est pas pr\u00eat \u00e0 renoncer \u00e0 un seul Resident Evil pour le ramener dans le pr\u00e9sent. Nous ne les bl\u00e2mons pas. <strong>Ce sont d&#8217;excellents jeux, pour la plupart, et ils ont plut\u00f4t bien vieilli <\/strong>. Avec les quelques changements que Capcom apporte \u00e0 leurs remakes, ils les adaptent parfaitement aux sensibilit\u00e9s modernes, tout en en faisant de nouvelles versions qui ne remplacent pas les originaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cela ne veut pas dire que les jeux originaux n&#8217;ont pas leur place dans nos c\u0153urs. Ce n&#8217;est pas pour rien qu&#8217;<strong>ils sont les pionniers des jeux de survival horror modernes, et s&#8217;il est vrai que les contr\u00f4les peuvent parfois \u00eatre un peu difficiles, ils n&#8217;en restent pas moins fabuleux<\/strong>. C&#8217;est pourquoi toute nouvelle concernant le retour du Resident Evil original est toujours une raison de se r\u00e9jouir. Et c&#8217;est exactement ce qui s&#8217;est pass\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resident Evil <a href=\"https:\/\/x.com\/gematsu\/status\/1802945852689801265\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">a re\u00e7u une classification PEGI 18 pour PC en Europe<\/a>. Si cela vous semble \u00e9trange, ce qui est encore plus bizarre, c&#8217;est que <strong>nous parlons du premier Resident Evil, celui de 1996, et la date \u00e0 laquelle il a \u00e9t\u00e9 enregistr\u00e9 est le 18 juin 2024<\/strong>. Cela sugg\u00e8re une possible r\u00e9\u00e9dition du jeu dont nous ne savons encore rien, mais que nous attendons avec impatience.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Resident Evil 1 1996 Ps1 Trailer\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/-z9MKsGtL6M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cela \u00e9tant dit, il a une caract\u00e9ristique assez remarquable. Resident Evil a d\u00e9j\u00e0 \u00e9t\u00e9 lanc\u00e9 \u00e0 l&#8217;\u00e9poque sur PC. <strong>Initialement sorti en d\u00e9cembre 1996 au Japon et arriv\u00e9 tout au long de 1997 en Am\u00e9rique du Nord et en Europe, c&#8217;\u00e9tait l&#8217;un des premiers et rares jeux de console de l&#8217;\u00e9poque \u00e0 sortir \u00e9galement sur PC<\/strong>. Cependant, cette \u00e9dition du jeu n&#8217;est plus disponible sur aucune plateforme moderne, il n&#8217;est donc plus possible d&#8217;en profiter. Du moins pas l\u00e9galement, \u00e0 moins de l&#8217;avoir achet\u00e9 il y a 27 ans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme il n&#8217;est pas disponible sur Steam, GOG ou toute autre plateforme num\u00e9rique, <strong>nous comprenons que cette classification PEGI doit \u00eatre pour une future sortie sur PC<\/strong>. Cependant, Capcom n&#8217;a encore rien annonc\u00e9 \u00e0 ce sujet. Cependant, on s&#8217;attend \u00e0 ce qu&#8217;ils disent quelque chose de concret dans les prochaines semaines ou mois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/3047d89c-96d0-11e6-8546-00163ed833e7\/2505233623\/steam-download.jpg\" alt=\"Steam\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Steam<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/steam.fr.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\">T\u00c9L\u00c9CHARGER<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        \r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/steam.fr.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Resident Evil original, de 1996, podr\u00eda llegar a PC seg\u00fan ha desvelado el PEGI al darle una clasificaci\u00f3n de edades que, por supuesto, es +18<\/p>\n","protected":false},"author":9268,"featured_media":139863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[16764,16761],"tags":[410,6726],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-139861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming","category-news","tag-pc","tag-resident-evil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/139861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/9268"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=139861"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/139861\/revisions"}],"predecessor-version":[{"id":161223,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/139861\/revisions\/161223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media\/139863"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=139861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=139861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=139861"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=139861"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=139861"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=139861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}