{"id":147372,"date":"2024-11-07T13:21:12","date_gmt":"2024-11-07T12:21:12","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=343547"},"modified":"2025-06-12T10:28:18","modified_gmt":"2025-06-12T09:28:18","slug":"tout-ce-que-la-version-1-3-de-zenless-zone-zero-apporte-agents-histoire-evenements-et-plus","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/tout-ce-que-la-version-1-3-de-zenless-zone-zero-apporte-agents-histoire-evenements-et-plus\/","title":{"rendered":"Tout ce que la version 1.3 de Zenless Zone Zero apporte : agents, histoire, \u00e9v\u00e9nements et plus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La derni\u00e8re grande mise \u00e0 jour de Zenless Zone Zero<strong>, la version 1.3<\/strong> (connue sous le nom de Virtual Revenge), <strong>est d\u00e9j\u00e0 disponible et apporte une multitude de contenu pour les nouveaux joueurs et les v\u00e9t\u00e9rans.<\/strong><\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/7dc509c6-769f-44ca-a4d6-c67415d17098\/1258040425\/zenless-zone-zero-Zenless-icon.png\" alt=\"Zenless Zone Zero\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Zenless Zone Zero<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/zenless-zone-zero.fr.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\">T\u00c9L\u00c9CHARGER<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        \r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/zenless-zone-zero.fr.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les principales nouveaut\u00e9s sont deux nouveaux agents jouables : Tsukishiro Yanagi et Lighter.<\/strong> Nous allons expliquer en quoi ces deux agents jouables se distinguent.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Yanagi est une agente de rang S de l&#8217;Anomalie \u00c9lectrique<\/strong> <em>et fait partie de la faction de la Section 6<\/em>. Son style de combat propose de multiples postures de combat, en plus de la capacit\u00e9 d&#8217;activer l&#8217;effet sp\u00e9cial Trouble de polarit\u00e9 pour infliger une \u00e9norme quantit\u00e9 de d\u00e9g\u00e2ts aux ennemis avec l&#8217;anomalie.<\/li>\n\n\n\n<li><strong>Lighter est un autre agent de rang S<\/strong>, cette fois de Feu \u00c9tourdissant et membre du gang des Enfants de Calydon. Il est \u00e9quip\u00e9 de boosters d&#8217;attributs \u00e9l\u00e9mentaires, avec la capacit\u00e9 de r\u00e9cup\u00e9rer du Moral \u00e0 mesure que ses compagnons consomment de l&#8217;\u00e9nergie. Avec suffisamment de Moral, il peut entrer en \u00e9tat d&#8217;explosion de Moral, ce qui augmente consid\u00e9rablement sa puissance.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Zenless Zone Zero Version 1.3 &quot;Virtual Revenge&quot; is Now Live!<a href=\"https:\/\/twitter.com\/hashtag\/zzzero?src=hash&amp;ref_src=twsrc%5Etfw\">#zzzero<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/zenlesszonezero?src=hash&amp;ref_src=twsrc%5Etfw\">#zenlesszonezero<\/a><a href=\"https:\/\/twitter.com\/hashtag\/VirtualRevenge?src=hash&amp;ref_src=twsrc%5Etfw\">#VirtualRevenge<\/a> <a href=\"https:\/\/t.co\/ErV0q5HOeT\">pic.twitter.com\/ErV0q5HOeT<\/a><\/p>&mdash; Zenless Zone Zero (@ZZZ_EN) <a href=\"https:\/\/twitter.com\/ZZZ_EN\/status\/1854010891580121208?ref_src=twsrc%5Etfw\">November 6, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ce que nous savons de la version 1.3 de Zenless Zone Zero<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deux nouveaux moteurs W de rang S ont \u00e9galement \u00e9t\u00e9 introduits, l&#8217;Anomaly Timeweaver et le Stun Blazing Laurel.<\/strong> En plus de deux nouveaux Bangboos de rang A, le sympathique Babbieboo et le Knightboo. Le Knightboo peut d\u00e9sormais \u00eatre obtenu via le nouvel \u00e9v\u00e9nement du jeu \u00ab Le myst\u00e8re de la faille d&#8217;arp\u00e8ge \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme pr\u00e9vu, <strong>la mise \u00e0 jour inclut \u00e9galement de nouveaux contenus, comme l&#8217;\u00e9pisode sp\u00e9cial \u00ab Vengeance virtuelle \u00bb<\/strong>. Cela s&#8217;ajoute \u00e0 une nouvelle histoire d&#8217;agent pour Lighter.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Version 1.3 Teaser - &quot;Virtual Revenge&quot; | Zenless Zone Zero\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/pvP1bv_gLtQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tout cela s&#8217;ajoute aux <strong>mises \u00e0 jour des zones existantes, comme le nouveau b\u00e2timent San-Z Studio \u00e0 Lumina Square,<\/strong> qui est accompagn\u00e9 d&#8217;un nouvel exposant dans Random Play pouvant \u00eatre utilis\u00e9 pour afficher les objets obtenus l\u00e0-bas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un camion de snacks est \u00e9galement arriv\u00e9 sur la place Lumina,<\/strong> mais il ne sera pr\u00e9sent que pendant l&#8217;\u00e9v\u00e9nement limit\u00e9 \u00ab Quand les snacks frappent \u00e0 la porte \u00bb. Une avalanche d&#8217;\u00e9v\u00e9nements a \u00e9galement commenc\u00e9, dont l&#8217;un vous permet d&#8217;obtenir dix objets du Ruban ma\u00eetre crypt\u00e9 simplement en vous connectant chaque jour.<\/p>\n\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/7dc509c6-769f-44ca-a4d6-c67415d17098\/1258040425\/zenless-zone-zero-Zenless-icon.png\" alt=\"Zenless Zone Zero\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Zenless Zone Zero<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/zenless-zone-zero.fr.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\">T\u00c9L\u00c9CHARGER<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        \r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/zenless-zone-zero.fr.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a \u00e9norm\u00e9ment de contenu, et ce r\u00e9sum\u00e9 ne fait qu&#8217;effleurer la surface de ce que la version 1.3 apporte. Vous pouvez trouver une r\u00e9partition compl\u00e8te sur la page officielle des d\u00e9tails de la mise \u00e0 jour du site web Zenless Zone Zero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La derni\u00e8re grande mise \u00e0 jour de Zenless Zone Zero, la version 1.3 (connue sous le nom de Virtual Revenge), est d\u00e9sormais disponible et apporte une multitude de contenus pour les nouveaux joueurs et les v\u00e9t\u00e9rans. Les principales nouveaut\u00e9s sont deux nouveaux agents jouables : Tsukishiro Yanagi et Lighter. Nous allons expliquer en quoi ces deux agents jouables se diff\u00e9rencient. Que savons-nous de la version 1.3 de Zenless Zone Zero Deux nouveaux moteurs W de rang S ont \u00e9galement \u00e9t\u00e9 introduits, l&#8217;Anomaly Timeweaver et le Stun Blazing Laurel. En plus de deux nouveaux Bangboos de rang A, le sympathique Babbieboo et le Knightboo. Le Knightboo peut \u00eatre obtenu maintenant [&hellip;]<\/p>\n","protected":false},"author":9265,"featured_media":147381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[16761],"tags":[17437],"usertag":[],"vertical":[],"content-category":[17583],"class_list":["post-147372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-zenless-zone-zero","content-category-style-vie"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/147372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/9265"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=147372"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/147372\/revisions"}],"predecessor-version":[{"id":159558,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/147372\/revisions\/159558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media\/147381"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=147372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=147372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=147372"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=147372"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=147372"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=147372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}