{"id":154862,"date":"2025-05-06T12:45:00","date_gmt":"2025-05-06T11:45:00","guid":{"rendered":"https:\/\/sftarticles.wpenginepowered.com\/es\/?p=354282"},"modified":"2025-06-11T20:00:18","modified_gmt":"2025-06-11T19:00:18","slug":"microsoft-annonce-la-fermeture-de-skype","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/microsoft-annonce-la-fermeture-de-skype\/","title":{"rendered":"Microsoft annonce la fermeture de Skype"},"content":{"rendered":"\n<p>Microsoft a annonc\u00e9 la fermeture d\u00e9finitive de Skype, une plateforme de communication num\u00e9rique qui a \u00e9t\u00e9 en fonctionnement pendant 22 ans. <strong>Depuis son lancement en 2003, Skype a travers\u00e9 plusieurs \u00e9tapes, \u00e9tant vendu \u00e0 trois reprises avant d&#8217;\u00eatre acquis par Microsoft en 2011 pour 8,5 milliards de dollars<\/strong>. \u00c0 son apog\u00e9e, l&#8217;application comptait plus de 100 millions d&#8217;utilisateurs mensuels et est devenue l&#8217;option pr\u00e9f\u00e9r\u00e9e de nombreuses g\u00e9n\u00e9rations pour la communication num\u00e9rique.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Skype \u00e0 partir de maintenant s&#8217;int\u00e9grera dans Steams<\/h2>\n\n\n<p>Cependant, au fil des ans, Skype a fait face \u00e0 une concurrence intense d&#8217;autres plateformes comme Discord, Zoom et Google Meet. <strong>Alors que les technologies de chat vocal devenaient omnipr\u00e9sentes dans des services alternatifs, Skype a commenc\u00e9 \u00e0 perdre sa pertinence<\/strong>. La r\u00e9vision constante de son interface utilisateur et l&#8217;introduction de fonctionnalit\u00e9s inutiles ont contribu\u00e9 \u00e0 cette diminution, poussant les utilisateurs \u00e0 chercher des alternatives plus simples et efficaces.<\/p>\n\n\n<p>Bien que Skype comptait encore 36 millions d&#8217;utilisateurs mensuels en 2023, ce chiffre \u00e9tait consid\u00e9r\u00e9 comme faible par rapport aux normes de Microsoft. <strong>Les utilisateurs de Skype ont connu un exode vers d&#8217;autres services, notamment pendant la pand\u00e9mie de COVID-19, lorsque des plateformes comme Zoom sont devenues la norme<\/strong>.<\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Next Chapter: From Skype to Teams\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/FK-WjbsVgB4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<p>Microsoft a annonc\u00e9 qu&#8217;\u00e0 partir de maintenant, les contacts et les discussions de Skype seront transf\u00e9r\u00e9s automatiquement vers Microsoft Teams, tandis que les utilisateurs de Skype for Business ne seront pas affect\u00e9s par cette fermeture. <strong>La fermeture a \u00e9t\u00e9 officiellement annonc\u00e9e en f\u00e9vrier, et en essayant d&#8217;acc\u00e9der \u00e0 la page de t\u00e9l\u00e9chargement de Skype, on obtient une erreur similaire \u00e0 un 404<\/strong>.<\/p>\n\n\n<p>Pour ceux qui d\u00e9pendent encore de Skype, <strong>Microsoft a indiqu\u00e9 qu&#8217;il est \u00e9galement possible d&#8217;exporter les donn\u00e9es de Skype pour un usage personnel<\/strong>. Cependant, la transition vers Microsoft Teams semble \u00eatre la direction par d\u00e9faut pour la plupart des utilisateurs.<\/p>\n\n<div class=\"sc-card-program\">\r\n  <div class=\"sc-card-program__body\">\r\n    <div class=\"sc-card-program__row clearfix\">\r\n      <div class=\"sc-card-program__col-logo\">\r\n        <img decoding=\"async\" class=\"sc-card-program__img\" src=\"https:\/\/images.sftcdn.net\/images\/t_app-icon-s\/p\/3a83edc2-8bcb-4baa-8fbe-3ddcf458c1a4\/1709716978\/windows-11-win11icon.png\" alt=\"Windows 11\" width=\"100px\" height=\"100px\">\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-title\">\r\n        <span class=\"sc-card-program__title\">Windows 11<\/span>\r\n        <a class=\"sc-card-program__button sc-card-program-internal\" href=\"https:\/\/windows-11.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\">T\u00c9L\u00c9CHARGER<\/a>\r\n      <\/div>\r\n      <div class=\"sc-card-program__col-rating\">\r\n        \r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <span class=\"sc-card-program__description\"><\/span>\r\n    <\/div>\r\n    <div class=\"sc-card-program__row\">\r\n      <img decoding=\"async\" class=\"sc-card-program__bigpic\" src=\"\">\r\n    <\/div>\r\n    <a class=\"sc-card-program__link track-link sc-card-program-internal\" href=\"https:\/\/windows-11.softonic.com\/\" target=\"_self\" rel=\"noopener noreferrer\"><\/a>\r\n  <\/div>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft a annonc\u00e9 la fermeture d\u00e9finitive de Skype, une plateforme de communication num\u00e9rique qui a \u00e9t\u00e9 en fonctionnement pendant 22 ans. Depuis son lancement en 2003, Skype a travers\u00e9 plusieurs \u00e9tapes, \u00e9tant vendu \u00e0 trois reprises avant d&#8217;\u00eatre acquis par Microsoft en 2011 pour 8,5 milliards de dollars. \u00c0 son apog\u00e9e, l&#8217;application comptait plus de 100 millions d&#8217;utilisateurs mensuels et est devenue l&#8217;option pr\u00e9f\u00e9r\u00e9e de nombreuses g\u00e9n\u00e9rations pour la communication num\u00e9rique. Skype sera d\u00e9sormais int\u00e9gr\u00e9 dans Steams Cependant, au fil des ans, Skype a fait face \u00e0 une concurrence intense [&hellip;]<\/p>\n","protected":false},"author":9318,"featured_media":154865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[16761],"tags":[20082,18504,22304,53,17155,278,22305,83],"usertag":[],"vertical":[],"content-category":[17598],"class_list":["post-154862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cierre","tag-discord","tag-google-meet","tag-microsoft","tag-microsoft-teams","tag-skype","tag-skype-for-business","tag-zoom","content-category-multimedia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/154862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/9318"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=154862"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/154862\/revisions"}],"predecessor-version":[{"id":156920,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/154862\/revisions\/156920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media\/154865"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=154862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=154862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=154862"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=154862"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=154862"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=154862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}