{"id":25124,"date":"2012-04-14T10:00:49","date_gmt":"2012-04-14T08:00:49","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=25124"},"modified":"2025-06-12T13:15:57","modified_gmt":"2025-06-12T12:15:57","slug":"virus-flashback-comment-desinfecter-votre-mac","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/virus-flashback-comment-desinfecter-votre-mac\/","title":{"rendered":"Virus Flashback : Comment d\u00e9sinfecter votre Mac ?"},"content":{"rendered":"<p><strong>Le Virus Flashback est un logiciel malveillant de type <a title=\"Cheval de troie virus\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Cheval_de_Troie_%28informatique%29\" target=\"_blank\" rel=\"noopener noreferrer\">cheval de Troie<\/a> qui cible la plateforme Mac OSX et qui aurait infect\u00e9 plus d\u2019un demi-million d\u2019ordinateurs sur la plan\u00e8te. D\u00e9couvrez la marche \u00e0 suivre pour prot\u00e9ger votre machine.<\/strong><\/p>\n<p><strong>M\u00e0j : <\/strong>Apple a publi\u00e9 une solution officielle pour supprimer ou \u00e9viter le virus Flashback<\/p>\n<p style=\"text-align: center\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-25265 aligncenter\" title=\"virus mac flashback\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/04\/virusmac-600x352.png\" alt=\"virus mac flashback\" width=\"600\" height=\"352\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2012\/04\/virusmac-600x352.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2012\/04\/virusmac-290x170.png 290w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2012\/04\/virusmac.png 980w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<\/strong><br \/>\n<!--more--><\/p>\n<h3><strong>Comment savoir si mon Mac est infect\u00e9 ?<\/strong><\/h3>\n<address style=\"width: 270px;float: right;margin-left: 15px;background-color: #87cefa\">\n<ul>\n<h3>Prot\u00e9gez votre Mac !<\/h3>\n<p id=\"file_title\"><a title=\"Avira Free Mac Security  1.0.0.50 \" href=\"http:\/\/avira-free-mac-security.softonic.fr\/mac\"><strong>Avira Free Mac Security<\/strong><\/a><\/p>\n<p id=\"file_title\"><a title=\"Little Snitch  2.0.5 \" href=\"http:\/\/little-snitch.softonic.fr\/mac\"><strong>Little Snitch<\/strong><\/a><\/p>\n<p id=\"file_title\"><a title=\"Onyx pour Snow Leopard 2.2 \" href=\"http:\/\/onyx.softonic.fr\/mac\"><strong>Onyx<\/strong><\/a><\/p>\n<p id=\"file_title\"><a title=\"Sophos Antivirus\" href=\"http:\/\/sophos-anti-virus.softonic.fr\/mac\"><strong>Sophos Anti-Virus<\/strong><\/a><\/p>\n<\/ul>\n<\/address>\n<p><strong><br \/>\n<\/strong><\/p>\n<p>Si l\u2019id\u00e9e d\u2019utiliser Terminal pour v\u00e9rifier si votre Mac est infect\u00e9 par le <strong>virus Flashback<\/strong> vous donne des boutons, sachez qu\u2019il existe un <strong>outil simple et gratuit<\/strong> qui s\u2019en charge automatiquement ! <a title=\"Flashback Checker\" href=\"http:\/\/flashback-checker.softonic.fr\/mac\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Flashback Checker<\/strong><\/a> fera le n\u00e9cessaire pour v\u00e9rifier que votre ordinateur ne fait pas partie des<a title=\"600000 macs contamin\u00e9s par le virus FlashBack\" href=\"http:\/\/www.francetv.fr\/info\/les-ordinateurs-mac-aussi-ont-droit-a-leur-virus_80769.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> 600000 ordinateurs Mac contamin\u00e9s par l\u2019\u00e9pid\u00e9mie.<\/strong><\/a> Une fois le scan de votre machine termin\u00e9, le logiciel vous indiquera si votre ordinateur est infect\u00e9 ou non.<\/p>\n<h3><strong>Comment d\u00e9sinfecter mon ordinateur ?<\/strong><\/h3>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-25138\" title=\"kaspersky-flashfake-removal-tool\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2006\/04\/kaspersky-flashfake-removal-tool-01-700x472-600x404.jpg\" alt=\"kaspersky-flashfake-removal-tool\" width=\"480\" height=\"323\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2006\/04\/kaspersky-flashfake-removal-tool-01-700x472-600x404.jpg 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2006\/04\/kaspersky-flashfake-removal-tool-01-700x472-120x80.jpg 120w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2006\/04\/kaspersky-flashfake-removal-tool-01-700x472-290x195.jpg 290w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2006\/04\/kaspersky-flashfake-removal-tool-01-700x472.jpg 700w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Au cas o\u00f9 votre machine serait malheureusement infect\u00e9e par le virus, vous devrez utiliser un logiciel qui se chargera de son <strong>\u00e9limination<\/strong>. Les plus press\u00e9s pourront utiliser <a title=\"Kaspersky Flashfake Removal Tool\" href=\"http:\/\/kaspersky-flashfake-removal-tool.softonic.fr\/mac\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Kaspersky Flashfake Removal Tool<\/strong> <\/a>, un outil tout en un qui se chargera de <strong>chercher et d\u2019\u00e9liminer le Virus Flashback<\/strong>. Vous pourrez \u00e9galement utiliser <strong>F-Secure <a title=\"F-Secure Flashback Removal Tool\" href=\"http:\/\/f-secure-flashback-removal-tool.softonic.fr\/mac\" target=\"_blank\" rel=\"noopener noreferrer\">Flashback Removal Tool<\/a><\/strong>, un petit logiciel simple d\u2019utilisation qui supprimera simplement le virus.<\/p>\n<h3><strong>Comment vacciner mon ordinateur ?<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-25135\" title=\"Mise \u00e0 jour Apple\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2006\/04\/HT1338_4-fr.png\" alt=\"Mise \u00e0 jour Apple\" width=\"314\" height=\"152\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2006\/04\/HT1338_4-fr.png 314w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2006\/04\/HT1338_4-fr-290x140.png 290w\" sizes=\"auto, (max-width: 314px) 100vw, 314px\" \/>Que votre Mac soit infect\u00e9 ou non, nous vous conseillons vivement d\u2019appliquer la <strong>mise \u00e0 jour de Java<\/strong> \u00e9dit\u00e9e par Apple afin de <strong>prot\u00e9ger les ordinateurs de futures failles de s\u00e9curit\u00e9s.<\/strong> Cliquez sur l\u2019ic\u00f4ne Apple en haut \u00e0 gauche de votre \u00e9cran puis cliquez sur <a title=\"Mise \u00e0 jour de logiciel Apple\" href=\"http:\/\/support.apple.com\/kb\/HT1338?viewlocale=fr_FR\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Mise \u00e0 jour de logiciels.<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>La solution officielle d&#8217;Apple<\/strong><a rel=\"attachment wp-att-25243\" href=\"http:\/\/onsoftware.softonic.fr\/virus-flashback-comment-desinfecter-votre-mac\/image-01-700x509\/\"><strong> <\/strong><\/a><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-25243\" title=\"image-01-700x509\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/04\/image-01-700x509-290x210.png\" alt=\"\" width=\"203\" height=\"147\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2012\/04\/image-01-700x509-290x210.png 290w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2012\/04\/image-01-700x509-600x436.png 600w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2012\/04\/image-01-700x509.png 700w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/strong><\/h3>\n<p><strong><a title=\"Apple Flashback Malware Removal Tool\" href=\"http:\/\/apple-flashback-malware-removal-tool.softonic.fr\/mac\">Apple Flashback Malware Removal Tool<\/a> est la solution officielle propos\u00e9e par Apple afin de d\u00e9tecter et<\/strong><a rel=\"attachment wp-att-25243\" href=\"http:\/\/onsoftware.softonic.fr\/virus-flashback-comment-desinfecter-votre-mac\/image-01-700x509\/\"><strong> <\/strong><\/a><strong> d&#8217;\u00e9liminer le virus Flashback de votre Mac. <\/strong>Apple Flashback Malware Removal Tool supprime les variantes les plus communes du virus Flashback. Si Flashback est trouv\u00e9, une\u00a0<strong>bo\u00eete de dialogue s&#8217;ouvre<\/strong> pour avertir l&#8217;utilisateur et l&#8217;informer de sa suppression.<\/p>\n<h3><strong>Qu\u2019est-ce que je risque ?<\/strong><\/h3>\n<p><strong>Pas de panique !<\/strong> D\u2019apr\u00e8s les premiers retours, <strong>aucune utilisation frauduleuse <\/strong>de donn\u00e9es personnelles en provenance d\u2019ordinateurs infect\u00e9s n\u2019a \u00e9t\u00e9 signal\u00e9e et la plateforme <strong>Mac OSX reste malgr\u00e9 tout plus s\u00fbre que Windows\u2026<\/strong> n\u2019en d\u00e9plaise aux possesseurs de PC !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Virus Flashback est un logiciel malveillant de type cheval de Troie qui cible la plateforme Mac OSX et qui aurait infect\u00e9 plus d\u2019un demi-million d\u2019ordinateurs sur la plan\u00e8te. D\u00e9couvrez la marche \u00e0 suivre pour prot\u00e9ger votre machine. M\u00e0j : Apple a publi\u00e9 une solution officielle pour supprimer ou \u00e9viter le virus Flashback<\/p>\n","protected":false},"author":8021,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[16774,1],"tags":[3182,3165,3169,3170,3167,3166,3183,61,3171,3168,3172],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-25124","post","type-post","status-publish","format-standard","hentry","category-how-to","category-uncategorized","tag-apple-flashback-malware-removal-tool","tag-cheval-de-troie","tag-cheval-de-troie-flash-back","tag-desinfecter-mac","tag-flash-back","tag-flashback","tag-trojan","tag-virus","tag-virus-apple","tag-virus-flash-back","tag-virus-mac"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/25124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8021"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=25124"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/25124\/revisions"}],"predecessor-version":[{"id":168046,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/25124\/revisions\/168046"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=25124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=25124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=25124"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=25124"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=25124"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=25124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}