{"id":33495,"date":"2012-10-26T18:00:20","date_gmt":"2012-10-26T16:00:20","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=33495"},"modified":"2025-06-12T13:10:20","modified_gmt":"2025-06-12T12:10:20","slug":"top-10-applications-windows-8","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/top-10-applications-windows-8\/","title":{"rendered":"10 applications pour Windows 8 \u00e0 installer d\u00e8s maintenant"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-34160\" title=\"Windows Store\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/windows-store-logo-121002.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Windows 8 est arriv\u00e9! Pour la grande majorit\u00e9 des utilisateurs Windows, le <strong>Windows Store<\/strong> reste cependant une v\u00e9ritable curiosit\u00e9. En effet, il s\u2019agit du premier magasin d\u2019applications officiel d\u00e9di\u00e9 au syst\u00e8me d\u2019exploitation de Microsoft.<\/p>\n<p>Jeux, r\u00e9seaux sociaux, photographie: pour vous aider \u00e0 faire votre s\u00e9lection d&#8217;applications dans le Windows Store,  nous avons concoct\u00e9 pour vous un <strong>top 10 des applications pour Windows 8 \u00e0 ne pas manquer<\/strong>.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/fresh-paint-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33502\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Fresh Paint\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/fresh-paint.jpg\" alt=\"\" width=\"120\" height=\"120\" \/>Fresh Paint<\/a><\/h3>\n<p>Fresh Paint est la meilleure application de dessin pour Windows, une v\u00e9ritable ardoise num\u00e9rique haute en couleurs. Ici, pas de formes \u00e0 appliquer, ni d&#8217;outil texte mais de simples pinceaux et une palette de couleurs. L&#8217;application id\u00e9ale pour faire ses premiers dessins et apprendre \u00e0 peindre.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/music-maker-jam-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33503\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Music Maker Jam\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/music-maker-jam.png\" alt=\"\" width=\"120\" height=\"120\" \/>Music Maker Jam<\/a><\/h3>\n<p>Music Maker Jam est une application pour composer de la musique tout en s\u2019amusant. Beaucoup plus accessible que les logiciels de cr\u00e9ation musicale professionnels, Music Maker Jam vous laisse au choix 3 styles musicaux et un total de 8 pistes avec lesquelles s\u2019amuser. Un vrai r\u00e9gal, d&#8217;autant que le rendu sonore est excellent.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/skype-pour-windows-8.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34169\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Skype pour Windows 8\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/skype-pour-windows-8.png\" alt=\"\" width=\"120\" height=\"120\" \/>Skype<\/a><\/h3>\n<p>Appeler ses amis, les voir en direct par webcam interpos\u00e9e, \u00e9changer des fichiers et partager son bureau: la version de Skype pour Windows 8 int\u00e8gre toutes les fonctionnalit\u00e9s que nous connaissons d\u00e9j\u00e0 \u00e0 l&#8217;exception de certaines tel que le &#8220;side-byside&#8221;. Celle-ci permet de partager le bureau de Windows 8 en deux et ainsi de discuter avec vos amis d&#8217;un c\u00f4t\u00e9 et de travailler sur d&#8217;autres t\u00e2ches de l&#8217;autre.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/metrotwit-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33504\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Metro Twit\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/metro-twit.jpg\" alt=\"\" width=\"120\" height=\"120\" \/>Metro Twit<\/a><\/h3>\n<p>Attirant et bien pr\u00e9sent\u00e9, Metro Twit est un excellent client Twitter pour Windows 8. Cette application vise \u00e0 vous offrir toutes les fonctionnalit\u00e9s de Twitter en dehors de votre navigateur. Et il faut avouer que Metro Twit a r\u00e9ussi avec succ\u00e8s le passage de la web app \u00e0 l\u2019application de bureau. On regrette cependant la non prise en charge de la gestion multi-comptes.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/cut-the-rope-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33505\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Cut The Rope\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/cut-the-rope.png\" alt=\"\" width=\"120\" height=\"120\" \/>Cut the Rope<\/a><\/h3>\n<p>Cut the Rope est un petit jeu tr\u00e8s simple: une b\u00e9b\u00eate enferm\u00e9e dans une bo\u00eete, \u00e0 laquelle vous devez faire parvenir un bonbon suspendu au bout d&#8217;une corde. Il faut couper la corde au bon moment. Sa version pour Windows 8 permet de jouer soit \u00e0 la souris soit \u00e0 l&#8217;aide de commandes tactiles.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/youcam-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33506\" style=\"margin-left: 00px;margin-right: 10px\" title=\"YouCam\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/20120304-youcam-metro-app-01.jpg\" alt=\"\" width=\"120\" height=\"120\" \/>YouCam<\/a><\/h3>\n<p>YouCam est une application photo et vid\u00e9o qui utilise le ou les appareils photos num\u00e9riques de votre machine. Elle se lance en clin d\u2019\u0153il et dispose de toute une ribambelle d\u2019effets avec lesquels s\u2019amuser: cadres, effets photo et vid\u00e9o, filtres de distorsion, etc. Bien que ses effets soient quelque peu fantaisistes, sa facilit\u00e9 d\u2019utilisation et son interface r\u00e9ussie en font une application recommandable.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/ebay-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33514\" style=\"margin-left: 00px;margin-right: 10px\" title=\"eBay\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/ebay-logo.png\" alt=\"\" width=\"120\" height=\"120\" \/>eBay<\/a><\/h3>\n<p>Le plus c\u00e9l\u00e8bre site de vente aux ench\u00e8res sur Internet propose son application pour Windows 8. Pratique pour d\u00e9nicher les bonnes affaires et suivre l\u2019\u00e9volution de vos ench\u00e8res, l\u2019application eBay pour Windows 8 est dot\u00e9e d\u2019une interface color\u00e9e qui charge les produits en un \u00e9clair!<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/wikipedia-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33516\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Wikip\u00e9dia\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/wikipedia.png\" alt=\"\" width=\"120\" height=\"120\" \/>Wikip\u00e9dia<\/a><\/h3>\n<p>L&#8217;encyclop\u00e9die en ligne la plus populaire dispose aussi de son application pour Windows 8. Wikip\u00e9dia permet de retrouver tous les contenus publi\u00e9s sur le site directement sur votre bureau. L&#8217;application ne propose rien de tr\u00e8s nouveau mais la navigation tactile entre les articles est tr\u00e8s agr\u00e9able et fluide. Une application pour Windows 8 \u00e0 installer les yeux ferm\u00e9s!<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/pinball-fx2-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33518\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Pinball FX2\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/pinball-fx2.png\" alt=\"\" width=\"120\" height=\"120\" \/>Pinball FX2<\/a><\/h3>\n<p>D\u00e9j\u00e0 disponible sur Xbox Live, Pinball FX2 l\u2019est d\u00e9sormais aussi sur Windows 8. La version d\u00e9mo ne propose qu\u2019une table de jeu (the Sorcerer&#8217;s Lair), suffisante cependant pour appr\u00e9cier l\u2019un des meilleurs jeu de flipper. Avec de bons graphismes et une bande son de qualit\u00e9, voici sans aucun doute un must pour les joueurs sur Windows 8.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"http:\/\/marmiton-metro.softonic.fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33519\" style=\"margin-left: 00px;margin-right: 10px\" title=\"Marmiton\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2012\/10\/marmiton.png\" alt=\"\" width=\"120\" height=\"120\" \/>Marmiton<\/a><\/h3>\n<p>Marmiton fait presque aussi bien que les applications d\u00e9di\u00e9es aux smartphones. Marmiton pour Windows 8 vous offre l&#8217;ensemble des recettes propos\u00e9es par le site du m\u00eame nom sur un plateau d&#8217;argent. D&#8217;ores et d\u00e9j\u00e0 stable et toujours aussi fonctionnelle, voici une application pour Windows 8 \u00e0 consommer sans mod\u00e9ration!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong><em>Vous avez install\u00e9 d\u2019autres applications sur votre PC ou tablette sous Windows 8? En connaissez-vous certaines que vous auriez ajout\u00e9 \u00e0 notre top 10?<\/em><\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Windows 8 est arriv\u00e9! Pour la grande majorit\u00e9 des utilisateurs Windows, le Windows Store reste cependant une v\u00e9ritable curiosit\u00e9. En effet, il s\u2019agit du premier magasin d\u2019applications officiel d\u00e9di\u00e9 au syst\u00e8me d\u2019exploitation de Microsoft. Jeux, r\u00e9seaux sociaux, photographie: pour vous aider \u00e0 faire votre s\u00e9lection d&#8217;applications dans le Windows Store, nous avons concoct\u00e9 pour vous &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/fr\/top-10-applications-windows-8\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;10 applications pour Windows 8 \u00e0 installer d\u00e8s maintenant&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8019,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[16795,4258,4259,3223,3891,2507,4260,4265,4262,4261,4264,240,777,3841,4254,4255,4256,4257,2276,4263],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-33495","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-app-subdomain-redirectionwindows-8","tag-application-metro","tag-application-windows-8","tag-applications-windows-8","tag-cut-the-rope","tag-ebay","tag-fresh-paint","tag-marmiton","tag-metro-twit","tag-music-maker-jam","tag-pinball-fx2","tag-softonic","tag-top","tag-top-10","tag-top-10-windows","tag-top-10-windows-8","tag-top-applications-windows","tag-top-applications-windows-8","tag-wikipedia","tag-youcam"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/33495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8019"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=33495"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/33495\/revisions"}],"predecessor-version":[{"id":167789,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/33495\/revisions\/167789"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=33495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=33495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=33495"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=33495"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=33495"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=33495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}