{"id":40887,"date":"2013-02-27T17:31:20","date_gmt":"2013-02-27T16:31:20","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=40887"},"modified":"2025-06-12T13:02:09","modified_gmt":"2025-06-12T12:02:09","slug":"2013-02-27-kindle-pour-iphone-la-mise-a-jour-3-6-efface-par-erreur-toute-votre-librairie","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/2013-02-27-kindle-pour-iphone-la-mise-a-jour-3-6-efface-par-erreur-toute-votre-librairie\/","title":{"rendered":"Kindle pour iPhone: la mise \u00e0 jour 3.6 efface par erreur toute votre librairie!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-40890\" title=\"kindle-logo\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2013\/02\/kindle-logo.png\" alt=\"\" width=\"124\" height=\"125\" \/><strong>Amazon<\/strong> a publi\u00e9 une mise \u00e0 jour bugg\u00e9e de son application<strong> Kindle pour iOS<\/strong> (iPhone, iPad et iPod touch). Celle-ci efface en effet toutes les donn\u00e9es de la biblioth\u00e8que de l&#8217;utilisateur. Un probl\u00e8me \u00e9pineux pour Amazon qui doit vite r\u00e9agir.<\/p>\n<p>Les utilisateurs de l&#8217;application Kindle pour iOS doivent donc redouter de prudence et \u00e9viter de mettre \u00e0 jour leur application (version 3.6.) sous peine d&#8217;\u00eatre affect\u00e9 par le probl\u00e8me \u00e9galement. Les utilisateurs touch\u00e9s l&#8217;ont d\u00e9j\u00e0 fait vivement savoir \u00e0 travers les commentaires et les notes sur l&#8217;application dans l&#8217;App Store.<!--more--><\/p>\n<p>Pour l&#8217;instant, la meilleure solution est d&#8217;attendre qu&#8217;Amazon clarifie la question et publie une une mise \u00e0 jour stable de son application Kindle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amazon a publi\u00e9 une mise \u00e0 jour bugg\u00e9e de son application Kindle pour iOS (iPhone, iPad et iPod touch). Celle-ci efface en effet toutes les donn\u00e9es de la biblioth\u00e8que de l&#8217;utilisateur. Un probl\u00e8me \u00e9pineux pour Amazon qui doit vite r\u00e9agir. Les utilisateurs de l&#8217;application Kindle pour iOS doivent donc redouter de prudence et \u00e9viter de &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/fr\/2013-02-27-kindle-pour-iphone-la-mise-a-jour-3-6-efface-par-erreur-toute-votre-librairie\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Kindle pour iPhone: la mise \u00e0 jour 3.6 efface par erreur toute votre librairie!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8020,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[16774,1],"tags":[863,5833,5832],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-40887","post","type-post","status-publish","format-standard","hentry","category-how-to","category-uncategorized","tag-kindle","tag-kindle-ios","tag-kindle-iphone"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/40887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8020"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=40887"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/40887\/revisions"}],"predecessor-version":[{"id":167398,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/40887\/revisions\/167398"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=40887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=40887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=40887"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=40887"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=40887"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=40887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}