{"id":93118,"date":"2014-07-02T17:30:36","date_gmt":"2014-07-02T15:30:36","guid":{"rendered":"http:\/\/onsoftware.softonic.fr\/?p=93118"},"modified":"2025-06-12T11:52:33","modified_gmt":"2025-06-12T10:52:33","slug":"batterie-android-l","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/fr\/batterie-android-l\/","title":{"rendered":"Jusqu&#8217;\u00e0 36% d&#8217;autonomie en plus avec Android L"},"content":{"rendered":"<p>Il semble que la nouvelle version d&#8217;Android pourrait am\u00e9liorer consid\u00e9rablemen<strong>t la vie de la batterie <\/strong>des terminaux. Google vise notamment \u00e0 am\u00e9liorer cet aspect \u00e0 travers le <strong>projet Volta<\/strong>, qui a \u00e9t\u00e9 pr\u00e9sent\u00e9 lors de la conf\u00e9rence Google I\/O.<\/p>\n<p>Volta r\u00e9duit ainsi le temps que l&#8217;appareil passe pour effectuer des op\u00e9rations de maintenance en arri\u00e8re-plan. Google a optimis\u00e9 ses applications, mais les d\u00e9veloppeurs devront \u00e9galement faire leur part pour adapter leurs applications \u00e0 la nouvelle norme. Ainsi, vous pouvez atteindre <strong>une \u00e9conomie jusqu&#8217;\u00e0 36% de la batterie<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-93127\" title=\"Battery-Saver\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/9\/2014\/07\/Battery-Saver-568x319.jpg\" alt=\"\" width=\"568\" height=\"319\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/07\/Battery-Saver.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/07\/Battery-Saver-268x150.jpg 268w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/07\/Battery-Saver-300x169.jpg 300w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/9\/2014\/07\/Battery-Saver-238x134.jpg 238w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>Google a \u00e9galement ajout\u00e9 <strong>un mode visant \u00e0 \u00e9conomiser la batterie<\/strong> qui d\u00e9sactive les services non essentiels.<\/p>\n<p>Enfin, Volta contribue \u00e9galement \u00e0 am\u00e9liorer l&#8217;exp\u00e9rience globale en utilisant le nouveau <strong>runtime ART<\/strong> plus efficace et plus performant. \u00c9tant donn\u00e9 que L n&#8217;est qu&#8217;une b\u00eata Android pour le moment, l&#8217;am\u00e9lioration pourrait \u00eatre encore plus \u00e9lev\u00e9e.<\/p>\n<p><em>Source:\u00a0<a href=\"http:\/\/arstechnica.com\/gadgets\/2014\/07\/examining-project-volta-we-put-android-l-through-our-battery-test\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ars Technica<\/a><\/em><\/p>\n<p><strong>A lire:<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/actualites.softonic.fr\/youtube-android-permet-lire-films-achetes-google-play\">YouTube pour Android permet de lire les films achet\u00e9s sur Google Play<\/a><\/li>\n<li><a href=\"http:\/\/actualites.softonic.fr\/youtube-prend-soin-createurs-videos-nouveaux-outils\">YouTube prend soin de ses cr\u00e9ateurs de vid\u00e9os avec de nouveaux outils<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"http:\/\/actualites.softonic.fr\/google-achete-songza-rivaliser-beats-spotify\">Google ach\u00e8te Songza pour rivaliser avec Beats et Spotify<\/a><\/li>\n<\/ul>\n<p><em>Suivez-moi sur Twitter:<a href=\"https:\/\/twitter.com\/pierrevitre\" target=\"_blank\" rel=\"noopener noreferrer\"> @pierrevitre<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il semble que la nouvelle version d&#8217;Android pourrait am\u00e9liorer consid\u00e9rablement la vie de la batterie des terminaux. Google vise notamment \u00e0 am\u00e9liorer cet aspect \u00e0 travers le projet Volta, qui a \u00e9t\u00e9 pr\u00e9sent\u00e9 lors de la conf\u00e9rence Google I\/O. Volta r\u00e9duit ainsi le temps que l&#8217;appareil passe pour effectuer des op\u00e9rations de maintenance en arri\u00e8re-plan. &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/fr\/batterie-android-l\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Jusqu&#8217;\u00e0 36% d&#8217;autonomie en plus avec Android L&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8020,"featured_media":93119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[33,12209],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-93118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-android","tag-android-l"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/93118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/users\/8020"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/comments?post=93118"}],"version-history":[{"count":1,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/93118\/revisions"}],"predecessor-version":[{"id":163826,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/posts\/93118\/revisions\/163826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media\/93119"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/media?parent=93118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/categories?post=93118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/tags?post=93118"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/usertag?post=93118"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/vertical?post=93118"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/fr\/wp-json\/wp\/v2\/content-category?post=93118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}