{"id":12920,"date":"2012-06-05T09:56:09","date_gmt":"2012-06-05T09:56:09","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=12920"},"modified":"2024-03-08T13:21:06","modified_gmt":"2024-03-08T12:21:06","slug":"cerca-contatti-skype","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/cerca-contatti-skype\/","title":{"rendered":"Come cercare contatti su Skype"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12937\" title=\"skype-contacts\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2012\/06\/skype-contacts.png\" alt=\"\" width=\"150\" height=\"150\" \/>Hai conosciuto un nuovo amico lo scorso fine settimana, ma ti sei dimenticato di chiedergli il suo contatto Skype! E ora? Come lo chiami?<\/p>\n<p>Niente panico! Ci sono possibilit\u00e0 di ritrovarlo, ma devi conoscere almeno una di queste informazioni: il suo nome e cognome, il suo indirizzo email, dove vive. Vediamo <strong>come fare a cercare una persona su Skype<\/strong>, passo passo, in questo semplice tutorial.<\/p>\n<p><!--more--><\/p>\n<address style=\"width: 270px;float: right;margin-left: 15px;background-color: #87cefa\">\n<h2>Altri post su Skype<\/h2>\n<p><strong><a title=\"Non vedi, non senti e non parli? Migliora la qualit\u00e0 delle tue chiamate via Skype\" href=\"http:\/\/onsoftware.softonic.it\/come-migliorare-qualita-chiamate-skype\" target=\"_self\" rel=\"noopener noreferrer\">Migliora la qualit\u00e0 delle tue chiamate via Skype<\/a><\/strong><\/p>\n<p><strong><a title=\"Registrare le chiamate via Skype con PrettyMay\" href=\"http:\/\/onsoftware.softonic.it\/registrare-chiamate-skype\" target=\"_self\" rel=\"noopener noreferrer\">Registrare le chiamate via Skype con PrettyMay<\/a><\/strong><\/p>\n<p><strong><a title=\"Guida base per imparare a usare il PC \u2013 episodio 9: Come usare Skype per telefonare gratis\" href=\"http:\/\/onsoftware.softonic.it\/guida-skype\" target=\"_self\" rel=\"noopener noreferrer\">Come usare Skype per telefonare gratis<\/a><\/strong><\/p>\n<\/address>\n<p><strong>Se conosci il suo nome e cognome o il suo indirizzo email <\/strong>\u00e8 facilissimo: basta aprire l&#8217;<a title=\"Scarica e installa Skype\" href=\"http:\/\/skype.softonic.it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>ultima versione di Skype<\/strong><\/a> e cliccare sul menu <strong>Contatti\/Aggiungi un contatto<\/strong>. Digita i dati della persona che stai cercando e clicca su <strong>Cerca<\/strong>. Se il tuo nuovo amico ha Skype (e se non usa uno pseudonimo), il suo nome comparir\u00e0 nella lista che si aprir\u00e0 cliccando su <strong>Visualizza<\/strong>. Baster\u00e0 cliccare sul pulsantino <strong>Aggiungi contatto <\/strong>per chiedergli il permesso di vedere quando \u00e8 online e chiamarlo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12936\" title=\"cerca-utenti-skype-0\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-0.jpg\" alt=\"\" width=\"700\" height=\"418\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-0.jpg 700w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-0-300x179.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><strong>Se conosci solo la citt\u00e0 dove vive il tuo nuovo amico e il suo nome<\/strong> (ma non il cognome), la situazione si fa un po&#8217; pi\u00f9 complicata, ma non impossibile. Le ultime versioni di Skype non ti permettono di cercare contatti inserendo solo la citt\u00e0, ma <strong>Skype 3.0<\/strong> te lo permetteva ed \u00e8 ancora possibile scaricarlo. Segui dunque questa procedura:<\/p>\n<p>1. Per prima cosa, <strong>fai un backup dei tuoi contatti <\/strong>per evitare brutte sorprese (installando una vecchia versione di Skype a volte sparisce tutta la lista contatti!). Clicca su <strong>Contatti\/Avanzate\/Esporta contatti in un file<\/strong> e salvalo dove vuoi.<\/p>\n<p>2. Ora disinstalla Skype dal tuo computer.<\/p>\n<p>3. Scarica e installa la <a title=\"Scarica e installa Skype 3.0\" href=\"http:\/\/skype.softonic.it\/download-versione\/skype-3.0.0.190\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>vecchia versione di Skype 3.0<\/strong><\/a><\/p>\n<p>4. Avvia Skype e accedi con i tuoi dati.<\/p>\n<p>5. Clicca sul menu <strong>Contatti\/Cerca utenti Skype<\/strong> e alla voce <strong>Citt\u00e0 <\/strong>scrivi dove vive la persona che stai cercando. Per esempio, mettiamo che ricordi che il tuo nuovo amico si chiama Marco e che \u00e8 di Milano. In questo caso ecco cosa scriverai nell&#8217;interfaccia di Skype:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12924\" title=\"cerca-utenti-skype-2\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-2.jpg\" alt=\"\" width=\"661\" height=\"565\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-2.jpg 661w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-2-300x256.jpg 300w\" sizes=\"auto, (max-width: 661px) 100vw, 661px\" \/><\/p>\n<p>Puoi anche aggiungere altri dettagli per restringere la ricerca: alla voce Intervallo di puoi aggiungere la fascia di et\u00e0, per esempio.<\/p>\n<p>6. A questo punto non resta che cliccare su <strong>Cerca <\/strong>e incrociare le dita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12926\" title=\"cerca-utenti-skype-3\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-3.jpg\" alt=\"\" width=\"694\" height=\"565\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-3.jpg 694w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2012\/06\/cerca-utenti-skype-3-300x244.jpg 300w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/p>\n<p>La lista proposta in questo caso \u00e8 abbastanza lunga: 113 risultati. Adesso tocca a te andare per esclusione, visualizzando i profili e spremendoti le meningi per ricordare i dettagli e i particolari che ti condurranno alla persona giusta. Buona fortuna!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hai conosciuto un nuovo amico lo scorso fine settimana, ma ti sei dimenticato di chiedergli il suo contatto Skype! E ora? Come lo chiami? Niente panico! Ci sono possibilit\u00e0 di ritrovarlo, ma devi conoscere almeno una di queste informazioni: il suo nome e cognome, il suo indirizzo email, dove vive. Vediamo come fare a cercare &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/it\/cerca-contatti-skype\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Come cercare contatti su Skype&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3001,"featured_media":12937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[2487,1],"tags":[2495],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-12920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","category-uncategorized","tag-app-subdomain-redirectionskype"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/12920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3001"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=12920"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/12920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media\/12937"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=12920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=12920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=12920"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=12920"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=12920"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=12920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}