{"id":25457,"date":"2013-04-09T15:49:01","date_gmt":"2013-04-09T15:49:01","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=25457"},"modified":"2024-03-08T01:57:13","modified_gmt":"2024-03-08T00:57:13","slug":"google-play-per-android-nuovo-look","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/google-play-per-android-nuovo-look\/","title":{"rendered":"Google Play per Android: nuovo look e pi\u00f9 importanza ai contenuti"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" width=\"462\" height=\"317\" class=\"aligncenter size-full wp-image-25458\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2013\/04\/new-google-play.jpg\" alt=\"new google play\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2013\/04\/new-google-play.jpg 462w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2013\/04\/new-google-play-300x205.jpg 300w\" sizes=\"auto, (max-width: 462px) 100vw, 462px\" \/><\/p>\n<p>Google Play cambia faccia. <strong>Lo store di Google rinnova il suo look su cellulari e tablet Android<\/strong>. Confermate quindi le <a title=\"Google Play cambia faccia: filtrate le immagini in rete\" href=\"http:\/\/onsoftware.softonic.it\/google-play-redesign-screenshot\">indiscrezioni<\/a> riportate ieri.<\/p>\n<p>L&#8217;annuncio \u00e8 stato dato sul<a href=\"http:\/\/officialandroid.blogspot.jp\/2013\/04\/a-fresh-new-look-for-google-play.html\" target=\"_blank\" rel=\"noopener noreferrer\"> blog ufficiale del team Android<\/a>. <strong>Il redesign \u00e8 disponibile a partire da oggi su dispositivi Android 2.2 (Froyo) e superiori<\/strong>. Il roll out sar\u00e0 graduale e avverr\u00e0 nel corso delle prossime settimane.<\/p>\n<h4><!--more--><\/h4>\n<p><strong>Il nuovo design del Google Play d\u00e0 maggior rilievo alle immagini, pi\u00f9 grandi e pi\u00f9 dettagliate<\/strong>.<\/p>\n<p>I contenuti simili sono ora raggruppati insieme e la sezione Consigliati per te \u00e8 pi\u00f9 visibile e continua ad apparire durante la navigazione nel Play. Semplificato anche il processo di acquisto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-25460\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2013\/04\/Play-Books-Home-Tablet--e1365522342488.png\" alt=\"new google play\" width=\"600\" height=\"432\" \/><\/p>\n<p>Il nuovo design d\u00e0 enfasi a tutti i contenuti, libri, film, musica&#8230; non solo alle app.<\/p>\n<p>Android punta in alto, evidentemente, e ora il robottino verde guarda alla luna, non al dito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google Play cambia faccia. Lo store di Google rinnova il suo look su cellulari e tablet Android. Confermate quindi le indiscrezioni riportate ieri. L&#8217;annuncio \u00e8 stato dato sul blog ufficiale del team Android. Il redesign \u00e8 disponibile a partire da oggi su dispositivi Android 2.2 (Froyo) e superiori. Il roll out sar\u00e0 graduale e avverr\u00e0 &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/it\/google-play-per-android-nuovo-look\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Google Play per Android: nuovo look e pi\u00f9 importanza ai contenuti&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3002,"featured_media":25458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-25457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/25457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3002"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=25457"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/25457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media\/25458"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=25457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=25457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=25457"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=25457"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=25457"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=25457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}