{"id":27454,"date":"2013-05-09T09:22:35","date_gmt":"2013-05-09T09:22:35","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=27454"},"modified":"2024-03-08T01:54:55","modified_gmt":"2024-03-08T00:54:55","slug":"google-earth-google-translate-android-aggiornamento","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/google-earth-google-translate-android-aggiornamento\/","title":{"rendered":"Google Earth e Google Translate per Android si aggiornano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27460\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2013\/05\/earth-+-translate.png\" alt=\"earth + translate\" width=\"292\" height=\"124\" \/><\/p>\n<p><strong>Google Earth e Google Traduttore, due tra le principali app Google per Android, ricevono aggiornamenti importanti<\/strong>.<\/p>\n<p><a href=\"http:\/\/google-earth.softonic.it\/android\" target=\"_self\" rel=\"noopener noreferrer\">Google Earth<\/a> introduce il tanto atteso supporto a Street View e <a href=\"http:\/\/google-translate.softonic.it\/android\" target=\"_self\" rel=\"noopener noreferrer\">Google Translate<\/a> permette ora di salvare le traduzioni preferite e sincronizzarle tra diversi dispositivi.<\/p>\n<p>Vediamo gli aggiornamenti pi\u00f9 nel dettaglio.<\/p>\n<h4><!--more--><\/h4>\n<h3>Google Earth<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27463\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2013\/05\/Screenshot_2013-05-09-10-51-12-e1368089796409.png\" alt=\"street view\" width=\"600\" height=\"360\" \/><\/p>\n<p>Google Earth per Android si aggiorna alla<strong> versione 7.1.1 e introduce\u00a0la Street View<\/strong>. Ora &#8220;Pegman&#8221; (il celebre omino arancione che simboleggia Street View)  pu\u00f2 spostarsi dalla galassia alla piazza dietro casa tua nel giro di un  tap sullo schermo.<\/p>\n<p>Per attivare la modalit\u00e0 Street View baster\u00e0 trascinare Pegman nel punto della mappa che ci interessa, proprio come nella versione web di <a href=\"http:\/\/google-maps.softonic.it\/applicazioni-web\" target=\"_self\" rel=\"noopener noreferrer\">Google Maps<\/a><\/p>\n<p><strong>Migliorata anche l&#8217;interfaccia.<\/strong> Con un tap in alto a sinistra sul logo di Google Earth si possono attivare funzioni aggiuntive, come le informazioni di Wikipedia o le foto di Panoramio.<\/p>\n<p>L&#8217;update ottimizza anche le indicazioni stradali e di ricerca: indicazioni per i mezzi pubblici e per percorsi in bicicletta, a piedi e in auto in 3D.<\/p>\n<h3>Google Traduttore<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27464\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2013\/05\/Screenshot_2013-05-09-10-53-14-e1368090109926.png\" alt=\"google traduttore android\" width=\"600\" height=\"360\" \/><\/p>\n<p>Google Translate introduce invece la possibilit\u00e0 di <strong>salvare e sincronizzare le proprie traduzioni su diversi dispositivi<\/strong>, per esempio dall&#8217;Android al PC. Per utilizzare la funzione bisogna accedere all&#8217;app con il proprio account Google.<\/p>\n<p>Leggi anche:<\/p>\n<h2><a title=\"Il mondo in 3D. Google Earth si aggiorna su Windows e Mac\" href=\"http:\/\/onsoftware.softonic.it\/google-earth-update-2013-01-31\">Il mondo in 3D. Google Earth si aggiorna su Windows e Mac<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Google Earth e Google Traduttore, due tra le principali app Google per Android, ricevono aggiornamenti importanti. Google Earth introduce il tanto atteso supporto a Street View e Google Translate permette ora di salvare le traduzioni preferite e sincronizzarle tra diversi dispositivi. Vediamo gli aggiornamenti pi\u00f9 nel dettaglio.<\/p>\n","protected":false},"author":3002,"featured_media":27460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[2529,124,739],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-27454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-app-subdomain-redirectiongoogle-earth","tag-google-earth","tag-google-traduttore"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/27454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3002"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=27454"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/27454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media\/27460"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=27454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=27454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=27454"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=27454"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=27454"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=27454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}