{"id":3889,"date":"2011-06-30T13:58:32","date_gmt":"2011-06-30T13:58:32","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=3889"},"modified":"2024-03-08T02:14:13","modified_gmt":"2024-03-08T01:14:13","slug":"3-anni-softonic-italia","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/3-anni-softonic-italia\/","title":{"rendered":"\u00c8 il nostro terzo compleanno!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3890\" title=\"auguri-softonic\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2011\/06\/auguri-softonic.jpg\" alt=\"E auguri anche a te!\" width=\"420\" height=\"279\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2011\/06\/auguri-softonic.jpg 849w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2011\/06\/auguri-softonic-120x80.jpg 120w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2011\/06\/auguri-softonic-300x199.jpg 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/p>\n<p><strong>30 giugno 2008<\/strong>: <strong><a href=\"http:\/\/www.softonic.it\">www.softonic.it<\/a><\/strong> compare online per la prima volta.<\/p>\n<p>E anche se stentiamo a crederci, il calendario ci informa che sono gi\u00e0 passati tre anni dal nostro primo download! In 3 anni Softonic Italia \u00e8 cresciuto e\u00a0 cambiato tanto: dal design, alla nostra maniera di scrivere, ai programmi della Top Download, ai componenti della redazione. Siamo passati attraverso un restyling grafico e l&#8217;ingresso su <a title=\"Softonic Italia su Facebook\" href=\"http:\/\/www.facebook.com\/pages\/Softonic-IT\/109280282452864\">Facebook<\/a> e <a title=\"Softonic Italia su Twitter\" href=\"http:\/\/twitter.com\/softonic_it\">Twitter<\/a>, hanno visto la luce il <strong><a title=\"Il blog di Softonic\" href=\"http:\/\/onsoftware.softonic.it\">blog OnSoftware<\/a><\/strong> e la newsletter <em>All about software<\/em>, la nascita della piattaforma <a title=\"Le web app di Softonic\" href=\"http:\/\/www.softonic.it\/applicazioni-web\">web app<\/a> e il boom delle applicazioni per cellulari, la creazione di <a title=\"La versione per cellulari di Softonic\" href=\"http:\/\/m.softonic.it\/\">Softonic Mobile<\/a> e la diffusione dei tutorial in formato video.<\/p>\n<p>Siamo entrati nella Top 100 dei siti pi\u00f9 visitati in Italia e siamo stati premiati per ben 3 volte consecutive come <a title=\"Best Place to Work\" href=\"http:\/\/www.greatplacetowork.it\/best\/list-es-2010.htm\" target=\"_blank\" rel=\"noopener noreferrer\">miglior posto dove lavorare in Spagna<\/a>. In tre anni ne sono cambiate di cose, ma non \u00e8 cambiata la nostra voglia di divertirci con un computer o un cellulare e di condividere con voi le nostre scoperte, nel linguaggio pi\u00f9 semplice possibile, perch\u00e9 tutti possiate capirci, qualunque sia la vostra et\u00e0 e le vostre esigenze con Internet, i cellulari e il computer.<\/p>\n<p>Scriveva Giancarlo Cammarota nel luglio del 2008 nel nostro primo comunicato stampa sul lancio del sito:\u00a0 &#8220;<em>Abbiamo lavorato durante un anno per preparare il sito italiano, e questo ci permette di offrire dal primo giorno pi\u00f9 di 2 mila programmi provati e recensiti per i principali sistemi operativi e dispositivi mobili<\/em>. <em>I\u00a0nostri test sono veri e indipendenti. Speriamo di aiutare i lettori a scoprire e scaricare facilmente le migliori applicazioni per le loro necessit\u00e0&#8221;. <\/em>Ci siamo riusciti? A voi spetta giudicare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3891\" title=\"softonic-compleanno\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2011\/06\/softonic-compleanno.jpg\" alt=\"Com'eravamo\" width=\"601\" height=\"185\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2011\/06\/softonic-compleanno.jpg 880w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2011\/06\/softonic-compleanno-300x92.jpg 300w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/>Adesso, dopo 3 anni, 12 mila programmi, quasi 4 mila recensioni (e altrettanti programmi testati di prima mano!), 146 blog post, migliaia di commenti e di utenti registrati, 4 newsletter e quasi 4 mila fan su Facebook, da parte nostra, possiamo solo ringraziarvi per l&#8217;affetto con cui ci seguite: gli auguri vanno per prima cosa a tutti voi, che vi sentite un poco&#8230; Softonic inside.<\/p>\n<p>E un grazie specialissimo a tutta la redazione, ai nuovi arrivati e a chi ha cambiato strada: a Daniel, Pier Francesco, Laura, Alessandro, Simone e Giancarlo da parte della matita che sta scrivendo questo post.<\/p>\n<p>Buon compleanno a tutti i Softonici! \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>30 giugno 2008: www.softonic.it compare online per la prima volta. E anche se stentiamo a crederci, il calendario ci informa che sono gi\u00e0 passati tre anni dal nostro primo download! In 3 anni Softonic Italia \u00e8 cresciuto e\u00a0 cambiato tanto: dal design, alla nostra maniera di scrivere, ai programmi della Top Download, ai componenti della &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/it\/3-anni-softonic-italia\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;\u00c8 il nostro terzo compleanno!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3001,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-3889","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/3889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3001"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=3889"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/3889\/revisions"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=3889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=3889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=3889"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=3889"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=3889"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=3889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}