{"id":51573,"date":"2014-03-31T09:44:45","date_gmt":"2014-03-31T09:44:45","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=51573"},"modified":"2024-03-08T01:21:55","modified_gmt":"2024-03-08T00:21:55","slug":"alien-isolation-uscita-7-ottobre-xbox-playstation-pc","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/alien-isolation-uscita-7-ottobre-xbox-playstation-pc\/","title":{"rendered":"Alien: Isolation uscir\u00e0 il 7 ottobre su Xbox, PlayStation e PC"},"content":{"rendered":"<p>Creative Assembly ha annunciato che <strong>Alien: Isolation  sar\u00e0 rilasciato il 7 ottobre 2014<\/strong>. A partire dal prossimo autunno, i giocatori potranno vivere la storia di Amanda Ripley, immersi in un&#8217;atmosfera di costante terrore e pericolo mortale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51575\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2014\/03\/alien-isolation-568x369.png\" alt=\"alien isolation\" width=\"568\" height=\"369\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2014\/03\/alien-isolation-568x369.png 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2014\/03\/alien-isolation-256x166.png 256w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2014\/03\/alien-isolation.png 808w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>La data di uscita \u00e8 stata comunicata nel corso di EGX Rezzed 2014, evento dedicato ai videogame che si svolge in questi giorni nel Regno Unito.<br \/>\nAlistair Hope, Creative Lead del gioco, ha dichiarato: &#8220;Abbiamo portato la serie alle radici del film del 1979 di Ridley Scott, il survival horror originale. <strong>Il nostro Alien \u00e8 una creatura realmente terribile<\/strong>, tanto intelligente quanto ostile, spietata, brutale e inarrestabile. Questo \u00e8 il gioco di Alien che i fan della serie hanno sempre voluto&#8221;.<br \/>\n<!-- Start of Brightcove Player --><\/p>\n<div style=\"display:none\">\n<\/div>\n<p><!--\nBy use of this code snippet, I agree to the Brightcove Publisher T and C \nfound at https:\/\/accounts.brightcove.com\/en\/terms-and-conditions\/. \n--><\/p>\n<p><script language=\"JavaScript\" type=\"text\/javascript\" src=\"http:\/\/admin.brightcove.com\/js\/BrightcoveExperiences.js\"><\/script><\/p>\n<p><object id=\"myExperience3412989227001\" class=\"BrightcoveExperience\"><param name=\"bgcolor\" value=\"#FFFFFF\" \/><param name=\"width\" value=\"568\" \/><param name=\"height\" value=\"320\" \/><param name=\"playerID\" value=\"1044271468001\" \/><param name=\"playerKey\" value=\"AQ~~,AAAA1j3vtSk~,6kECJuBTHVVyHn1Zlpb9SHWnGFywN71t\" \/><param name=\"isVid\" value=\"true\" \/><param name=\"isUI\" value=\"true\" \/><param name=\"dynamicStreaming\" value=\"true\" \/><param name=\"@videoPlayer\" value=\"3412989227001\" \/><\/object><\/p>\n<p><!-- \nThis script tag will cause the Brightcove Players defined above it to be created as soon\nas the line is read by the browser. If you wish to have the player instantiated only after\nthe rest of the HTML is processed and the page load is complete, remove the line.\n--><br \/>\n<script type=\"text\/javascript\">brightcove.createExperiences();<\/script><\/p>\n<p><!-- End of Brightcove Player --><\/p>\n<p>Pubblicato da Sega , Alien: Isolation  \u00e8 uno shooter survival horror che ha come protagonista la figlia di Ellen Ripley, Amanda. Il gameplay ci porter\u00e0 in una stazione spaziale abbandonata ai limiti del cosmo. Ingrediente principale: la paura.<\/p>\n<p><em>Via: <a href=\"http:\/\/news.alienisolation.com\/2014\/03\/29\/alien-isolation-available-from-7th-october-2014\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alien: Isolation website<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Creative Assembly ha annunciato che Alien: Isolation sar\u00e0 rilasciato il 7 ottobre 2014. A partire dal prossimo autunno, i giocatori potranno vivere la storia di Amanda Ripley, immersi in un&#8217;atmosfera di costante terrore e pericolo mortale. La data di uscita \u00e8 stata comunicata nel corso di EGX Rezzed 2014, evento dedicato ai videogame che si &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/it\/alien-isolation-uscita-7-ottobre-xbox-playstation-pc\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Alien: Isolation uscir\u00e0 il 7 ottobre su Xbox, PlayStation e PC&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3002,"featured_media":51575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[1252],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-51573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-alien-isolation"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/51573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3002"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=51573"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/51573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media\/51575"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=51573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=51573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=51573"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=51573"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=51573"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=51573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}