{"id":63621,"date":"2014-08-25T19:17:41","date_gmt":"2014-08-25T17:17:41","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=63621"},"modified":"2024-03-08T13:10:39","modified_gmt":"2024-03-08T12:10:39","slug":"app-insegnanti-professori","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/app-insegnanti-professori\/","title":{"rendered":"Rientro a scuola: 16 app per maestri, insegnanti e professori"},"content":{"rendered":"<p>La tecnologia si \u00e8 messa al servizio anche di insegnanti ed educatori. Eccoti delle app che ti faranno da assistente in aula, ti aiuteranno a dare il meglio nei tuoi corsi e ti permetteranno anche di programmare delle lezioni virtuali. Diventa un maestro del XXI secolo!<\/p>\n<p>L&#8217;insegnamento non \u00e8 facile, soprattutto quando gli studenti sono distratti con WhatsApp o Candy Crush. Ma la\u00a0<strong>tecnologia<\/strong> che usano tutti i giorni pu\u00f2 essere il veicolo perfetto per lezioni pi\u00f9 interattive e interessanti.<\/p>\n<p>Le applicazioni che ho scelto per questo elenco sono progettate affinch\u00e9 tu, professore o insegnante, di qualsiasi livello educativo, possa <strong>arricchire<\/strong> i tuoi metodi di insegnamento. Dei programmi validi per quasi tutti i tipi di lezione.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"nearpodicon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/nearpodicon.jpg\" alt=\"\" width=\"100\" height=\"100\" \/>Nearpod, lezioni su tutti i dispositivi<\/h3>\n<p>Immagina di creare una presentazione multimediale, condividerla con i tuoi studenti e che loro possano caricarla sui loro telefoni, indipendentemente dalla marca o modello. \u00c8 possibile farlo grazie a\u00a0Nearpod, un&#8217;applicazione progettata per facilitare l&#8217;e-learning.<\/p>\n<p>Sia il servizio che le app per Android e iPhone sono gratuiti. \u00c8 possibile iscriversi cliccando\u00a0<a title=\"Registrazione\" href=\"http:\/\/www.nearpod.com\/signup\/\" target=\"_blank\" rel=\"noopener noreferrer\">qui<\/a>. E se vai di fretta, invece di creare i materiali, puoi acquistarli presso il negozio ufficiale.<\/p>\n<p><a title=\"Scarica Nearpod per Android\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.panareadigital.Nearpod\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica Nearpod per Android<\/strong><\/a><\/p>\n<p><a title=\"Scarica Nearpod per iOS\" href=\"https:\/\/itunes.apple.com\/us\/app\/nearpod\/id523540409\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica Nearpod per iPhone e iPad<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Nearpod\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/nearpod1.jpg\" alt=\"\" width=\"568\" height=\"266\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"viper\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/viper1.jpg\" alt=\"\" width=\"100\" height=\"100\" \/>Viper, il rilevatore di plagi per Windows<\/h3>\n<p>Quale insegnante non si \u00e8 mai ritrovato dei\u00a0compiti plagiati da Wikipedia? Si tratta di un problema comune. Fortunatamente, ci sono dei rilevatori di plagio potenti, come\u00a0<a title=\"Scarica Viper\" href=\"http:\/\/viper.softonic.it\/\">Viper<\/a> (Windows), che ricerca tra i documenti locali e su Internet.<\/p>\n<p>Per utilizzare Viper devi creare un account gratuito. Una volta nel programma, scegli i documenti da analizzare e Viper confronter\u00e0 il testo e ti dir\u00e0 qual \u00e8 la probabilit\u00e0 che il documento sia stato copiato senza modifiche.<\/p>\n<p><a title=\"Scarica Viper\" href=\"http:\/\/viper.softonic.it\/\" target=\"_self\" rel=\"noopener noreferrer\"><strong>Scarica Viper per Windows<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"viper\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/viper.jpg\" alt=\"\" width=\"568\" height=\"347\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"attendance-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/attendance-icon.jpg\" alt=\"\" width=\"100\" height=\"99\" \/>Attendance, l&#8217;elenco delle presenze sul cellulare<\/h3>\n<p>Un elenco delle presenze cartaceo \u00e8 molto utile, ma con\u00a0<a title=\"Link al Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.aor.attendance\">Attendance<\/a> (Android) potrai tenere il controllo, in modo pi\u00f9 visivo e veloce, di chi si assenta di pi\u00f9 alle tue lezioni. Puoi visualizzare per studenti, gruppi, classi e hai anche una vista generale del calendario.<\/p>\n<p>Lo svantaggio di Attendance\u00a0\u00e8 che devi configurarlo abbastanza all&#8217;inizio: bisogna creare nomi e corsi, cos\u00ec come caricare le foto. Ma una volta pronto, ne vale la pena.<\/p>\n<p><strong><a title=\"Link al Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.aor.attendance\" target=\"_blank\" rel=\"noopener noreferrer\">Scarica Attendance per Android<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Attendance\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/Attendance.jpg\" alt=\"\" width=\"568\" height=\"480\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"toonoisyicon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/toonoisyicon.jpg\" alt=\"\" width=\"100\" height=\"100\" \/>TooNoisy, il rilevatore di\u00a0rumore ambientale con allarme<\/h3>\n<p><a title=\"Pagina ufficiale\" href=\"http:\/\/toonoisyapp.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">TooNoisy<\/a> \u00e8 un divertente rilevatore di rumore per iPhone e Android, che mostra un grafico ed emette un allarme se il rumore supera una soglia di tolleranza. Quando il rumore diventa troppo alto, l&#8217;immagine cambia.<\/p>\n<p>Ovviamente, le conseguenze dipendono dal docente. Se il superamento della soglia di rumore si associa a un&#8217;azione di qualche tipo (ad esempio, rimanere pi\u00f9 a lungo in aula), maggiore \u00e8 la probabilit\u00e0 che gli studenti rispettino il limite.<\/p>\n<p><a title=\"Link al Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.walsallacademy.toonoisylite\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica TooNoisy per Android<\/strong><\/a><\/p>\n<p><strong><a title=\"Link allo store di iTunes\" href=\"https:\/\/itunes.apple.com\/gb\/app\/too-noisy\/id499844023\" target=\"_blank\" rel=\"noopener noreferrer\">Scarica TooNoisy per iPhone e iPad<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"toonoisy\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/toonoisy.jpg\" alt=\"\" width=\"568\" height=\"352\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"thinglink-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/thinglink-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>ThingLink, immagini che dicono pi\u00f9 di mille parole<\/h3>\n<p>Le immagini sono un&#8217;ottima risorsa educativa. Ma possono essere anche meglio quando si aggiungono dei punti interattivi. E&#8217; ci\u00f2 che fa\u00a0<a title=\"Pagina ufficiale\" href=\"http:\/\/www.thinglink.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">ThingLink<\/a>, un&#8217;applicazione che consente di creare immagini interattive.<\/p>\n<p>Thinglink funziona su tutti i browser e l&#8217;iscrizione \u00e8 gratuita. Creare un&#8217;immagine \u00e8 semplice e puoi caricarla dal disco rigido, Flickr o Facebook, per por aggiungere dei\u00a0<strong>punti interattivi<\/strong>.<\/p>\n<p><a title=\"Web app\" href=\"https:\/\/www.thinglink.com\/edu\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Accedi a ThingLink dal browser<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Thinglink\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/thinglink.gif\" alt=\"\" width=\"568\" height=\"487\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"pdfdoc-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/pdfdoc-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>PDF Document Scanner, lo scanner sul tuo telefono<\/h3>\n<p><a title=\"Link al Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.ape.camera.docscan\" target=\"_blank\" rel=\"noopener noreferrer\">PDF Document Scanner<\/a> \u00e8 utile per coloro che non vogliono trasportare chili di carta. Un semplice tocco e i documenti che inquadri con la fotocamera del cellulare saranno salvati come file PDF, pronti per essere inviati al PC.<\/p>\n<p>Tra le altre opzioni, PDF Document Scanner consente di scegliere la dimensione della pagina (A4, Letter, ed altro) e ritagliare la cattura della pagina prima di salvarla come documento finale.<\/p>\n<p><a title=\"Link al Play Store\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.ape.camera.docscan\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica PDF Document Scanner per Android<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"pdfdocscanner\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/pdfdocscanner.jpg\" alt=\"\" width=\"568\" height=\"354\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"evernote\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/evernote.png\" alt=\"\" width=\"100\" height=\"100\" \/>Evernote, il bloc notes del nuovo millennio<\/h3>\n<p>Prendi appunti sul tuo PC e aprili dal tuo cellulare. Modificali al volo, ordinali e condividili con studenti ed insegnanti. Tutto questo e molto altro \u00e8 ci\u00f2 che si pu\u00f2 fare con\u00a0<a title=\"Evernote per Windows\" href=\"http:\/\/evernote.softonic.it\/\">Evernote<\/a>, il blocco note multipiattaforma.<\/p>\n<p>Uno dei vari usi che gli autori di Evernote suggeriscono agli insegnanti \u00e8 quello di fare foto della lavagna o delle pagine web per lavori di ricerca. Le possibilit\u00e0 sono\u00a0infinite.<\/p>\n<p><a href=\"http:\/\/evernote.softonic.it\/\"><strong>Scarica Evernote per Windows<\/strong><\/a><\/p>\n<p><a href=\"http:\/\/evernote.softonic.it\/mac\"><strong><\/strong><\/a><strong><a href=\"http:\/\/evernote.softonic.it\/mac\"><strong>Scarica<\/strong><\/a> Evernote per Mac<\/strong><\/p>\n<p><a href=\"http:\/\/evernote.softonic.it\/android\"><strong><\/strong><\/a><strong><a href=\"http:\/\/evernote.softonic.it\/android\"><strong>Scarica<\/strong><\/a> Evernote per Android<\/strong><\/p>\n<p><a href=\"http:\/\/evernote.softonic.it\/iphone\"><strong><\/strong><\/a><strong><a href=\"http:\/\/evernote.softonic.it\/iphone\"><strong>Scarica<\/strong><\/a> Evernote per iPhone e iPad<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Evernote\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/evernote.jpg\" alt=\"\" width=\"568\" height=\"340\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"box\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/box.png\" alt=\"\" width=\"100\" height=\"100\" \/>Box, il disco rigido per lavorare in gruppo<\/h3>\n<p>Invece di utilizzare chiavette USB o inviare e-mail, cosa c&#8217;\u00e8 di meglio di utilizzare uno spazio online condiviso? Con\u00a0Box tu ed i tuoi studenti potrete creare cartelle in cui i file possono essere scaricati in qualsiasi momento.<\/p>\n<p>La possibilit\u00e0 di aggiungere commenti o accedere ai file da qualsiasi telefono o tablet d\u00e0 a Box una versatilit\u00e0 che lo rende ideale per il lavoro in classe.<\/p>\n<p><a href=\"http:\/\/box.softonic.it\/android\"><strong>Scarica Box per Android<\/strong><\/a><\/p>\n<p><a href=\"http:\/\/box.softonic.it\/iphone\"><strong>Scarica Box per iPhone<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"box\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/box.jpg\" alt=\"\" width=\"568\" height=\"480\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"trello-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/trello-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Trello, gestione delle attivit\u00e0, progetti e altro ancora<\/h3>\n<p><a href=\"http:\/\/trello.softonic.it\/applicazioni-web\">Trello<\/a> \u00e8 una bacheca virtuale dove si possono appendere idee, attivit\u00e0, immagini o link. E&#8217; cos\u00ec versatile e facile da usare che \u00e8 possibile utilizzarlo per qualsiasi tipo di compito che richieda di organizzare delle informazioni.<\/p>\n<p>Vuoi degli esempi? Distribuire i compiti per lavori di gruppo, raccogliere idee per un tema, raccogliere immagini per un murales o semplicemente organizzare e dare priorit\u00e0 ai materiali della classe.<\/p>\n<p><a href=\"http:\/\/trello.softonic.it\/android\"><strong>Scarica Trello per Android<\/strong><\/a><\/p>\n<p><a href=\"http:\/\/trello.softonic.it\/iphone\"><strong>Scarica Trello per iPhone<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"trello\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/trello.jpg\" alt=\"\" width=\"568\" height=\"354\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"paperlicon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/paperlicon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Paper.li, il giornalino di classe in rete<\/h3>\n<p>Con\u00a0<a title=\"Pagina ufficiale\" href=\"http:\/\/paper.li\/\" target=\"_blank\" rel=\"noopener noreferrer\">Paper.li<\/a> tutta la classe pu\u00f2 raccogliere notizie e creare una sorta di giornale online. Puoi aggiungere i collaboratori e diventare il redattore capo&#8230; della tua classe.<\/p>\n<p>I passaggi per creare un giornale virtuale sono semplici: prima scegli le fonti, poi personalizzi l&#8217;aspetto e infine condividi i risultati sui social network. E in pi\u00f9 si vede bene sul cellulare.<\/p>\n<p><a href=\"http:\/\/paper.li\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Accedi a Paper.li sul tuo browser<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Paper.li\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/Paperli.jpg\" alt=\"\" width=\"568\" height=\"362\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"socrative-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/socrative-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Socrative, i compiti sul browser<\/h3>\n<p>Niente irrita di pi\u00f9 un insegnante che correggere decine di compiti. Con\u00a0<a title=\"Pagina ufficiale\" href=\"http:\/\/www.socrative.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Socrative<\/a> si pu\u00f2 rispondere ai test su telefono cellulare, tablet o PC. Si integra con Google Drive e ha anche dei giochi educativi.<\/p>\n<p>Si tratta di una interessante alternativa a carta e penna, non solo per i compiti in classe, ma anche per i test giornalieri o settimanali. Con Socrative verificare se i tuoi studenti hanno seguito una lezione sar\u00e0 semplice e veloce.<\/p>\n<p><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.socrative.teacher\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica Socrative per Android<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/itunes.apple.com\/us\/app\/socrative-teacher\/id477620120\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica Socrative per iPhone e iPad<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Socrative\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/socrative.jpg\" alt=\"\" width=\"568\" height=\"355\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"screenr-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/screenr-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Screenr, tutorial video senza bisogno di una videocamera<\/h3>\n<p>Con\u00a0<a href=\"https:\/\/www.screenr.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Screenr<\/a> \u00e8 possibile registrare filmati di ci\u00f2 che visualizzi sul tuo PC, aggiungendo commenti con il microfono. I video saranno archiviati sul web e possono essere facilmente condivisi. Per registrare hai bisogno soltanto di un browser con Java.<\/p>\n<p>Screenr \u00e8 l&#8217;ideale per spiegare dei programmi (ad esempio, Excel) o commentare pagine web. Ed \u00e8 molto pi\u00f9 facile da usare rispetto ai costosi concorrenti commerciali.<\/p>\n<p><strong><a href=\"https:\/\/www.screenr.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Accedi a Screenr sul tuo browser<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"screenr\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/screenr.jpg\" alt=\"\" width=\"568\" height=\"306\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"calibre-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/calibre-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Calibre, l&#8217;eBook manager per definizione<\/h3>\n<p>I libri di carta sono costosi e pesanti, ma anche le note. Se usi gli eBook con\u00a0<a href=\"http:\/\/calibre.softonic.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Calibre<\/a>, potrai inviarli ai tuoi studenti per farli caricare sul loro cellulare, tablet o lettore di ebook.<\/p>\n<p>Calibre\u00a0\u00e8 lo strumento necessario per gestire i libri elettronici, convertirli in altri formati e crearli da altri documenti. Un bibliotecario virtuale indispensabile.<\/p>\n<p><a href=\"http:\/\/calibre.softonic.it\/\" target=\"_self\" rel=\"noopener noreferrer\"><strong>Scarica Calibre per Windows<\/strong><\/a><\/p>\n<p><strong><a href=\"http:\/\/calibre.softonic.it\/mac\" target=\"_self\" rel=\"noopener noreferrer\">Scarica Calibre per Mac<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"calibre\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/calibre.jpg\" alt=\"\" width=\"568\" height=\"303\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"animoto-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/animoto-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Animoto, video senza sforzo da testi e immagini<\/h3>\n<p>Un\u00a0<strong>video<\/strong> pu\u00f2 essere un potente strumento nelle mani del maestro che sappia usarlo e crearlo. Con i suoni, la musica e gli effetti visivi, puoi mantenere l&#8217;attenzione degli studenti molto pi\u00f9 alta che con un libro o una lavagna.<\/p>\n<p><a href=\"http:\/\/animoto.com\/pro\/education\" target=\"_blank\" rel=\"noopener noreferrer\">Animoto<\/a> permette la creazione di video con testo, immagini e suoni di una forma incredibilmente semplice. Se paghi per la versione Pro, avrai accesso a oltre 2.000 brani musicali e molte funzioni interattive.<\/p>\n<p><a href=\"http:\/\/animoto.com\/pro\/education\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Accedi a Animoto sul tuo browser<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Animoto\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/animot.jpg\" alt=\"\" width=\"568\" height=\"384\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"google-forms-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/google-forms-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Google Forms, questionari con marchio Google<\/h3>\n<p>Lo sapevi che su Google Drive \u00e8 possibile\u00a0creare sondaggi e questionari di tutti i tipi? Oggi \u00e8 forse il miglior strumento per la creazione di questionari, in termini di rapporto qualit\u00e0\/prezzo.<\/p>\n<p>Le domande le lasciamo alla tua immaginazione, ma basta dare uno sguardo ai\u00a0<a href=\"https:\/\/drive.google.com\/templates?category=7&amp;type=forms&amp;sort=hottest&amp;view=public\" target=\"_blank\" rel=\"noopener noreferrer\">modelli per studenti e insegnanti<\/a> per vedere le molte possibilit\u00e0 offerte da Google Form per le lezioni.<\/p>\n<p><a href=\"http:\/\/google-drive.softonic.it\/applicazioni-web\" target=\"_self\" rel=\"noopener noreferrer\"><strong>Accedi a Google Drive sul tuo browser<\/strong><br \/>\n<\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Google Forms\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/googleforms.jpg\" alt=\"\" width=\"568\" height=\"292\" \/><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"remind-icon\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/remind-icon.png\" alt=\"\" width=\"100\" height=\"100\" \/>Remind, promemoria sicuri per gli alunni<\/h3>\n<p>Adesso disponibile in tutto il mondo,\u00a0<a href=\"https:\/\/www.remind.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Remind<\/a> \u00e8 una app che soddisfa un&#8217;esigenza specifica: poter inviare messaggi agli studenti e tenere informati i genitori, allo stesso tempo.<\/p>\n<p>Oltre ai classici incontri con i genitori, un ottimo complemento sar\u00e0 proprio Remind. Invia promemoria e compiti, nonch\u00e9 messaggi ai genitori, il tutto senza rivelare i numeri di telefono.<\/p>\n<p><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.remind101\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica Remind per Android<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/itunes.apple.com\/us\/app\/remind-safe-classroom-communication\/id522826277\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Scarica Remind per iPhone<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"remind\" src=\"https:\/\/articles-images.sftcdn.net\/wp-content\/uploads\/sites\/2\/2014\/08\/remind.jpg\" alt=\"\" width=\"568\" height=\"319\" \/><\/p>\n<h3>La tecnologia non sostituisce il tuo lavoro, lo arricchisce<\/h3>\n<p>Le applicazioni che ho appena presentato possono essere piccoli alleati nel tuo giorno dopo giorno da insegnante. Essi possono essere utilizzati insieme o separatamente. Ma indipendentemente da come li usi, richiedono molto impegno da parte sia tua che dei tuoi studenti.<\/p>\n<p><strong>Che applicazioni consiglieresti ad insegnanti e professori?<\/strong><\/p>\n<p style=\"text-align: right;\"><em>[Articolo di <a href=\"https:\/\/twitter.com\/remoquete\" target=\"_blank\" rel=\"noopener noreferrer\">Fabrizio Ferri-Benedetti <\/a>su <a href=\"http:\/\/articulos.softonic.com\/apps-para-maestros-y-profesores-tic-aula\" target=\"_self\" rel=\"noopener noreferrer\">Softonic ES<\/a>]<a href=\"https:\/\/twitter.com\/remoquete\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<\/a><\/em><\/p>\n<p style=\"text-align: right;\"><em>[Fonti immagini: Nearpod, Google Play, Paper.li, Calibre]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tecnologia si \u00e8 messa al servizio anche di insegnanti ed educatori. Eccoti delle app che ti faranno da assistente in aula, ti aiuteranno a dare il meglio nei tuoi corsi e ti permetteranno anche di programmare delle lezioni virtuali. Diventa un maestro del XXI secolo! L&#8217;insegnamento non \u00e8 facile, soprattutto quando gli studenti sono &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/it\/app-insegnanti-professori\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Rientro a scuola: 16 app per maestri, insegnanti e professori&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3020,"featured_media":63626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":1},"categories":[1],"tags":[],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-63621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/63621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3020"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=63621"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/63621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media\/63626"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=63621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=63621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=63621"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=63621"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=63621"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=63621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}