{"id":69097,"date":"2014-10-09T17:08:15","date_gmt":"2014-10-09T15:08:15","guid":{"rendered":"http:\/\/onsoftware.softonic.it\/?p=69097"},"modified":"2024-03-08T00:52:00","modified_gmt":"2024-03-07T23:52:00","slug":"street-view-deserto-arabo","status":"publish","type":"post","link":"https:\/\/cms-articles.softonic.io\/it\/street-view-deserto-arabo\/","title":{"rendered":"Attraversa il deserto arabo con Street View"},"content":{"rendered":"<p>vuoi attraversare il deserto di Liwa senza muoverti da casa? Oggi puoi farlo grazie a <strong>Street View di Google Maps<\/strong>. Sono disponibili alcuni percorsi che attraversano il deserto degli Emirati Arabi Uniti. Ecco un video che mostra come sono state scattate le foto.<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"568\" height=\"320\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"\/\/www.youtube.com\/v\/4pVCToDTbT4?hl=it_IT&amp;version=3\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"568\" height=\"320\" src=\"\/\/www.youtube.com\/v\/4pVCToDTbT4?hl=it_IT&amp;version=3\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/p>\n<p>La fotocamera di Google \u00e8 stata <strong>collocata su un cammello<\/strong> che ha percorso il lungo viaggio.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-69103 aligncenter\" title=\"Google-Maps-deserto\" src=\"https:\/\/articles-img.sftcdn.net\/sft\/articles\/auto-mapping-folder\/sites\/4\/2014\/10\/Google-Maps-deserto.jpg\" alt=\"\" width=\"568\" height=\"469\" srcset=\"https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2014\/10\/Google-Maps-deserto.jpg 568w, https:\/\/articles-img.sftcdn.net\/auto-mapping-folder\/sites\/4\/2014\/10\/Google-Maps-deserto-256x211.jpg 256w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p style=\"text-align: left;\">\u00c8 il momento di superare le dune del deserto di Liwa e godersi gli incredibili paesaggi immortalati da Google. Un&#8217;ulteriore prova di quanto Google voglia andare fino in fondo con il suo progetto Street View coprendo gli angoli pi\u00f9 belli del pianeta.<\/p>\n<p style=\"text-align: left;\"><em>Fonte: <a href=\"http:\/\/google-latlong.blogspot.co.uk\/2014\/10\/roam-arabian-desert-with-street-view.html\" target=\"_blank\" rel=\"noopener noreferrer\">Google Maps Blog<\/a><\/em><\/p>\n<p style=\"text-align: left;\">\n<p><strong>Leggi anche:<\/p>\n<p><\/strong><br \/>\n<a href=\"http:\/\/news.softonic.it\/google-street-view-macchina-del-tempo\"><br \/>\nCon Google Street View ora puoi viaggiare nel tempo<\/a><\/p>\n<p><a href=\"http:\/\/news.softonic.it\/le-piramidi-di-giza-google-maps\">Le piramidi di Giza e l&#8217;Antico Egitto su Google Maps<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>vuoi attraversare il deserto di Liwa senza muoverti da casa? Oggi puoi farlo grazie a Street View di Google Maps. Sono disponibili alcuni percorsi che attraversano il deserto degli Emirati Arabi Uniti. Ecco un video che mostra come sono state scattate le foto. La fotocamera di Google \u00e8 stata collocata su un cammello che ha &hellip; <a href=\"https:\/\/cms-articles.softonic.io\/it\/street-view-deserto-arabo\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Attraversa il deserto arabo con Street View&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3065,"featured_media":69101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","wpcf-pageviews":0},"categories":[1],"tags":[271],"usertag":[],"vertical":[],"content-category":[],"class_list":["post-69097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-street-view"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/69097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/users\/3065"}],"replies":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/comments?post=69097"}],"version-history":[{"count":0,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/posts\/69097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media\/69101"}],"wp:attachment":[{"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/media?parent=69097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/categories?post=69097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/tags?post=69097"},{"taxonomy":"usertag","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/usertag?post=69097"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/vertical?post=69097"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/cms-articles.softonic.io\/it\/wp-json\/wp\/v2\/content-category?post=69097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}